{"id":151987,"date":"2019-03-25T07:22:39","date_gmt":"2019-03-25T06:22:39","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=151987"},"modified":"2019-03-25T00:30:32","modified_gmt":"2019-03-24T23:30:32","slug":"tennistavolo-il-brindisino-matteo-antonazzo-sul-podio-piu-alto-del-campionato-interprovinciale-categoria-giovanissimi","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/tennistavolo-il-brindisino-matteo-antonazzo-sul-podio-piu-alto-del-campionato-interprovinciale-categoria-giovanissimi\/","title":{"rendered":"Tennistavolo: il brindisino Matteo Antonazzo sul podio pi\u00f9 alto del campionato interprovinciale categoria Giovanissimi"},"content":{"rendered":"<p>Ancora una vittoria del brindisino Matteo Antonazzo: primo al campionato interprovinciale BR-LE-TA categoria Giovanissimi.<\/p>\n<p>&nbsp;<\/p>\n<p>Ancora un torneo in cassaforte per il baby Matteo Antonazzo che si aggiudica il campionato interprovinciale Brindisi \u2013 Lecce \u2013 Taranto svoltosi nel fine settimana a Uggiano La Chiesa (LE), nella categoria Giovanissimi.<\/p>\n<p>&nbsp;<\/p>\n<p>Il nostro Matteo si \u00e8 imposto per 3-1 sul secondo classificato Centonze (TT Salento) e per 3-0 sul terzo classificato Vantaggiato (TT D. G. Palam\u00e0), aggiudicandosi il primo gradino del podio.<\/p>\n<p>&nbsp;<\/p>\n<p>Molto soddisfatto il coach Doriano Orfano: \u201ccontinuiamo a migliorare con i nostri ragazzi e oggi \u00e8 maturato un altro frutto importante: Matteo ha regalato a s\u00e9 stesso ed a noialtri una grande soddisfazione. Adesso concentriamoci per il finale di campionato e prepariamoci per i campionati italiani giovanili.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>UFFICIO STAMPA ENEL TT BRINDISI<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ancora una vittoria del brindisino Matteo Antonazzo: primo al campionato interprovinciale BR-LE-TA categoria Giovanissimi. &nbsp; Ancora un torneo in cassaforte per il baby Matteo Antonazzo che si aggiudica il campionato interprovinciale Brindisi \u2013 Lecce \u2013 Taranto svoltosi nel fine settimana a Uggiano La Chiesa (LE), nella categoria Giovanissimi. &nbsp; Il nostro Matteo si \u00e8 imposto per 3-1 sul secondo classificato Centonze (TT Salento) e per 3-0 sul terzo classificato Vantaggiato (TT D. G. Palam\u00e0), aggiudicandosi il primo gradino del podio. &nbsp; Molto soddisfatto il coach Doriano Orfano: \u201ccontinuiamo a migliorare con i nostri ragazzi e oggi \u00e8 maturato un altro frutto importante: Matteo ha regalato a s\u00e9 stesso ed a noialtri una grande soddisfazione. Adesso concentriamoci per il finale di campionato e prepariamoci per i campionati italiani giovanili.\u201d &nbsp; &nbsp; UFFICIO STAMPA ENEL TT BRINDISI<\/p>\n","protected":false},"author":2,"featured_media":151988,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[557],"tags":[],"class_list":["post-151987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis-tavolo"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/151987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=151987"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/151987\/revisions"}],"predecessor-version":[{"id":151989,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/151987\/revisions\/151989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/151988"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=151987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=151987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=151987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}