{"id":152166,"date":"2019-03-27T14:31:56","date_gmt":"2019-03-27T13:31:56","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=152166"},"modified":"2019-03-27T14:31:56","modified_gmt":"2019-03-27T13:31:56","slug":"i-piccoli-atleti-della-boxe-iaia-brindisi-in-evidenza-al-i-criterium-giovanile-regionale-puglia-basilicata-svoltosi-a-taranto","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/i-piccoli-atleti-della-boxe-iaia-brindisi-in-evidenza-al-i-criterium-giovanile-regionale-puglia-basilicata-svoltosi-a-taranto\/","title":{"rendered":"I piccoli atleti della Boxe Iaia Brindisi in evidenza al \u201cI\u00b0 Criterium Giovanile Regionale Puglia\/Basilicata\u201d svoltosi a Taranto"},"content":{"rendered":"<p>La Boxe Iaia Brindisi, capitanata dal maestro Carmine Iaia, si afferma tra le pi\u00f9 rappresentative societ\u00e0 Appulo-Lucane, le stesse che la scorsa domenica, 24 Marzo, hanno preso parte al \u201cI\u00b0 Criterium Giovanile Regionale Puglia\/Basilicata\u201d della stagione 2019, organizzato a Taranto presso la Masseria Vaccarella dalla societ\u00e0 Vivere Solidale con lo Sport del maestro Salvatore Cupri per conto del Comitato Regionale Pugliese\/Lucano presieduto dal dott. Nicola Causi con la collaborazione del Tecnico Responsabile dell\u2019Attivit\u00e0 Giovanile Regionale Cataldo Quero<\/p>\n<p>&nbsp;<\/p>\n<p>La societ\u00e0 pugilistica brindisina, arrivata nel tarantino con un numeroso gruppo di bambini e famiglie al seguito, ha pienamente centrato lo spirito della Manifestazione Sportiva grazie anche al grande entusiasmo con il quale i giovanissimi atleti brindisini hanno preso parte all\u2019attivit\u00e0 pugilistica proposta nella giornata di incontro.<\/p>\n<p>&nbsp;<\/p>\n<p>Nel particolare al Criterium hanno partecipato:<\/p>\n<p>&#8211; nella Categoria \u201cCuccioli\u201d (cos\u00ec chiamata dalla FPI \u2013 Federazione Pugilistica Italiana): Christian Montenegro 5 anni, Antonio Monaco 5 anni, Antonio Coffa 6 anni, Andrea Schena 6 anni, Dylan Mingolla 6 anni, Bianca Pinnizzotto 6 anni;<\/p>\n<p>&#8211; nella Categoria \u201cCangurini\u201d Samuele Semeraro 7 anni, Samuele Balsamo 8 anni, Christian Allegrini 9 anni;<\/p>\n<p>&#8211; nella categoria \u201cCanguri\u201d Carmine Iaia 9 anni, Antonio Iaia 9 anni, Davide Balsamo 10 anni, Giuseppe Pinnizzotto 11 anni;<\/p>\n<p>&#8211; nella categoria \u201cAllievi \u201c parteciperanno: Iustin Badu 11 anni.<\/p>\n<p>&nbsp;<\/p>\n<p>Al Criterium oltre alla Boxe Iaia Brindisi hanno partecipato la societ\u00e0 Vivere Solidale con lo Sport di Taranto, la societ\u00e0 Boxe Fiore di Canosa (Bat), la societ\u00e0 Boxe Di Palo di Andria, la Boxe Palumbo, la societ\u00e0 Pugilistica Taralli e la societ\u00e0 Boxe Luciano tutti di Foggia<\/p>\n<p>&nbsp;<\/p>\n<p>Soddisfazione per il tecnico Carmine Iaia e per l\u2018aspirante tecnico Riccardo Gallo per i progressi raggiunti e dimostrati dal settore giovanile della Boxe Iaia, gradimento condiviso anche dalle famiglie che settimanalmente accompagnano i ragazzi agli allenamenti tenuti all\u2019interno della palestra Iaia nel pieno centro di Br<a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/03\/BoxeIaia-I\u00b0Criterium2019-Taranto3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-152167\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/03\/BoxeIaia-I\u00b0Criterium2019-Taranto3-300x229.jpg\" alt=\"\" width=\"300\" height=\"229\" \/><\/a>indisi presso Piazza Mercato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Boxe Iaia Brindisi, capitanata dal maestro Carmine Iaia, si afferma tra le pi\u00f9 rappresentative societ\u00e0 Appulo-Lucane, le stesse che la scorsa domenica, 24 Marzo, hanno preso parte al \u201cI\u00b0 Criterium Giovanile Regionale Puglia\/Basilicata\u201d della stagione 2019, organizzato a Taranto presso la Masseria Vaccarella dalla societ\u00e0 Vivere Solidale con lo Sport del maestro Salvatore Cupri per conto del Comitato Regionale Pugliese\/Lucano presieduto dal dott. Nicola Causi con la collaborazione del Tecnico Responsabile dell\u2019Attivit\u00e0 Giovanile Regionale Cataldo Quero &nbsp; La societ\u00e0 pugilistica brindisina, arrivata nel tarantino con un numeroso gruppo di bambini e famiglie al seguito, ha pienamente centrato lo spirito della Manifestazione Sportiva grazie anche al grande entusiasmo con il quale i giovanissimi atleti brindisini hanno preso parte all\u2019attivit\u00e0 pugilistica proposta nella giornata di incontro. &nbsp; Nel particolare al Criterium hanno partecipato: &#8211; nella Categoria \u201cCuccioli\u201d (cos\u00ec chiamata dalla FPI \u2013 Federazione Pugilistica Italiana): Christian Montenegro 5 anni, Antonio Monaco 5 anni, Antonio Coffa 6 anni, Andrea Schena 6 anni, Dylan Mingolla 6 anni, Bianca Pinnizzotto 6 anni; &#8211; nella&#8230;<\/p>\n","protected":false},"author":2,"featured_media":152168,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[398],"tags":[],"class_list":["post-152166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/152166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=152166"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/152166\/revisions"}],"predecessor-version":[{"id":152169,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/152166\/revisions\/152169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/152168"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=152166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=152166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=152166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}