{"id":152317,"date":"2019-03-30T18:50:07","date_gmt":"2019-03-30T17:50:07","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=152317"},"modified":"2019-03-30T18:50:07","modified_gmt":"2019-03-30T17:50:07","slug":"conserve-marcescenti-in-azienda-di-mesagne-denunciati-conducente-e-titolare-della-ditta","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/conserve-marcescenti-in-azienda-di-mesagne-denunciati-conducente-e-titolare-della-ditta\/","title":{"rendered":"Conserve marcescenti in azienda di Mesagne: denunciati conducente e titolare della ditta"},"content":{"rendered":"<p>\nIntervento dei Carabinieri Forestali del Nucleo Investigativo (NIPAAF) di Brindisi, dopo che un autocarro che trasportava conserve alimentari scadute e marcescenti, contenute fusti in plastica, era stato intercettato nei pressi di San Vito dei Normanni dagli ispettori della Repressione Frodi (ICQRF) di Lecce.<br \/>\nI Militari, accertata la destinazione del materiale come rifiuti, di cui disfarsi evidentemente in materia illecita, senza documentazione che potesse comprovarne l\u2019 eventuale riutilizzo, hanno proceduto al sequestro dell\u2019 automezzo con tutto il carico, ammontante ad oltre 7 quintali, denunciando il conducente e proprietario del mezzo, O.U., 50enne di Carovigno, alla Procura della Repubblica di Brindisi, per gestione di rifiuti non autorizzata, ai sensi dell\u2019 art. 256, comma 1, del decreto legislativo 152 del 2006 (\u201cCodice dell\u2019 Ambiente\u201d).<br \/>\nStesso articolo, comma 2, per il reato ascritto contestualmente a G.R., 49enne di Mesagne, legale rappresentante del conservificio da cui i rifiuti provenivano. Il sopralluogo presso l\u2019 azienda ha evidenziato un\u2019 area interna, in cui erano stoccati, da anni, 18 bancali con barattoli in latta contenti conserve in putrefazione, pi\u00f9 altri fusti in plastica.<br \/>\nIl liquido di putrefazione aveva inoltre ossidato diffusamente i contenitori metallici, ormai ricoperti in gran parte di ruggine, nonch\u00e9 perforati e percolanti gli olii, alterati, di conserva.<br \/>\nI Carabinieri Forestali hanno quindi proceduto a sottoporre a sequestro anche tutta questa superficie a deposito, dove le conserve scadute giacevano da tempo, presumibilmente in attesa di essere smaltite, ma configurando di fatto un deposito incontrollato di rifiuti.<br \/>\nIn collaborazione con i Militari di Brindisi hanno operato anche i Carabinieri della Stazione Carabinieri di Cellino San Marco, che si sono occupati in particolare delle irregolarit\u00e0 afferenti al Codice della Strada.<br \/>\nSi conferma il massimo sforzo che i Reparti dei Carabinieri Forestali dipendenti dal Gruppo di Brindisi stanno profondendo nel controllo del territorio, finalizzati all\u2019 accertamento di depositi illeciti e di attivit\u00e0 di gestioni di rifiuti non autorizzate, con l\u2019 individuazione dei responsabili e loro deferimento all\u2019 Autorit\u00e0 giudiziaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Intervento dei Carabinieri Forestali del Nucleo Investigativo (NIPAAF) di Brindisi, dopo che un autocarro che trasportava conserve alimentari scadute e marcescenti, contenute fusti in plastica, era stato intercettato nei pressi di San Vito dei Normanni dagli ispettori della Repressione Frodi (ICQRF) di Lecce. I Militari, accertata la destinazione del materiale come rifiuti, di cui disfarsi evidentemente in materia illecita, senza documentazione che potesse comprovarne l\u2019 eventuale riutilizzo, hanno proceduto al sequestro dell\u2019 automezzo con tutto il carico, ammontante ad oltre 7 quintali, denunciando il conducente e proprietario del mezzo, O.U., 50enne di Carovigno, alla Procura della Repubblica di Brindisi, per gestione di rifiuti non autorizzata, ai sensi dell\u2019 art. 256, comma 1, del decreto legislativo 152 del 2006 (\u201cCodice dell\u2019 Ambiente\u201d). Stesso articolo, comma 2, per il reato ascritto contestualmente a G.R., 49enne di Mesagne, legale rappresentante del conservificio da cui i rifiuti provenivano. Il sopralluogo presso l\u2019 azienda ha evidenziato un\u2019 area interna, in cui erano stoccati, da anni, 18 bancali con barattoli in latta contenti conserve in putrefazione,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":152323,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-152317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/152317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=152317"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/152317\/revisions"}],"predecessor-version":[{"id":152325,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/152317\/revisions\/152325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/152323"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=152317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=152317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=152317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}