{"id":152348,"date":"2019-03-30T19:32:57","date_gmt":"2019-03-30T18:32:57","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=152348"},"modified":"2019-03-30T19:09:47","modified_gmt":"2019-03-30T18:09:47","slug":"francavilla-le-iniziative-in-programma-per-la-settimana-santa-2019","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/francavilla-le-iniziative-in-programma-per-la-settimana-santa-2019\/","title":{"rendered":"Francavilla: le iniziative in programma per la Settimana Santa 2019"},"content":{"rendered":"<p>Proseguono le iniziative collaterali per la Settimana Santa promosse dall\u2019Amministrazione Comunale.  Luned\u00ec 1 aprile alle 18.30 nella Sala del Belvedere, al secondo piano di Castello Imperiali, sar\u00e0 proiettato il capolavoro di Pierpaolo Pasolini \u201cIl Vangelo secondo Matteo\u201d con introduzione del docente Davide Gatto. Il film traspone il Vangelo di Matteo che narra la vita di Ges\u00f9 Cristo, dalla nascita alla crocifissione e resurrezione.<br \/>\nGioved\u00ec 4 aprile alle 19.00 nella Sala del Lampadario di Castello Imperiali \u00e8 in programma il convegno \u201cVivere il paese guardando il cielo\u201d a cura della Confraternita Maria Santissima del Carmine. Al centro della discussione ci saranno i \u201cPappamusci\u201d, coppie di anime incappucciate e scalze che ogni anno compiono il loro cammino di devozione. All\u2019evento interverranno: il Sindaco, l\u2019Assessora alla Cultura e al Turismo, il parroco don Andrea Santoro, il priore della Confraternita Carmine della Corte, il vice Priore Giuseppe Arpa, il Priore della Confraternita Orazione e Morte Oronzo Cal\u00f2, l\u2019artista Pietro Balsamo, il docente Carmine Carluccio e il coordinatore delle iniziative collaterali per la Settimana Santa.<br \/>\nVenerd\u00ec 5 aprile alle 19.00 a Castello Imperiali sar\u00e0 di scena \u201cLa Principessa Mandorla\u201d. L\u2019evento propone una riflessione sulla mandorla che sar\u00e0 declinata nei linguaggi della letteratura, della filosofia e dell\u2019arte. La mandorla, in passato, insieme ai fichi, l&#8217;uva e le olive, ha costituito una ricchezza della nostra terra che intere generazioni hanno utilizzato per nutrirsi e dare lustro alla tavola, arricchendo il nostro patrimonio culinario. Interverranno i docenti Francesco Capobianco, Carmela Stasi e Guglielmo Cozzolino.<br \/>\nSabato 6 aprile dalle 17.00 ci sar\u00e0 una tappa dedicata ai riti della Settimana Santa all\u2019interno del progetto Filia Solis Terra di\u2026 Attraverso una visita guidata sar\u00e0 possibile scoprire le storie degli angoli e delle chiese pi\u00f9 belle del Centro Storico della citt\u00e0 e ammirare le statue protagoniste della processione del Venerd\u00ec Santo. Al termine, nella Chiesa dei Padri Liguorini, Concerto della Passione dell&#8217;Orchestra di Matera e della Basilicata, a cura del Lams Matera e dell\u2019Associazione D\u2019Ambrosio.<br \/>\nTutte le iniziative godono del patrocinio della Regione Puglia, della Provincia di Brindisi, del Comune di Matera, di Matera2019, di Puglia Promozione e, per quanto concerne la mostra di Palazzo Madama, del Senato della Repubblica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proseguono le iniziative collaterali per la Settimana Santa promosse dall\u2019Amministrazione Comunale. Luned\u00ec 1 aprile alle 18.30 nella Sala del Belvedere, al secondo piano di Castello Imperiali, sar\u00e0 proiettato il capolavoro di Pierpaolo Pasolini \u201cIl Vangelo secondo Matteo\u201d con introduzione del docente Davide Gatto. Il film traspone il Vangelo di Matteo che narra la vita di Ges\u00f9 Cristo, dalla nascita alla crocifissione e resurrezione. Gioved\u00ec 4 aprile alle 19.00 nella Sala del Lampadario di Castello Imperiali \u00e8 in programma il convegno \u201cVivere il paese guardando il cielo\u201d a cura della Confraternita Maria Santissima del Carmine. Al centro della discussione ci saranno i \u201cPappamusci\u201d, coppie di anime incappucciate e scalze che ogni anno compiono il loro cammino di devozione. All\u2019evento interverranno: il Sindaco, l\u2019Assessora alla Cultura e al Turismo, il parroco don Andrea Santoro, il priore della Confraternita Carmine della Corte, il vice Priore Giuseppe Arpa, il Priore della Confraternita Orazione e Morte Oronzo Cal\u00f2, l\u2019artista Pietro Balsamo, il docente Carmine Carluccio e il coordinatore delle iniziative collaterali per la Settimana Santa&#8230;.<\/p>\n","protected":false},"author":2,"featured_media":151864,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-152348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/152348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=152348"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/152348\/revisions"}],"predecessor-version":[{"id":152351,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/152348\/revisions\/152351"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/151864"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=152348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=152348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=152348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}