{"id":153430,"date":"2019-04-15T20:56:11","date_gmt":"2019-04-15T18:56:11","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=153430"},"modified":"2019-04-15T20:56:11","modified_gmt":"2019-04-15T18:56:11","slug":"porto-m5s-ennesima-guerra-tra-guelfi-e-ghibellini-a-perdere-sara-brindisi","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/porto-m5s-ennesima-guerra-tra-guelfi-e-ghibellini-a-perdere-sara-brindisi\/","title":{"rendered":"Porto, M5S: &#8220;ennesima guerra tra guelfi e ghibellini. A perdere sar\u00e0 Brindisi&#8221;"},"content":{"rendered":"<p>In una Citt\u00e0 in crisi come la nostra, sulle vicende importanti riguardanti il futuro economico e lo sviluppo, dovremmo assumere tutti posizioni responsabili.<br \/>\nAbbiamo sempre affermato che \u201cuna discussione ampia su ci\u00f2 che vorremo essere e quale modello di sviluppo portuale abbracciare non potr\u00e0 che essere fatta quando Istituzioni ed Enti si confronteranno sul Piano Regolatore del Porto\u201d e \u201csenza un Piano Regolatore o varianti approvate (o in itinere) anche una fontanella farebbe la fine dei varchi doganali\u201d.<br \/>\nSe ora non faremo in fretta rischieremo di pagare cara la nostra atavica assenza di programmazione: potremmo diventare il nulla assoluto nella portualit\u00e0 italiana.<\/p>\n<p>In questo non edificante contesto si inserisce il contestato da alcuni, ed esaltato da altri, Consiglio Comunale monotematico, che ha avuto solo la valenza di esprimere un favore condiviso ad opere ritenute, da molti ma non da tutti, come come \u201cuna boccata di ossigeno\u201d per la nostra economia portuale e per l&#8217;economia cittadina tutta.<\/p>\n<p>Purtroppo i dubbi da noi sollevati sulle reali posizioni dell&#8217;amministrazione e del Sindaco, dopo poche ore, hanno trovato conferma nelle dichiarazioni dell&#8217;Assessore all&#8217;Urbanistica, il quale ha ribadito con forza le propria contrariet\u00e0 rispetto alle opere portuali votate, ancorando le proprie speranze di fermarle proprio ad un emendamento del Sindaco.<\/p>\n<p>&nbsp;<\/p>\n<p>Appare evidente che l&#8217;esecutivo abbia una idea ben precisa su che direzione debba prendere la vicenda, forse la maggioranza un po&#8217; meno.<\/p>\n<p>L&#8217;assessore \u00e8 ancora al suo posto ed il PD, partito di maggioranza relativa, reagisce ma non centra l&#8217;avversario e, come un pugile suonato dopo un colpo da ko, sposta le mosche con colpi nel vuoto.<\/p>\n<p>Il Sindaco ed il suo assessore di punta rafforzeranno le proprie posizioni e presumiamo troveranno anche autorevoli appoggi politici fuori dalla Citt\u00e0.<\/p>\n<p>La Citt\u00e0 assister\u00e0 come al solito all&#8217;ennesima sfida tra Guelfi e Ghibellini, poco importa chi vincer\u00e0 tanto sar\u00e0 sempre Brindisi a perdere.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>MoVimento 5 Stelle Brindisi<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In una Citt\u00e0 in crisi come la nostra, sulle vicende importanti riguardanti il futuro economico e lo sviluppo, dovremmo assumere tutti posizioni responsabili. Abbiamo sempre affermato che \u201cuna discussione ampia su ci\u00f2 che vorremo essere e quale modello di sviluppo portuale abbracciare non potr\u00e0 che essere fatta quando Istituzioni ed Enti si confronteranno sul Piano Regolatore del Porto\u201d e \u201csenza un Piano Regolatore o varianti approvate (o in itinere) anche una fontanella farebbe la fine dei varchi doganali\u201d. Se ora non faremo in fretta rischieremo di pagare cara la nostra atavica assenza di programmazione: potremmo diventare il nulla assoluto nella portualit\u00e0 italiana. In questo non edificante contesto si inserisce il contestato da alcuni, ed esaltato da altri, Consiglio Comunale monotematico, che ha avuto solo la valenza di esprimere un favore condiviso ad opere ritenute, da molti ma non da tutti, come come \u201cuna boccata di ossigeno\u201d per la nostra economia portuale e per l&#8217;economia cittadina tutta. Purtroppo i dubbi da noi sollevati sulle reali posizioni dell&#8217;amministrazione e del Sindaco, dopo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":153431,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-153430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/153430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=153430"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/153430\/revisions"}],"predecessor-version":[{"id":153432,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/153430\/revisions\/153432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/153431"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=153430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=153430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=153430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}