{"id":153964,"date":"2019-04-26T07:47:22","date_gmt":"2019-04-26T05:47:22","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=153964"},"modified":"2019-04-26T07:47:22","modified_gmt":"2019-04-26T05:47:22","slug":"targa-non-abbinata-al-telaio-dellauto-coniugi-cellinesi-denunciati-per-ricettazione-e-riciclaggio","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/targa-non-abbinata-al-telaio-dellauto-coniugi-cellinesi-denunciati-per-ricettazione-e-riciclaggio\/","title":{"rendered":"Targa non abbinata al telaio dell&#8217;auto: coniugi cellinesi denunciati per ricettazione e riciclaggio"},"content":{"rendered":"<p>I Carabinieri della Stazione di Cellino San Marco a conclusione degli accertamenti hanno deferito in stato di libert\u00e0 due coniugi del luogo per ricettazione e riciclaggio. La coppia \u00e8 stata fermata nel corso di un posto di controllo alla circolazione stradale sulla SP75, mentre erano a bordo di una Fiat bravo.<\/p>\n<p>Da un primo esame \u00e8 emerso che il mezzo era sprovvisto di polizza assicurativa obbligatoria, scaduta di validit\u00e0 da qualche mese.<\/p>\n<p>Ulteriori verifiche hanno fatto emergere una serie di incongruenze e in particolare che il veicolo risultava immatricolato nel 2008, con in dotazione tutti e 4 i vetri laterali e il lunotto anteriore e posteriore dell\u2019anno 2011. Ed ancora nell\u2019ultima revisione effettuata nel giugno del 2017 aveva percorso 188.214 Km, mentre attualmente all\u2019atto del controllo misurava circa 30.000 km in meno.<\/p>\n<p>Pertanto, i militari hanno acclarato che la vettura \u00e8 risultata oggetto di furto denunciato dal proprietario presso la Stazione Carabinieri di Porto Cesareo (LE) il 14 agosto 2018, ed \u00e8 stata sottoposta a sequestro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Carabinieri della Stazione di Cellino San Marco a conclusione degli accertamenti hanno deferito in stato di libert\u00e0 due coniugi del luogo per ricettazione e riciclaggio. La coppia \u00e8 stata fermata nel corso di un posto di controllo alla circolazione stradale sulla SP75, mentre erano a bordo di una Fiat bravo. Da un primo esame \u00e8 emerso che il mezzo era sprovvisto di polizza assicurativa obbligatoria, scaduta di validit\u00e0 da qualche mese. Ulteriori verifiche hanno fatto emergere una serie di incongruenze e in particolare che il veicolo risultava immatricolato nel 2008, con in dotazione tutti e 4 i vetri laterali e il lunotto anteriore e posteriore dell\u2019anno 2011. Ed ancora nell\u2019ultima revisione effettuata nel giugno del 2017 aveva percorso 188.214 Km, mentre attualmente all\u2019atto del controllo misurava circa 30.000 km in meno. Pertanto, i militari hanno acclarato che la vettura \u00e8 risultata oggetto di furto denunciato dal proprietario presso la Stazione Carabinieri di Porto Cesareo (LE) il 14 agosto 2018, ed \u00e8 stata sottoposta a sequestro.<\/p>\n","protected":false},"author":2,"featured_media":153468,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-153964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/153964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=153964"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/153964\/revisions"}],"predecessor-version":[{"id":153966,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/153964\/revisions\/153966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/153468"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=153964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=153964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=153964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}