{"id":154154,"date":"2019-04-29T16:58:32","date_gmt":"2019-04-29T14:58:32","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=154154"},"modified":"2019-04-29T22:00:57","modified_gmt":"2019-04-29T20:00:57","slug":"scherma-storica-promozione-per-lenel-lame-azzurre-in-serie-a2-di-spada-femminile","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/scherma-storica-promozione-per-lenel-lame-azzurre-in-serie-a2-di-spada-femminile\/","title":{"rendered":"Scherma: storica promozione per l&#8217;Enel Lame Azzurre in serie A2 di spada femminile"},"content":{"rendered":"<p>I sorrisi splendenti delle ragazze dell&#8217;Enel Scherma Lame Azzurre Brindisi\/Novoli, una medaglia d&#8217;argento che sancisce non solo l aver sfiorato il titolo italiano, ma l aver conquistato il passaggio storico alla serie successiva A2, questo \u00e8 sufficiente a descrivere le forti provate nella giornata di ieri 26 aprile ad Adria durante il campionato italiano a squadre di spada femminile.<br \/>\nProtagoniste della straordinaria impresa: Chiara Spedicato, Miriana Morciano, Mariella Gigliola e Liliana Verdesca, che dopo una gara a dir poco eccezionale giungono alla finalissima terminata 45-37 contro il Circolo della Scherma Imola, e per un soffio non salgono sul gradino pi\u00f9 alto del podio! La gioia resta comunque incontenibile da parte di tutto il consiglio direttivo e tecnico dell\u2019 Enel Scherma Lame Azzurre Brindisi Novoli va il plauso a queste atlete che hanno dato il massimo e centrato a pieni voti l obiettivo prefissato, cos\u00ec come allo stesso modo hanno fatto i ragazzi della squadra maschile composta da Di Coste Samuele, Di Coste Matteo, Rinaldi Pietro e Samuele Erriquez che hanno confermato a denti stretti, durante il campionato italiano squadre svoltosi a Reggio Emilia, la serie A2 conquistata con successo e sudore lo scorso anno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I sorrisi splendenti delle ragazze dell&#8217;Enel Scherma Lame Azzurre Brindisi\/Novoli, una medaglia d&#8217;argento che sancisce non solo l aver sfiorato il titolo italiano, ma l aver conquistato il passaggio storico alla serie successiva A2, questo \u00e8 sufficiente a descrivere le forti provate nella giornata di ieri 26 aprile ad Adria durante il campionato italiano a squadre di spada femminile. Protagoniste della straordinaria impresa: Chiara Spedicato, Miriana Morciano, Mariella Gigliola e Liliana Verdesca, che dopo una gara a dir poco eccezionale giungono alla finalissima terminata 45-37 contro il Circolo della Scherma Imola, e per un soffio non salgono sul gradino pi\u00f9 alto del podio! La gioia resta comunque incontenibile da parte di tutto il consiglio direttivo e tecnico dell\u2019 Enel Scherma Lame Azzurre Brindisi Novoli va il plauso a queste atlete che hanno dato il massimo e centrato a pieni voti l obiettivo prefissato, cos\u00ec come allo stesso modo hanno fatto i ragazzi della squadra maschile composta da Di Coste Samuele, Di Coste Matteo, Rinaldi Pietro e Samuele Erriquez che hanno&#8230;<\/p>\n","protected":false},"author":2,"featured_media":154155,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[295],"tags":[],"class_list":["post-154154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scherma"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/154154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=154154"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/154154\/revisions"}],"predecessor-version":[{"id":154156,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/154154\/revisions\/154156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/154155"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=154154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=154154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=154154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}