{"id":154628,"date":"2019-05-07T14:55:45","date_gmt":"2019-05-07T12:55:45","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=154628"},"modified":"2019-05-07T14:55:45","modified_gmt":"2019-05-07T12:55:45","slug":"45-esemplari-di-uccelli-protetti-trasportati-in-furgone-verso-il-lazio-denunciate-due-persone","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/45-esemplari-di-uccelli-protetti-trasportati-in-furgone-verso-il-lazio-denunciate-due-persone\/","title":{"rendered":"45 esemplari di uccelli protetti trasportati in furgone verso il Lazio: denunciate due persone"},"content":{"rendered":"<p>Nel corso di un\u2019 attivit\u00e0 di controllo del territorio, i Carabinieri del Nucleo Operativo Radiomobile di Brindisi hanno fermato, per un controllo stradale, lungo la SS379 all\u2019 intersezione per Pezze di Greco un automezzo furgonato e, richiesto al conducente di aprire i portelloni posteriori, vi hanno rinvenuto gabbie e cartoni che contenevano esemplari di avifauna presumibilmente protetta.<\/p>\n<p>Sono quindi intervenuti i Carabinieri Forestali della Stazione di Brindisi, con il supporto di un veterinario dell\u2019 ASL, riconoscendovi 10 esemplari di piovanello, 17 di piro-piro, 15 di gambecchio, 2 di corriere grosso, 1 di piovanello pancianera, in tutto 45 individui di specie protette ai sensi della legge-quadro nazionale n. 157 dell\u2019 11 febbraio 1992, che fa propria la Direttiva \u201cUccelli\u201d comunitaria 79\/49\/CEE. Gli uccelli, abitatori delle rive fangose di aree umide, erano probabilmente il frutto di ripetute azioni di bracconaggio lungo il litorale brindisino.<\/p>\n<p>I Carabinieri Forestali hanno quindi proceduto al sequestro di tutti gli esemplari e delle gabbie. Il conducente del mezzo, E.S. di 64 anni, ed il passeggero, M.C. di 60, entrambi di Cisterna di Latina (LT), sono stati denunciati alla Procura della Repubblica di Brindisi per detenzione in concorso di avifauna protetta, ai sensi dell\u2019 art. 21 comma 1 lett. ee) della richiamata legge 157\/92, sanzionata dall\u2019 art. 30 comma 1 lett. c) della norma medesima.<\/p>\n<p>Gli uccelli, per la cui custodia era stato preallertato il centro di soccorso della fauna selvatica di Ostuni, sono stati liberati a fine dell\u2019 operazione, avendo verificato il generale buono stato di salute, e considerato che avrebbero mal sopportato un ulteriore periodo di detenzione, sebbene in condizioni pi\u00f9 favorevoli di quelle a cui erano stati sottoposti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel corso di un\u2019 attivit\u00e0 di controllo del territorio, i Carabinieri del Nucleo Operativo Radiomobile di Brindisi hanno fermato, per un controllo stradale, lungo la SS379 all\u2019 intersezione per Pezze di Greco un automezzo furgonato e, richiesto al conducente di aprire i portelloni posteriori, vi hanno rinvenuto gabbie e cartoni che contenevano esemplari di avifauna presumibilmente protetta. Sono quindi intervenuti i Carabinieri Forestali della Stazione di Brindisi, con il supporto di un veterinario dell\u2019 ASL, riconoscendovi 10 esemplari di piovanello, 17 di piro-piro, 15 di gambecchio, 2 di corriere grosso, 1 di piovanello pancianera, in tutto 45 individui di specie protette ai sensi della legge-quadro nazionale n. 157 dell\u2019 11 febbraio 1992, che fa propria la Direttiva \u201cUccelli\u201d comunitaria 79\/49\/CEE. Gli uccelli, abitatori delle rive fangose di aree umide, erano probabilmente il frutto di ripetute azioni di bracconaggio lungo il litorale brindisino. I Carabinieri Forestali hanno quindi proceduto al sequestro di tutti gli esemplari e delle gabbie. Il conducente del mezzo, E.S. di 64 anni, ed il passeggero, M.C. di&#8230;<\/p>\n","protected":false},"author":2,"featured_media":154629,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-154628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/154628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=154628"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/154628\/revisions"}],"predecessor-version":[{"id":154630,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/154628\/revisions\/154630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/154629"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=154628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=154628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=154628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}