{"id":155133,"date":"2019-05-15T14:06:57","date_gmt":"2019-05-15T12:06:57","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=155133"},"modified":"2019-05-15T19:09:55","modified_gmt":"2019-05-15T17:09:55","slug":"bocciato-il-progetto-del-campo-da-golf-a-francavilla-lopinione-di-articolo-9","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/bocciato-il-progetto-del-campo-da-golf-a-francavilla-lopinione-di-articolo-9\/","title":{"rendered":"Bocciato il progetto del campo da golf a Francavilla: l&#8217;opinione di Articolo 9"},"content":{"rendered":"<p>La questione \u201cCampo da Golf\u201d in agro di Francavilla Fontana merita una valutazione complessiva che parta dall&#8217;iter che ha portato fino al recente pronunciamento della Regione.<br \/>\nNon possiamo infatti esimerci dal sottolineare il ruolo decisivo del processo partecipativo da parte della cittadinanza francavillese rispetto all&#8217;esito di una questione tanto delicata.<br \/>\nForse, per la prima volta nella storia di questa comunit\u00e0, un argomento che solitamente passa solo ed esclusivamente dai tavoli tecnici e della burocrazia, \u00e8 diventato di dominio pubblico. La cittadinanza ha potuto informarsi, partecipare ad incontri, conoscere le sfaccettature e le caratteristiche di un progetto che, indipendentemente dalle proprie percezioni, avrebbe modificato l\u2019assetto di una zona enorme dell\u2019agro di Francavilla Fontana.<br \/>\nUn tema che \u00e8 stato addirittura discusso in Consiglio Comunale per ben due volte, nonostante non vi fosse nessuna delibera da votare o regolamento da licenziare.<br \/>\nIl dibattitto su questa iniziativa privata ha scatenato un momento di democrazia che possiamo oggettivamente definire inedito.<br \/>\n\u00c8 successo, insomma, che la cittadinanza abbia influito attivamente sulle dinamiche di un procedimento che indubbiamente avrebbe intaccato la sfera pubblica.<br \/>\nL\u2019esito arrivato con la Determinazione Regionale del 23.04.2019 e pubblicata nel Bollettino Regionale in data 09.05.2019, \u00e8 solo l\u2019ultimo di tanti passaggi che questa storia ha vissuto.<br \/>\nNoi di Articolo 9 ci eravamo gi\u00e0 espressi in passato sulla contrariet\u00e0 ad un progetto che ritenevamo, dopo averne studiato bene i pro e i contro, essere in contrasto con quello che vogliamo sia il modello di sviluppo che Francavilla Fontana dovrebbe perseguire. Le motivazioni della contrariet\u00e0 sono molteplici e tra queste vogliamo ricordare l\u2019enorme cementificazione prevista nell\u2019intero progetto che non prevedeva solo il campo da golf, lo spostamento di ulivi anche secolari, l\u2019utilizzo di muretti a secco centenari, come semplici linee di demarcazione per i percorsi previsti, l\u2019utilizzo di quantitativi di acqua non pi\u00f9 sostenibili.<br \/>\nL&#8217;aspetto che qui ci preme sottolineare \u00e8 semplicissimo: l\u2019attivismo delle cittadine e dei cittadini, la volont\u00e0 di partecipare ad un percorso, ha apportato indubbiamente un valore aggiunto a tutto l\u2019iter, rilevando delle problematiche e delle eccezioni al progetto che, senza timore di smentita, hanno fatto da pungolo anche a chi ha dovuto prendere le decisioni definitive.<br \/>\nSu questo vogliamo batterci.<br \/>\nSu questo vogliamo porre le nostre attenzioni, sulla possibilit\u00e0 (e la certezza come in questo caso) che la cittadinanza, abbia voce in capitolo. Vogliamo ribadire che non sempre \u00e8 tutto gi\u00e0 deciso. Vogliamo che chiunque sia parte attiva nei processi che determinano il futuro dell\u2019intera comunit\u00e0.<br \/>\nSu queste tematiche si fonda l\u2019attivit\u00e0 di Articolo 9 dentro e fuori dal Consiglio Comunale e, con queste basi, continueremo a lavorare.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Il Movimento Politico<\/strong><br \/>\n<strong>\u201cArticolo 9\u201d<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La questione \u201cCampo da Golf\u201d in agro di Francavilla Fontana merita una valutazione complessiva che parta dall&#8217;iter che ha portato fino al recente pronunciamento della Regione. Non possiamo infatti esimerci dal sottolineare il ruolo decisivo del processo partecipativo da parte della cittadinanza francavillese rispetto all&#8217;esito di una questione tanto delicata. Forse, per la prima volta nella storia di questa comunit\u00e0, un argomento che solitamente passa solo ed esclusivamente dai tavoli tecnici e della burocrazia, \u00e8 diventato di dominio pubblico. La cittadinanza ha potuto informarsi, partecipare ad incontri, conoscere le sfaccettature e le caratteristiche di un progetto che, indipendentemente dalle proprie percezioni, avrebbe modificato l\u2019assetto di una zona enorme dell\u2019agro di Francavilla Fontana. Un tema che \u00e8 stato addirittura discusso in Consiglio Comunale per ben due volte, nonostante non vi fosse nessuna delibera da votare o regolamento da licenziare. Il dibattitto su questa iniziativa privata ha scatenato un momento di democrazia che possiamo oggettivamente definire inedito. \u00c8 successo, insomma, che la cittadinanza abbia influito attivamente sulle dinamiche di un procedimento che&#8230;<\/p>\n","protected":false},"author":2,"featured_media":76760,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-155133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/155133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=155133"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/155133\/revisions"}],"predecessor-version":[{"id":155134,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/155133\/revisions\/155134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/76760"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=155133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=155133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=155133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}