{"id":155163,"date":"2019-05-16T13:42:15","date_gmt":"2019-05-16T11:42:15","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=155163"},"modified":"2019-05-16T14:44:43","modified_gmt":"2019-05-16T12:44:43","slug":"presentata-la-sesta-edizione-di-adotta-un-monumento","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/presentata-la-sesta-edizione-di-adotta-un-monumento\/","title":{"rendered":"Presentata la sesta edizione di \u201cAdotta un monumento\u201d"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/05\/adotta-un-monumento-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-155165\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/05\/adotta-un-monumento-1-300x146.jpeg\" alt=\"\" width=\"300\" height=\"146\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/05\/adotta-un-monumento-1-300x146.jpeg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/05\/adotta-un-monumento-1-768x373.jpeg 768w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/05\/adotta-un-monumento-1-1024x497.jpeg 1024w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/05\/adotta-un-monumento-1.jpeg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Sabato 18 maggio, dalle 10 alle 13, si svolger\u00e0 l\u2019iniziativa \u201cAdotta un monumento\u201d, organizzata da Comune e associazione Le Colonne, che coinvolge le scuole di Brindisi.<\/p>\n<p>Il progetto, giunto alle sesta edizione, mira a sensibilizzare gli studenti su tutela e valorizzazione del patrimonio culturale della citt\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>Le Colonne romane sono state \u201cadottate\u201d dalla scuola secondaria di primo grado \u201cVirgilio\u201d, Palazzo Nervegna e l\u2019area archeologica di San Pietro degli Schiavoni dal Liceo classico \u201cMarzolla\u201d, il Tempio di San Giovanni al Sepolcro dalla secondaria di primo grado \u201cMarzabotto\u201d, la chiesa di San Paolo Eremita, il Monumento ai Caduti e la fontana De Torres di piazza Vittoria dall\u2019Iiss e dal Liceo delle scienze \u201cMajorana, l\u2019area delle Sciabiche dall\u2019Istituto comprensivo Sant\u2019Elia-Commenda, la Palazzina Belvedere dall\u2019Iiss \u201cFerraris De Marco\u201d, il Monumento a Virgilio dall\u2019Istituto comprensivo Centro \u201cSalvemini\u201d, il Monumento nazionale al Marinaio d\u2019Italia dall\u2019Istituto comprensivo Casale \u201cKennedy\u201d e piazza del Salento dal Liceo \u201cPalumbo\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cMi fa particolarmente piacere che i ragazzi e le ragazze delle nostre scuole intraprendano questo percorso di conoscenza del nostro patrimonio monumentale &#8211; spiega il sindaco Riccardo Rossi &#8211; e che poi si facciano promotori, anche nelle loro stesse famiglie, di ci\u00f2 che hanno appreso\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Oltre al sindaco, hanno presentato i dettagli dell\u2019iniziativa per il Comune Antonella Grassi e per l\u2019associazione \u201cLe Colonne\u201d Anna Cinti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 18 maggio, dalle 10 alle 13, si svolger\u00e0 l\u2019iniziativa \u201cAdotta un monumento\u201d, organizzata da Comune e associazione Le Colonne, che coinvolge le scuole di Brindisi. Il progetto, giunto alle sesta edizione, mira a sensibilizzare gli studenti su tutela e valorizzazione del patrimonio culturale della citt\u00e0. &nbsp; Le Colonne romane sono state \u201cadottate\u201d dalla scuola secondaria di primo grado \u201cVirgilio\u201d, Palazzo Nervegna e l\u2019area archeologica di San Pietro degli Schiavoni dal Liceo classico \u201cMarzolla\u201d, il Tempio di San Giovanni al Sepolcro dalla secondaria di primo grado \u201cMarzabotto\u201d, la chiesa di San Paolo Eremita, il Monumento ai Caduti e la fontana De Torres di piazza Vittoria dall\u2019Iiss e dal Liceo delle scienze \u201cMajorana, l\u2019area delle Sciabiche dall\u2019Istituto comprensivo Sant\u2019Elia-Commenda, la Palazzina Belvedere dall\u2019Iiss \u201cFerraris De Marco\u201d, il Monumento a Virgilio dall\u2019Istituto comprensivo Centro \u201cSalvemini\u201d, il Monumento nazionale al Marinaio d\u2019Italia dall\u2019Istituto comprensivo Casale \u201cKennedy\u201d e piazza del Salento dal Liceo \u201cPalumbo\u201d. &nbsp; \u201cMi fa particolarmente piacere che i ragazzi e le ragazze delle nostre scuole intraprendano questo percorso di conoscenza del&#8230;<\/p>\n","protected":false},"author":2,"featured_media":155166,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-155163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/155163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=155163"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/155163\/revisions"}],"predecessor-version":[{"id":155167,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/155163\/revisions\/155167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/155166"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=155163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=155163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=155163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}