{"id":155241,"date":"2019-05-18T16:59:05","date_gmt":"2019-05-18T14:59:05","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=155241"},"modified":"2019-05-18T17:01:16","modified_gmt":"2019-05-18T15:01:16","slug":"domani-a-san-pancrazio-s-no-la-finale-interregionale-di-gazzetta-football-league","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/domani-a-san-pancrazio-s-no-la-finale-interregionale-di-gazzetta-football-league\/","title":{"rendered":"Domani a San Pancrazio S.no la finale interregionale di Gazzetta Football League"},"content":{"rendered":"<p>Domani, domenica 19 maggio, a San Pancrazio Salentino presso il Centro Sportivo Forum Eventi (via Taranto), si terr\u00e0 una delle 8 finali interregionali di Gazzetta Football League, il pi\u00f9 grande campionato di calcio amatoriale d\u2019Italia organizzato in 60 citt\u00e0 da \u201cLa Gazzetta dello Sport\u201d e da Umbro, che sar\u00e0 presente sul posto con il supporto di Sport Leader di Squinzano. Le squadre vincitrici delle competizioni locali di Calcio a 5 di San Pancrazio Salentino, Villa Castelli, Gravina, Manduria, Altamura e quelle che invece hanno vinto i tornei di Calcio a 7 a San Pancrazio, Lecce, Francavilla Fontana e Altamura si contenderanno l\u2019accesso alle finali nazionali di Gazzetta Football League, in programma allo Stadio Olimpico di Roma sabato 1\u00b0giugno.<\/p>\n<p>&nbsp;<\/p>\n<p>Tutte le squadre che partecipano a Gazzetta Football League sono supportate da Umbro, il marchio pi\u00f9 antico del mondo del calcio, fondato in Inghilterra nel 1924 dai fratelli Humphreys, tornato in Italia con l\u2019obiettivo di diventare il marchio del cuore per chi pratica lo street football, per chi crede che il calcio sia ancora uno sport autentico, giocoso e per tutti. Lo storico brand britannico, sponsor tecnico del campionato, punta al coinvolgimento dei veri protagonisti del mondo del calcio. Quel calcio che si gioca per strada, nei centri sportivi, democratico e reale, come i valori di Umbro.<\/p>\n<p>&nbsp;<\/p>\n<p>Ufficio stampa Umbro<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domani, domenica 19 maggio, a San Pancrazio Salentino presso il Centro Sportivo Forum Eventi (via Taranto), si terr\u00e0 una delle 8 finali interregionali di Gazzetta Football League, il pi\u00f9 grande campionato di calcio amatoriale d\u2019Italia organizzato in 60 citt\u00e0 da \u201cLa Gazzetta dello Sport\u201d e da Umbro, che sar\u00e0 presente sul posto con il supporto di Sport Leader di Squinzano. Le squadre vincitrici delle competizioni locali di Calcio a 5 di San Pancrazio Salentino, Villa Castelli, Gravina, Manduria, Altamura e quelle che invece hanno vinto i tornei di Calcio a 7 a San Pancrazio, Lecce, Francavilla Fontana e Altamura si contenderanno l\u2019accesso alle finali nazionali di Gazzetta Football League, in programma allo Stadio Olimpico di Roma sabato 1\u00b0giugno. &nbsp; Tutte le squadre che partecipano a Gazzetta Football League sono supportate da Umbro, il marchio pi\u00f9 antico del mondo del calcio, fondato in Inghilterra nel 1924 dai fratelli Humphreys, tornato in Italia con l\u2019obiettivo di diventare il marchio del cuore per chi pratica lo street football, per chi crede che il&#8230;<\/p>\n","protected":false},"author":2,"featured_media":149784,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,7],"tags":[],"class_list":["post-155241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calcio","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/155241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=155241"}],"version-history":[{"count":3,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/155241\/revisions"}],"predecessor-version":[{"id":155245,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/155241\/revisions\/155245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/149784"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=155241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=155241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=155241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}