{"id":155569,"date":"2019-05-24T07:26:49","date_gmt":"2019-05-24T05:26:49","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=155569"},"modified":"2019-05-24T08:34:26","modified_gmt":"2019-05-24T06:34:26","slug":"antonino-pri-salvate-il-soldato-gimmi","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/antonino-pri-salvate-il-soldato-gimmi\/","title":{"rendered":"Antonino (PRI): &#8220;salvate il soldato Gimmi&#8221;"},"content":{"rendered":"<p>Il 3 dicembre dello scorso anno avevo rivolto al Sindaco una interrogazione urgente per il caso del Signor GIMMI Cosimo.<\/p>\n<p>Si tratta di un ex dipendente del Ministero della Difesa costretto su una sedia a rotelle e che da anni combatte una battaglia per avere un alloggio dignitoso e idoneo alle sue precarie condizioni di salute.<\/p>\n<p>Finalmente sembrava che la sua situazione avesse trovato un rimedio, sia pure temporaneo. Un sogno che si avverava.<\/p>\n<p>Il Signor GIMMI aveva avuto assegnato dal Commissario Prefettizio, in via provvisoria e per sei mesi, un alloggio sequestrato alla criminalit\u00e0 organizzata. Stante l\u2019urgenza e le precarie condizioni economiche e di salute del Signor GIMMI alla deliberazione commissariale era stata data immediata esecutivit\u00e0.<\/p>\n<p>Tanto accadeva il 21 febbraio del 2018!<\/p>\n<p>Purtroppo il Signor GIMMI non aveva fatto i conti con la burocrazia comunale che ha ritenuto l\u2019immobile di dimensioni eccessive rispetto alla composizione del suo nucleo famigliare, disponendone la divisione.<\/p>\n<p>In Consiglio Comunale mi era stato risposto dall\u2019Assessore MASIELLO che la gara era stata svolta, i lavori erano stati assegnati e la ditta doveva solo consegnare la documentazione di rito per avviare finalmente i lavori.<\/p>\n<p>Ad oltre un anno e mezzo dalla data in cui la Deliberazione del Commissario \u00e8 stata adottata il Signor GIMMI non ha ancora potuto prendere possesso dell\u2019alloggio che gli era stato assegnato: nulla si sa sulla esecuzione dei lavori di divisione dell\u2019appartamento e sui tempi di consegna dell\u2019immobile che, magari, come spesso accade, rischia nel frattempo di essere occupato abusivamente da altri nuclei famigliari bisognosi.<\/p>\n<p>A nulla \u00e8 servito anche un esposto presentato dal Signor GIMMI alla Procura della Repubblica per chiedere il rispetto delle proprie ragioni.<\/p>\n<p>Ma la beffa \u00e8 che il Signor GIMMI giorni addietro ha ricevuto una lettera con cui gli si comunica che l\u2019assegnazione provvisoria dell\u2019alloggio \u00e8 stata prorogata al 31 maggio di quest\u2019anno.<\/p>\n<p>Il rischio, quindi, \u00e8 che il Signor GIMMI perda ogni diritto sull\u2019alloggio senza mai aver avuto la possibilit\u00e0 di mettervi piede!<\/p>\n<p>Mi sembra doveroso denunciare pubblicamente quanto accaduto per sottolineare la superficialit\u00e0 on cui si st\u00e0 procedendo ad affrontare un problema gravissimo quale quello della emergenza abitativa.<\/p>\n<p>Che dire: speriamo che qualcuno si decida finalmente a salvare il soldato GIMMI, prima che le cose prendano una piega irreparabile.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>IL CAPOGRUPPO PRI<br \/>\nGabriele ANTONINO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 3 dicembre dello scorso anno avevo rivolto al Sindaco una interrogazione urgente per il caso del Signor GIMMI Cosimo. Si tratta di un ex dipendente del Ministero della Difesa costretto su una sedia a rotelle e che da anni combatte una battaglia per avere un alloggio dignitoso e idoneo alle sue precarie condizioni di salute. Finalmente sembrava che la sua situazione avesse trovato un rimedio, sia pure temporaneo. Un sogno che si avverava. Il Signor GIMMI aveva avuto assegnato dal Commissario Prefettizio, in via provvisoria e per sei mesi, un alloggio sequestrato alla criminalit\u00e0 organizzata. Stante l\u2019urgenza e le precarie condizioni economiche e di salute del Signor GIMMI alla deliberazione commissariale era stata data immediata esecutivit\u00e0. Tanto accadeva il 21 febbraio del 2018! Purtroppo il Signor GIMMI non aveva fatto i conti con la burocrazia comunale che ha ritenuto l\u2019immobile di dimensioni eccessive rispetto alla composizione del suo nucleo famigliare, disponendone la divisione. In Consiglio Comunale mi era stato risposto dall\u2019Assessore MASIELLO che la gara era stata svolta, i&#8230;<\/p>\n","protected":false},"author":2,"featured_media":155572,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-155569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/155569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=155569"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/155569\/revisions"}],"predecessor-version":[{"id":155573,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/155569\/revisions\/155573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/155572"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=155569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=155569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=155569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}