{"id":155884,"date":"2019-05-30T11:13:03","date_gmt":"2019-05-30T09:13:03","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=155884"},"modified":"2019-05-30T09:19:37","modified_gmt":"2019-05-30T07:19:37","slug":"oggi-ad-ostuni-si-presenta-il-corso-teorico-pratico-maestri-lenitori","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/oggi-ad-ostuni-si-presenta-il-corso-teorico-pratico-maestri-lenitori\/","title":{"rendered":"Oggi ad Ostuni si presenta il corso teorico \u2013 pratico \u201cMaestri lenitori\u201d"},"content":{"rendered":"<p>Oggi, alle ore 18.00, presso il Museo Civico di Ostuni verr\u00e0 presentato, nell\u2019 ambito della \u201cSettimana bianca\u201d organizzata dall&#8217; Associazione \u201cLu Scupariedde\u201d, il corso teorico \u2013 pratico \u201cMaestri lenitori\u201d, che si terr\u00e0 nelle prossime settimane. Il corso \u00e8 rivolto a tutti, in special modo nei confronti di maestranze inoccupate e disoccupate del territorio. Lo stesso prevede il rilascio di attestazione di frequentazione al corso stesso, certificato dall\u2019 Ente di formazione edile Edilscuola di Puglia.<\/p>\n<p> Il Presidente della dell\u2019 Edilscuola di Puglia Marcello De Giorgi: \u201c ritiene indispensabile rafforzare la presenza della scuola di formazione sul territorio regionale anche attraverso l\u2019impegno delle piccole imprese e degli artigiani che vantano la conoscenza dei mestieri che ormai sono in disuso nei cantieri edili.<\/p>\n<p>Le imprese iscritte al nostro sistema bilaterale per l\u2019esercizio ottobre 17 \u2013 settembre 18 sono 1.698 con una leggera crescita rispetto al precedente esercizio di 34 imprese. Un dato positivo anche se il settore edile continua a vivere momenti di crisi.<\/p>\n<p>Far crescere le imprese in formazione ed informazione, tramandare i mestieri da mastro anziano al giovane manovale rimane l\u2019impegno della Edilscuola di Puglia &#8211; dichiara il vice presidente Crescenzio Gallo \u2013 un impegno che va affrontato tutti I giorni attraverso I corsi teorici e pratici che vengono predisposti dalla nostra scuola.<\/p>\n<p>Recuperare gli antichi mestieri, dal maestro lenitore, al posatore di sampietrini o al costruttore di muretti a secco, sono alcuni degli impegni che la Edilscuola ha affrontato insieme alla formazione di nuove professionalit\u00e0  che abbisognano oggi per far crescere tutto il sistema dell\u2019edilizia pugliese.<\/p>\n<p>Anche il Presidente Beniamino Farina &#8211;  Associazione \u201cLu Scupariedde\u201d \u2013 plaude all\u2019intervento dell\u2019Edilscuola di Puglia e rivolge un appello: \u201cil corso maestri lenitori \u00e8 un importante punto di partenza al fine di avvicinare maestranze qualificate al bianco, un lavoro oggi necessario non solo per rendere pi\u00f9 bello e attrattivo il nostro territorio ma anche e soprattutto per sostenere i nostri giovani inoccupati e disoccupati al fine di ritrovare nella comunit\u00e0 il senso pi\u00f9 profondo dello stare insieme che si fonda sul lavoro e sulla solidariet\u00e0 sociale\u201d.<\/p>\n<p>Con preghiera di pubblicazione<\/p>\n<p>Presentazione corso Edilscuola.png<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi, alle ore 18.00, presso il Museo Civico di Ostuni verr\u00e0 presentato, nell\u2019 ambito della \u201cSettimana bianca\u201d organizzata dall&#8217; Associazione \u201cLu Scupariedde\u201d, il corso teorico \u2013 pratico \u201cMaestri lenitori\u201d, che si terr\u00e0 nelle prossime settimane. Il corso \u00e8 rivolto a tutti, in special modo nei confronti di maestranze inoccupate e disoccupate del territorio. Lo stesso prevede il rilascio di attestazione di frequentazione al corso stesso, certificato dall\u2019 Ente di formazione edile Edilscuola di Puglia. Il Presidente della dell\u2019 Edilscuola di Puglia Marcello De Giorgi: \u201c ritiene indispensabile rafforzare la presenza della scuola di formazione sul territorio regionale anche attraverso l\u2019impegno delle piccole imprese e degli artigiani che vantano la conoscenza dei mestieri che ormai sono in disuso nei cantieri edili. Le imprese iscritte al nostro sistema bilaterale per l\u2019esercizio ottobre 17 \u2013 settembre 18 sono 1.698 con una leggera crescita rispetto al precedente esercizio di 34 imprese. Un dato positivo anche se il settore edile continua a vivere momenti di crisi. Far crescere le imprese in formazione ed informazione, tramandare&#8230;<\/p>\n","protected":false},"author":2,"featured_media":155889,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-155884","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/155884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=155884"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/155884\/revisions"}],"predecessor-version":[{"id":155890,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/155884\/revisions\/155890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/155889"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=155884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=155884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=155884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}