{"id":156044,"date":"2019-06-03T11:22:57","date_gmt":"2019-06-03T09:22:57","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=156044"},"modified":"2019-06-03T10:56:24","modified_gmt":"2019-06-03T08:56:24","slug":"final-days-la-new-basket-brindisi-e-campione-regionale-u20","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/final-days-la-new-basket-brindisi-e-campione-regionale-u20\/","title":{"rendered":"Final Days: la New Basket Brindisi \u00e8 campione regionale U20"},"content":{"rendered":"<p>Otto giorni di gare, da una domenica all&#8217;altra, undici titoli in palio dall&#8217;under 20 all&#8217;under 13 con 16 gare complessive. E poi ancora il 3&#215;3 all&#8217;aperto, a due passi dal mare, ed il minibasket per i pi\u00f9 piccoli, con il Jamboree ed il Memorial Federici. Si \u00e8 rinnovata a Bari, per il terzo anno di fila, la magia dei Final Days di pallacanestro giovanile, la kermesse ideata dal comitato Fip Puglia per raggruppare in un&#8217;unica sede le finali dei campionati regionali non ancora disputate. E&#8217; stato ancora una volta il Centro Universitario Sportivo di lungomare Starita a far da crocevia delle ambizioni di centinaia di giovani cestisti, ospitando le attivit\u00e0 indoor e oudoor.<\/p>\n<p>Nel campionato under 20, successo per New Basket Brindisi su Mola New Basket. Tris di coppe per Murgia Santeramo, in altrettanti finali giocate: al titolo U14 Elite si sono aggiunte, una dopo l&#8217;altra, le vittorie in under 13 Elite e under 15 Oro, l&#8217;ultima contro Progetto Cestistica San Severo. La societ\u00e0 foggiana, dal canto suo, pu\u00f2 consolarsi con l&#8217;affermazione in under 18 Platino, contro Aurora Brindisi. Bozzano Brindisi si aggiudica l&#8217;unica finale femminile, quella valevole per il titolo under 14, mentre nelle finali Oro festeggiano Angel Manfredonia (under 18), Nuova Pallacanestro Monteroni (under 16), Basket Lucera (under 14) e Nuova Matteotti Corato (under 13). Per Manfredonia anche la soddisfazione di vincere una fina<a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/U20-M-New-Bk-Brindisi-Mola-New-Basket-2012-rid2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-156045\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/U20-M-New-Bk-Brindisi-Mola-New-Basket-2012-rid2-300x270.jpg\" alt=\"\" width=\"300\" height=\"270\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/U20-M-New-Bk-Brindisi-Mola-New-Basket-2012-rid2-300x270.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/U20-M-New-Bk-Brindisi-Mola-New-Basket-2012-rid2-768x691.jpg 768w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/U20-M-New-Bk-Brindisi-Mola-New-Basket-2012-rid2-1024x921.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>le Argento, condivisa con Basket Noicattaro, Cestistica Ostuni, New Basket Barletta e Devils Nard\u00f2. La finale U16 Ferro \u00e8 invece andata ad Anspi Santa Rita.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abE&#8217; cresciuto l&#8217;impegno organizzativo \u2013 osserva la presidente Fip Puglia Margaret Gonnella \u2013 ma \u00e8 aumentata la soddisfazione dei partecipanti. Abbiamo aperto il programma a quante pi\u00f9 finali possibili perch\u00e9 crediamo nel confronto e nell&#8217;attivit\u00e0 giovanile. E alla possibilit\u00e0 di dare ad ogni livello il piacere di giocare la propria partita in un unico grande evento\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>Ora il testimone passa al 3&#215;3, con le finali nazionali under 18 e under 16 in programma a Castellana Grotte a fine mese: a rappresentare la Puglia ci saranno Aurora Brindisi e Lions Bisceglie fra i ragazzi, Nuova Matteotti Corato e VoloRosa Brindisi fra le ragazze: \u00abAnche per l&#8217;estate \u2013 ricorda Gonnella \u2013 lavoriamo per offrire del buon basket in Puglia. Prima le finali nazionali under 16 di Eccellenza di Taranto, quindi le finali giovanili 3&#215;3 che stanno offrendo un valore aggiunto alle bellezze di Grotte di Castellana. E poi, a settembre, il PalaFlorio di Bari ospiter\u00e0 la Supercoppa 2019\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>I risultati delle finali<br \/>\nU20 M New Basket Brindisi-Mola New Basket 2012 87-68<br \/>\nU14 M Elite Murgia Santeramo-New Bk Brindisi 77-75<br \/>\nU14 F Anspi Santa Rita Taranto-Bozzano Brindisi 43-56<br \/>\nU13 M Elite New Basket Brindisi-Murgia Santeramo 56-61<br \/>\nU18 M Platino Aurora Brindisi-Progetto Cestistica San Severo 74-80 dts<br \/>\nU18 M Oro Angel Manfredonia-Asia Bats Acquaviva 86-35<br \/>\nU16 M Oro Progetto Cestistica San Severo-Nuova Pallacanestro Monteroni 43-66<br \/>\nU15 M Oro Murgia Santeramo-Progetto Cestistica San Severo 56-49<br \/>\nU14 M Oro Nuova Pall. Grottaglie-Bk Lucera 69-70<br \/>\nU13 M Oro Nuova Matteotti Corato-Angiulli Bari 63-53<br \/>\nU16 M Ferro Anspi Santa Rita Taranto-Virtus Foggia 60-57<br \/>\nU18 M Argento Bk Noicattaro-Nuova Libertas Foggia 61-52<br \/>\nU16 M Argento Cestistica Ostuni-Ags Toritto 56-54<br \/>\nU15 M Argento New Basket Barletta-Varansport 56-46<br \/>\nU14 M Argento Angel Manfredonia-New Jt Trani 65-38<br \/>\nU13 M Argento Basket Francavilla-Devils Nard\u00f2 50-58<\/p>\n<p>3&#215;3<br \/>\nU18 M: Aurora Brindisi<br \/>\nU16 M: Lions Bisceglie<br \/>\nU18 F: Nuova Matteotti Corato<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Otto giorni di gare, da una domenica all&#8217;altra, undici titoli in palio dall&#8217;under 20 all&#8217;under 13 con 16 gare complessive. E poi ancora il 3&#215;3 all&#8217;aperto, a due passi dal mare, ed il minibasket per i pi\u00f9 piccoli, con il Jamboree ed il Memorial Federici. Si \u00e8 rinnovata a Bari, per il terzo anno di fila, la magia dei Final Days di pallacanestro giovanile, la kermesse ideata dal comitato Fip Puglia per raggruppare in un&#8217;unica sede le finali dei campionati regionali non ancora disputate. E&#8217; stato ancora una volta il Centro Universitario Sportivo di lungomare Starita a far da crocevia delle ambizioni di centinaia di giovani cestisti, ospitando le attivit\u00e0 indoor e oudoor. Nel campionato under 20, successo per New Basket Brindisi su Mola New Basket. Tris di coppe per Murgia Santeramo, in altrettanti finali giocate: al titolo U14 Elite si sono aggiunte, una dopo l&#8217;altra, le vittorie in under 13 Elite e under 15 Oro, l&#8217;ultima contro Progetto Cestistica San Severo. La societ\u00e0 foggiana, dal canto suo, pu\u00f2 consolarsi&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-156044","post","type-post","status-publish","format-standard","hentry","category-basket"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/156044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=156044"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/156044\/revisions"}],"predecessor-version":[{"id":156046,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/156044\/revisions\/156046"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=156044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=156044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=156044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}