{"id":156335,"date":"2019-06-09T15:00:26","date_gmt":"2019-06-09T13:00:26","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=156335"},"modified":"2019-06-09T15:58:09","modified_gmt":"2019-06-09T13:58:09","slug":"picchiano-linquilina-marocchina-denunciati-proprietaria-dellappartamento-e-il-suo-compagno","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/picchiano-linquilina-marocchina-denunciati-proprietaria-dellappartamento-e-il-suo-compagno\/","title":{"rendered":"Picchiano l&#8217;inquilina marocchina: denunciati proprietaria dell&#8217;appartamento e il suo compagno"},"content":{"rendered":"<p>I Carabinieri della Stazione di Latiano, al termine degli accertamenti, hanno deferito in stato di libert\u00e0 una coppia di conviventi, un 56enne e una 53enne, entrambi del luogo, per violazione di domicilio, esercizio arbitrario delle proprie ragioni con violenza sulle persone e ingiuria.<\/p>\n<p>I predetti, qualche giorno fa, si sono recati presso un\u2019abitazione di loro propriet\u00e0 dove vive, in affitto, una 35enne di origine marocchina con il figlio minore. Dopo essere entrati, senza alcuna autorizzazione, all\u2019interno della casa hanno  cominciato a inveire contro la donna, minacciandola di buttarla fuori, e successivamente hanno iniziato a sfasciare tutto, percuotendola anche violentemente al volto, tutto per il mancato pagamento di alcune mensilit\u00e0 relative alla locazione dell\u2019immobile.<\/p>\n<p>La vittima \u00e8 dovuta ricorrere alla cure mediche dei sanitari dell\u2019Ospedale Perrino di Brindisi, che l\u2019hanno riscontrata affetta da \u201ctrauma facciale con edema\u201d e giudicata guaribile in gg. 7 s.c.<\/p>\n<p>L\u2019uomo deferito in stato di libert\u00e0 era stato gi\u00e0 tratto in arresto all\u2019inizio dell\u2019anno per maltrattamenti nei confronti di un familiare e a seguito della sua scarcerazione fu sottoposto alla misura cautelare del divieto di avvicinamento alla vittima, misura alla quale \u00e8 ancora sottoposto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Carabinieri della Stazione di Latiano, al termine degli accertamenti, hanno deferito in stato di libert\u00e0 una coppia di conviventi, un 56enne e una 53enne, entrambi del luogo, per violazione di domicilio, esercizio arbitrario delle proprie ragioni con violenza sulle persone e ingiuria. I predetti, qualche giorno fa, si sono recati presso un\u2019abitazione di loro propriet\u00e0 dove vive, in affitto, una 35enne di origine marocchina con il figlio minore. Dopo essere entrati, senza alcuna autorizzazione, all\u2019interno della casa hanno cominciato a inveire contro la donna, minacciandola di buttarla fuori, e successivamente hanno iniziato a sfasciare tutto, percuotendola anche violentemente al volto, tutto per il mancato pagamento di alcune mensilit\u00e0 relative alla locazione dell\u2019immobile. La vittima \u00e8 dovuta ricorrere alla cure mediche dei sanitari dell\u2019Ospedale Perrino di Brindisi, che l\u2019hanno riscontrata affetta da \u201ctrauma facciale con edema\u201d e giudicata guaribile in gg. 7 s.c. L\u2019uomo deferito in stato di libert\u00e0 era stato gi\u00e0 tratto in arresto all\u2019inizio dell\u2019anno per maltrattamenti nei confronti di un familiare e a seguito della sua scarcerazione&#8230;<\/p>\n","protected":false},"author":2,"featured_media":152444,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-156335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/156335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=156335"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/156335\/revisions"}],"predecessor-version":[{"id":156338,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/156335\/revisions\/156338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/152444"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=156335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=156335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=156335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}