{"id":156339,"date":"2019-06-09T11:58:24","date_gmt":"2019-06-09T09:58:24","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=156339"},"modified":"2019-06-09T16:00:39","modified_gmt":"2019-06-09T14:00:39","slug":"tenta-di-cambiare-tre-banconote-false-denunciato-peruviano","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/tenta-di-cambiare-tre-banconote-false-denunciato-peruviano\/","title":{"rendered":"Tenta di cambiare tre banconote false: denunciato peruviano"},"content":{"rendered":"<p>I Carabinieri della Stazione di Fasano, al termine degli accertamenti, hanno deferito in stato di libert\u00e0 un 50enne residente a Roma per il reato di truffa e spendita di banconote false.<\/p>\n<p>L\u2019uomo ha dapprima approfittato del rapporto conoscenza con un pensionato del luogo, quindi si \u00e8 fatto cambiare due banconote da 100 \u20ac e una da 50, che sono poi risultate false, e si \u00e8 fatto consegnare il corrispettivo in contanti di piccolo taglio. Subito dopo si \u00e8 dileguato a piedi, facendo perdere le proprie tracce. Banconote sottoposte a sequestro. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Carabinieri della Stazione di Fasano, al termine degli accertamenti, hanno deferito in stato di libert\u00e0 un 50enne residente a Roma per il reato di truffa e spendita di banconote false. L\u2019uomo ha dapprima approfittato del rapporto conoscenza con un pensionato del luogo, quindi si \u00e8 fatto cambiare due banconote da 100 \u20ac e una da 50, che sono poi risultate false, e si \u00e8 fatto consegnare il corrispettivo in contanti di piccolo taglio. Subito dopo si \u00e8 dileguato a piedi, facendo perdere le proprie tracce. Banconote sottoposte a sequestro.<\/p>\n","protected":false},"author":2,"featured_media":20398,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-156339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/156339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=156339"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/156339\/revisions"}],"predecessor-version":[{"id":156340,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/156339\/revisions\/156340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/20398"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=156339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=156339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=156339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}