{"id":156441,"date":"2019-06-11T07:37:06","date_gmt":"2019-06-11T05:37:06","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=156441"},"modified":"2019-06-11T06:40:46","modified_gmt":"2019-06-11T04:40:46","slug":"taberna-book-festival-dal-18-giugno-a-latiano-un-percorso-di-libri-musica-teatro-ed-enogastronomia","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/taberna-book-festival-dal-18-giugno-a-latiano-un-percorso-di-libri-musica-teatro-ed-enogastronomia\/","title":{"rendered":"Taberna Book Festival: dal 18 Giugno a Latiano un percorso di libri, musica, teatro ed enogastronomia"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/Frontale-locandina-TBF2019.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-156442\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/Frontale-locandina-TBF2019-196x300.jpg\" alt=\"\" width=\"196\" height=\"300\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/Frontale-locandina-TBF2019-196x300.jpg 196w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/Frontale-locandina-TBF2019.jpg 458w\" sizes=\"auto, (max-width: 196px) 100vw, 196px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Un evento culturale che coinvolge grandi e piccoli in un percorso di libri, musica, teatro ed enogastronomia.<\/p>\n<p>\u00c8 questa la definizione che meglio descrive il Taberna Book Festival, la 4 giorni estiva targata Taberna Libraria patrocinata dell\u2019Amministrazione Comunale di Latiano e in programma dal 18 al 21 giugno 2019 presso la Galleria Commerciale in via Francesco D\u2019Ippolito-Via Roma.<\/p>\n<p>&nbsp;<\/p>\n<p>La Kermesse culturale \u00e8 stata presentata nel pomeriggio di oggi, luned\u00ec 10 giugno 2019, presso la Sala Flora del Comune di Latiano nel corso di una conferenza stampa, moderata dal giornalista Nico Lorusso alla presenza del Sindaco Mino Maiorano, del Responsabile dell\u2019Area Eventi di Taberna Libraria Paolo Legrottaglie, del Responsabile dell\u2019Associazione Taberna Teatrale, l\u2019attore Daniele Barletta, di Raffaele De Vivo di De Vivo Home Design e del Prof Cosimo Galasso della Pro Loco di Latiano.<\/p>\n<p>&nbsp;<\/p>\n<p>Nel corso dell\u2019incontro \u00e8 stato reso noto il programma degli appuntamenti di alto livello culturale previsti durante le giornate interessate dalla manifestazione e di seguito indicati<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/Il-Programma-del-TBF2019.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-156443 alignright\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/Il-Programma-del-TBF2019-300x240.jpg\" alt=\"\" width=\"300\" height=\"240\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/Il-Programma-del-TBF2019-300x240.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/Il-Programma-del-TBF2019.jpg 700w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/>\n<\/a>Marted\u00ec 18 giugno:<br \/>\n&#8211; Ore 17 Apertura Festival \u2013 Animazione a cura degli Studenti del \u201cLiceo Palumbo\u201d di Latiano<br \/>\n&#8211; Ore 19 \u201cRocco e lo scirocco\u201d \u2013 Fiaba musicale di Cantacunti compagnia di Cantastorie di Maria Rosaria Coppola e Gianni Vico<br \/>\n&#8211; Ore 21 Once upon a Time 1969 \u2013 Spettacolo ricordando il 1969, a 50 anni dal primo uomo sulla Luna. Direzione musicale del Maestro Mimmo Ann\u00e8. Presenta la serata Raffaele Romano.<\/p>\n<p>&nbsp;<\/p>\n<p>Mercoled\u00ec 19 giugno:<br \/>\n&#8211; Ore 17 Apertura Stand<br \/>\n&#8211; Ore 18 \u201cI miei nonni giocavano cos\u00ec\u201d \u2013 Giochi Antichi per bambini, il gioco dell\u2019Oca umano<br \/>\n&#8211; Ore 21 Presentazione del libro La ballata dei sassi con l\u2019autore Carlos Solito, intermezzo teatrale a cura di Tonino Papadia [Premio alla Cultura Samadi]. Presenta la serata Raffaele Romano.<\/p>\n<p>Gioved\u00ec 20 giugno:<br \/>\n&#8211; Ore 16 Secondo Torneo Amatoriale di Scacchi in collaborazione con la A.D. Scacchi Brindisi<br \/>\n&#8211; Ore 17 Apertura Stand<br \/>\n&#8211; Ore 18 \u201cPresentazione giochi da tavola\u201d \u2013 Spazio ludico di partecipazione attiva<br \/>\n&#8211; Ore 21 \u201cPoeti Cantastorie e musica da barberia\u201d, di e con Tonino Zurlo [Premio alla cultura Samadi] Mauro Semeraro \u2013 mandolino, Giovanni Palma \u2013 chitarra<\/p>\n<p>&nbsp;<\/p>\n<p>Venerd\u00ec 21 giugno:<br \/>\n&#8211; Ore 16:30 \u201cEd ora bagnamoci tutti\u201d giochi d\u2019acqua a squadre<br \/>\n&#8211; Ore 17 Apertura Stand<br \/>\n&#8211; Ore 18 Gare podistiche a cura di ASD Olimpo Latiano<br \/>\n&#8211; Ore 19 Presentazione del libro Una storia all\u2019italiana con l\u2019autore Michele Camassa. Presenta Paolo Franza<br \/>\n&#8211; Ore 21 Meravigliosamente Puglia \u2013 spettacolo con la partecipazione di Ada Acquaviva, Daniele Barletta e Palma Caliandro e con la partecipazione straordinaria di Gino Cesaria e Tani Roma [Premi alla cultura Samadi]<\/p>\n<p>&nbsp;<\/p>\n<p>Ogni mattina, dalle 9:30 alle 12:30 giochi e laboratori all\u2019aperto.<\/p>\n<p>&nbsp;<\/p>\n<p>Ufficio Stampa SummerTime \u2013 Animazione &amp; Spettacolo<br \/>\nPer Taberna Libraria<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Un evento culturale che coinvolge grandi e piccoli in un percorso di libri, musica, teatro ed enogastronomia. \u00c8 questa la definizione che meglio descrive il Taberna Book Festival, la 4 giorni estiva targata Taberna Libraria patrocinata dell\u2019Amministrazione Comunale di Latiano e in programma dal 18 al 21 giugno 2019 presso la Galleria Commerciale in via Francesco D\u2019Ippolito-Via Roma. &nbsp; La Kermesse culturale \u00e8 stata presentata nel pomeriggio di oggi, luned\u00ec 10 giugno 2019, presso la Sala Flora del Comune di Latiano nel corso di una conferenza stampa, moderata dal giornalista Nico Lorusso alla presenza del Sindaco Mino Maiorano, del Responsabile dell\u2019Area Eventi di Taberna Libraria Paolo Legrottaglie, del Responsabile dell\u2019Associazione Taberna Teatrale, l\u2019attore Daniele Barletta, di Raffaele De Vivo di De Vivo Home Design e del Prof Cosimo Galasso della Pro Loco di Latiano. &nbsp; Nel corso dell\u2019incontro \u00e8 stato reso noto il programma degli appuntamenti di alto livello culturale previsti durante le giornate interessate dalla manifestazione e di seguito indicati &nbsp; Marted\u00ec 18 giugno: &#8211; Ore 17 Apertura&#8230;<\/p>\n","protected":false},"author":2,"featured_media":156444,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-156441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/156441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=156441"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/156441\/revisions"}],"predecessor-version":[{"id":156445,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/156441\/revisions\/156445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/156444"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=156441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=156441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=156441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}