{"id":15696,"date":"2014-06-17T15:54:13","date_gmt":"2014-06-17T13:54:13","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=15696"},"modified":"2014-06-17T19:56:38","modified_gmt":"2014-06-17T17:56:38","slug":"tutte-le-partite-della-nazionale-italiana-su-maxischermo-al-multisala-andromeda","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/tutte-le-partite-della-nazionale-italiana-su-maxischermo-al-multisala-andromeda\/","title":{"rendered":"Tutte le partite della Nazionale Italiana su maxischermo al Multisala Andromeda"},"content":{"rendered":"<p>Il tricolore sventola nel <strong>Maxicinema Andromeda<\/strong> di Brindisi. In occasione dei <strong>Campionati Mondiali di calcio 2014<\/strong> in Brasile, il multisala del capoluogo <strong>offre ai brindisini la possibilit\u00e0 di assistere alla proiezione in HD su schermo cinematografico delle partite della Nazionale Italiana<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Con soli <strong>3 euro<\/strong>, la comodit\u00e0 di una poltrona riservata, il comfort dell\u2019aria condizionata, il coinvolgimento sonoro grazie al dolby surround, la magnificenza di immagini ad alta definizione si potranno seguire le gesta degli azzurri di Prandelli con la sensazione di assistere dal vivo all\u2019evento sportivo dell\u2019anno.<\/p>\n<p>&nbsp;<\/p>\n<p>Il prossimo <strong>20 giugno<\/strong> (venerd\u00ec), <strong>a partire dalle 18<\/strong>, sar\u00e0 quindi possibile seguire la <strong>gara tra Italia e Costa Rica<\/strong>, secondo incontro della nazionale nel girone D del mondiale carioca. <strong>Terzo appuntamento<\/strong>, invece, per <strong>marted\u00ec 24 giugno<\/strong> sempre alle 18 per tifare ancora tutti insieme.<\/p>\n<p>&nbsp;<\/p>\n<p>Un&#8217;altra iniziativa che il Maxicinema Andromeda di Brindisi mette in atto a favore dei propri clienti creando un modo alternativo di condividere la passione per il calcio, che mira a coinvolgere l\u2019intera cittadinanza favorendo momenti di aggregazione.<\/p>\n<p>&nbsp;<\/p>\n<p>La struttura cinematografica brindisina offre comunque diversi spunti adatti ai palati pi\u00f9 difficili, con una vasta e attrezzata area intrattenimento sia all\u2019interno che all\u2019esterno dei locali adiacenti l\u2019ampio parcheggio.<\/p>\n<p>&nbsp;<\/p>\n<p>Il multisala brindisino si candida cos\u00ec a protagonista della stagione estiva rispondendo presente a tutte le partite che saranno disputate dalla Nazionale italiana per i Mondiali di Calcio 2014.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il tricolore sventola nel Maxicinema Andromeda di Brindisi. In occasione dei Campionati Mondiali di calcio 2014 in Brasile, il multisala del capoluogo offre ai brindisini la possibilit\u00e0 di assistere alla proiezione in HD su schermo cinematografico delle partite della Nazionale Italiana. &nbsp; Con soli 3 euro, la comodit\u00e0 di una poltrona riservata, il comfort dell\u2019aria condizionata, il coinvolgimento sonoro grazie al dolby surround, la magnificenza di immagini ad alta definizione si potranno seguire le gesta degli azzurri di Prandelli con la sensazione di assistere dal vivo all\u2019evento sportivo dell\u2019anno. &nbsp; Il prossimo 20 giugno (venerd\u00ec), a partire dalle 18, sar\u00e0 quindi possibile seguire la gara tra Italia e Costa Rica, secondo incontro della nazionale nel girone D del mondiale carioca. Terzo appuntamento, invece, per marted\u00ec 24 giugno sempre alle 18 per tifare ancora tutti insieme. &nbsp; Un&#8217;altra iniziativa che il Maxicinema Andromeda di Brindisi mette in atto a favore dei propri clienti creando un modo alternativo di condividere la passione per il calcio, che mira a coinvolgere l\u2019intera cittadinanza favorendo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":15697,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,7,8],"tags":[1676,2116],"class_list":["post-15696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calcio","category-news","category-sport","tag-andromeda","tag-mondiali-2014"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/15696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=15696"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/15696\/revisions"}],"predecessor-version":[{"id":15698,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/15696\/revisions\/15698"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/15697"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=15696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=15696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=15696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}