{"id":157013,"date":"2019-06-24T18:13:55","date_gmt":"2019-06-24T16:13:55","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=157013"},"modified":"2019-07-06T14:58:06","modified_gmt":"2019-07-06T12:58:06","slug":"le-prime-immagini-dei-reperti-archeologici-di-valore-inestimabile-ritrovati-nello-specchio-di-mare-antistante-il-litorale-brindisino","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/le-prime-immagini-dei-reperti-archeologici-di-valore-inestimabile-ritrovati-nello-specchio-di-mare-antistante-il-litorale-brindisino\/","title":{"rendered":"Le prime immagini dei reperti archeologici di valore inestimabile ritrovati nello specchio di mare antistante il litorale brindisino"},"content":{"rendered":"\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-157013 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.brundisium.net\/index.php\/le-prime-immagini-dei-reperti-archeologici-di-valore-inestimabile-ritrovati-nello-specchio-di-mare-antistante-il-litorale-brindisino\/reperti-archeologici-fondali-brindisi-1\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/reperti-archeologici-fondali-brindisi-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/reperti-archeologici-fondali-brindisi-1-150x150.jpg 150w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/reperti-archeologici-fondali-brindisi-1-600x600.jpg 600w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/reperti-archeologici-fondali-brindisi-1-60x60.jpg 60w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.brundisium.net\/index.php\/le-prime-immagini-dei-reperti-archeologici-di-valore-inestimabile-ritrovati-nello-specchio-di-mare-antistante-il-litorale-brindisino\/reperti-archeologici-fondali-brindisi-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/reperti-archeologici-fondali-brindisi-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/reperti-archeologici-fondali-brindisi-3-150x150.jpg 150w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/reperti-archeologici-fondali-brindisi-3-600x600.jpg 600w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/reperti-archeologici-fondali-brindisi-3-60x60.jpg 60w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.brundisium.net\/index.php\/le-prime-immagini-dei-reperti-archeologici-di-valore-inestimabile-ritrovati-nello-specchio-di-mare-antistante-il-litorale-brindisino\/reperti-archeologici-fondali-brindisi-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/reperti-archeologici-fondali-brindisi-4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/reperti-archeologici-fondali-brindisi-4-150x150.jpg 150w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/reperti-archeologici-fondali-brindisi-4-600x600.jpg 600w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/06\/reperti-archeologici-fondali-brindisi-4-60x60.jpg 60w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>Nei primi giorni della stagione estiva, grazie all\u2019attenzione e l&#8217;impegno quotidiano che il Corpo delle Capitanerie di Porto &#8211; Guardia Costiera rivolge nel contesto della preservazione e tutela del patrimonio storico-archeologico nazionale, anche con l\u2019ausilio dei propri mezzi e dei subacquei del Nucleo Sommozzatori di San Benedetto del Tronto si \u00e8 giunti al ritrovamento di alcuni frammenti archeologici presso il litorale brindisino, tra Punta del Serrone e l\u2019Area Marina Protetta di Torre Guaceto.<\/p>\n<p>&nbsp;<\/p>\n<p>La bonifica dell\u2019intera area ha portato al recupero di reperti archeologici. In particolare, si possono annoverare: n. 25 (venticinque) frammenti ceramici di anfore di varia forma; n. 1 anfora con anse senza fondo; n. 3 colli di anfore con anse; n. 1 collo di anfora con ansa; n. 1 parte di anfora, con collo, anse e pancia; n. 1 piede di anfora con frammento pancia facente parte dell\u2019anfora precedente; n. 1 frammento di fondo di piatto; n. 3 colli di anfore con anse; n. 1 frammento di collo di anfora senza ansa; n. 1 frammento di fondo di anfora e una bigotta con landa di una nave a vela.<\/p>\n<p>&nbsp;<\/p>\n<p>Tali reperti risalgono ad epoche differenti; i pi\u00f9 antichi si possono datare a partire dal II Sec. A.C. fino all\u2019epoca tardo imperiale.<br \/>\nCon la supervisione della Soprintendenza Archeologia e Belle Arti delle Provincie di Brindisi, Lecce e Taranto sono state avanzate varie ipotesi ancora sotto indagine.<\/p>\n<p>&nbsp;<\/p>\n<p>Di particolare importanza \u00e8 stato il ritrovamento di pezzi di un\u2019anfora di Forlimpopoli, testimonianza dei numerosi scambi commerciali di quella antica citt\u00e0 con il Salento.<\/p>\n<p>Da ultimo, ma non per rilevanza, \u00e8 stata trovata una bigotta con landa di una nave a vela molto probabilmente riconducibile ad un relitto del 1600.<\/p>\n<p>&nbsp;<\/p>\n<p>Tutto il materiale \u00e8 stato temporaneamente affidato alla Capitaneria di Porto di Brindisi, per il successivo trasferimento alla Soprintendenza.<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;operazione di ritrovamento dei giorni scorsi rappresenta, in sintesi, l&#8217;attenzione e l&#8217;impegno quotidiano che il Corpo delle Capitanerie di Porto &#8211; Guardia Costiera rivolge nel contesto della tutela del patrimonio storico-archeologico nazionale, anche ai sensi del Decreto Ministeriale 12 luglio 89 \u201cDisposizioni per la tutela delle aree marine di interesse storico, artistico o archeologico\u201d che attribuisce al Corpo proprio questa competenza in mare.<\/p>\n<p>&nbsp;<\/p>\n<p>Si ricorda che per informazioni il personale della Capitaneria di porto &#8211; Guardia Costiera di Brindisi \u00e8 sempre disponibile al numero 0831521022 e mail cp.brindisi@mit.gov.it, mentre permane attivo 24 ore su 24, 7 giorni su 7 il numero blu 1530 da utilizzarsi esclusivamente per segnalare eventuali emergenze in mare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nei primi giorni della stagione estiva, grazie all\u2019attenzione e l&#8217;impegno quotidiano che il Corpo delle Capitanerie di Porto &#8211; Guardia Costiera rivolge nel contesto della preservazione e tutela del patrimonio storico-archeologico nazionale, anche con l\u2019ausilio dei propri mezzi e dei subacquei del Nucleo Sommozzatori di San Benedetto del Tronto si \u00e8 giunti al ritrovamento di alcuni frammenti archeologici presso il litorale brindisino, tra Punta del Serrone e l\u2019Area Marina Protetta di Torre Guaceto. &nbsp; La bonifica dell\u2019intera area ha portato al recupero di reperti archeologici. In particolare, si possono annoverare: n. 25 (venticinque) frammenti ceramici di anfore di varia forma; n. 1 anfora con anse senza fondo; n. 3 colli di anfore con anse; n. 1 collo di anfora con ansa; n. 1 parte di anfora, con collo, anse e pancia; n. 1 piede di anfora con frammento pancia facente parte dell\u2019anfora precedente; n. 1 frammento di fondo di piatto; n. 3 colli di anfore con anse; n. 1 frammento di collo di anfora senza ansa; n. 1 frammento di&#8230;<\/p>\n","protected":false},"author":2,"featured_media":157051,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-157013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=157013"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157013\/revisions"}],"predecessor-version":[{"id":157054,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157013\/revisions\/157054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/157051"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=157013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=157013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=157013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}