{"id":157016,"date":"2019-06-24T09:25:45","date_gmt":"2019-06-24T07:25:45","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=157016"},"modified":"2019-06-24T13:28:10","modified_gmt":"2019-06-24T11:28:10","slug":"torre-santa-susanna-cia-pronta-per-terreni-confiscati-e-iniziative-anti-xylella","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/torre-santa-susanna-cia-pronta-per-terreni-confiscati-e-iniziative-anti-xylella\/","title":{"rendered":"Torre Santa Susanna: CIA pronta per terreni confiscati e iniziative anti-Xylella"},"content":{"rendered":"<p>Due giorni a Torre Santa Susanna, in provincia di Brindisi, per l\u2019ottimismo e per superare la crisi che la Xylella e il maltempo hanno gettato sulla produzione agricola pugliese.<br \/>\nCon CIA-Agricoltori Italiani, Slow Food Italia, Gal del Primitivo, il Sindaco Michele Saccomanno e l\u2019intera Amministrazione comunale hanno preparato degustazioni e convegni, hanno presentato la Guida degli oli extravergini e premiato i migliori produttori italiani.<br \/>\n\u00c8 stato suggellato un patto tra Istituzioni e mondo del lavoro inaugurando un monumento vivo alla tradizione e alle speranze: il Museo dell\u2019olio e delle olive. Radici e prospettive trasferite con la ricchezza della conoscenza.<br \/>\nHanno partecipato, oltre al Sindaco e all\u2019intera Amministrazione, il Prefetto di Brindisi Umberto Guidato, il Vescovo di Oria Mons. Vincenzo Pisanello, l\u2019Assessore Regionale Loredana Capone, il Generale dei Carabinieri forestali Danilo Mostacchi, Francesca Baldereschi di Slow Food Italia, il Sovrintendente delle Belle Arti Carmelo Di Fonzo, Marcello Longo per Slow Food Puglia<br \/>\nPer CIA Agricoltori Italiani hanno partecipato Cinzia Pagni, presidente di ASeS-Agricoltori, Solidariet\u00e0 e Sviluppo, Pietro De Padova, presidente CIA Due Mari (Taranto \u2013Brindisi), Vito Rubino, direttore CIA Due Mari (Taranto-Brindisi) e Giannicola D\u2019Amico, vicepresidente CIA Puglia.<br \/>\nASeS e CIA hanno rinnovato l\u2019impegno a svolgere sul territorio iniziative di implementazione di pratiche di agricoltura sociale a favore dei pi\u00f9 deboli e hanno confermato la disponibilit\u00e0 a portare avanti un progetto di rinascita di alcuni terreni confiscati alla mafia ed affidati al Comune di Torre Santa Susanna, prevedendo anche la realizzazione di iniziative anti-Xylella.<br \/>\nCIA ha, inoltre, confermato l\u2019impegno a favore degli olivicoltori pugliesi e brindisini in questa particolare fase di congiunture negative \u2013 dovuta a calamit\u00e0 naturali e alla emergenza Xylella \u2013 evidenziando come iniziative come quelle della Guida agli extravergini presentata da Slow Food non fanno che valorizzare un comparto importantissimo per l\u2019economia territoriale, di fatto smentendo le tendenziose voci che circolano sui mercati internazionali che danno l\u2019olio di oliva pugliese infetto da Xylella. Nulla di pi\u00f9 falso, perch\u00e9 il batterio Xylella non attacca le drupe ma bens\u00ec la parte legnosa delle piante.<br \/>\nCIA Due Mari, infine, ha curato anche la presentazione ed esposizione di prodotti agricoli di eccellenza del territorio (vino, olio, confetture, funghi, ciliegie, albicocche, pomodori, prodotti da forno, etc), coordinando la partecipazione delle seguenti aziende associate:<br \/>\nAzienda agricola Mero Lorenzo &#8211; Avetrana (olio);<br \/>\nAzienda agricola San Francesco &#8211; Avetrana (olio);<br \/>\nTenuta Canneddi &#8211; Avetrana (olio e vino);<br \/>\nCazzolla Anastasio &#8211; Avetrana (olio);<br \/>\nAgriturismo Marina Piccola &#8211; Avetrana (olio, olive e vino);<br \/>\nAzienda agricola biodinamica Lacalamita Rosa (salsa e confetture) &#8211; Castellaneta;<br \/>\nFunghi e ballette De Biasi &#8211; Castellaneta;<br \/>\nAzienda agricola Di Cristo (albicocche) &#8211; Palagianello;<br \/>\nAzienda agricola Le Grotte di Sileno (vino e olio) &#8211; Castellaneta;<br \/>\nAzienda sinergica Dibenedetto (vini l\u2019Archetipo) &#8211; Castellaneta;<br \/>\nOlio Terrusi &#8211; Castellaneta;<br \/>\nAntonicelli Massimiliano (ciliegie) &#8211; Castellaneta. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Due giorni a Torre Santa Susanna, in provincia di Brindisi, per l\u2019ottimismo e per superare la crisi che la Xylella e il maltempo hanno gettato sulla produzione agricola pugliese. Con CIA-Agricoltori Italiani, Slow Food Italia, Gal del Primitivo, il Sindaco Michele Saccomanno e l\u2019intera Amministrazione comunale hanno preparato degustazioni e convegni, hanno presentato la Guida degli oli extravergini e premiato i migliori produttori italiani. \u00c8 stato suggellato un patto tra Istituzioni e mondo del lavoro inaugurando un monumento vivo alla tradizione e alle speranze: il Museo dell\u2019olio e delle olive. Radici e prospettive trasferite con la ricchezza della conoscenza. Hanno partecipato, oltre al Sindaco e all\u2019intera Amministrazione, il Prefetto di Brindisi Umberto Guidato, il Vescovo di Oria Mons. Vincenzo Pisanello, l\u2019Assessore Regionale Loredana Capone, il Generale dei Carabinieri forestali Danilo Mostacchi, Francesca Baldereschi di Slow Food Italia, il Sovrintendente delle Belle Arti Carmelo Di Fonzo, Marcello Longo per Slow Food Puglia Per CIA Agricoltori Italiani hanno partecipato Cinzia Pagni, presidente di ASeS-Agricoltori, Solidariet\u00e0 e Sviluppo, Pietro De Padova, presidente CIA&#8230;<\/p>\n","protected":false},"author":2,"featured_media":157018,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-157016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=157016"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157016\/revisions"}],"predecessor-version":[{"id":157019,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157016\/revisions\/157019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/157018"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=157016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=157016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=157016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}