{"id":157158,"date":"2019-06-26T17:52:47","date_gmt":"2019-06-26T15:52:47","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=157158"},"modified":"2019-06-26T16:56:34","modified_gmt":"2019-06-26T14:56:34","slug":"torna-il-fasano-fish-festival-il-cibo-del-mare-appuntamento-a-savelletri-il-29-e-30-giugno","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/torna-il-fasano-fish-festival-il-cibo-del-mare-appuntamento-a-savelletri-il-29-e-30-giugno\/","title":{"rendered":"Torna il \u201cFasano Fish Festival \u2013 Il cibo del mare\u201d: appuntamento a Savelletri il 29 e 30 giugno"},"content":{"rendered":"<p>Il 29 e 30 giugno torna il Fasano Fish Festival, organizzato dal GAL Valle d\u2019Itria (che comprende i comuni di Fasano, Locorotondo, Martina Franca e Cisternino). Dopo l\u2019appuntamento nel centro storico di Fasano a dicembre, questa volta l\u2019evento dedicato al pesce del Mediterraneo, si svolger\u00e0 nella caratteristica area portuale di Savelletri. Affacciandosi sul mare, a partire dalle 19 di sabato e domenica, si potranno assaggiare le prelibatezze preparate dagli chef della Valle d\u2019Itria.<\/p>\n<p>Dai piatti vegani ai tradizionali sapori del Mediterraneo, passando per gustosissimi finger food preparati rigorosamente con il pescato locale e con materie prime pugliesi, saranno tante le ricette da scoprire in una due giorni ricca di eventi.<\/p>\n<p>Non soltanto food e degustazioni nella seconda edizione del Fasano Fish Festival: ampio spazio sar\u00e0 dedicato anche ai temi ambientali, a partire dalla sensibilizzazione verso l\u2019inquinamento provocato dalla plastica in mare. <\/p>\n<p>Dai primi giorni di giugno un\u2019opera d\u2019arte campeggia sulla spiaggia di Lido Morelli, nel Parco delle Dune Costiere (nei pressi di Torre Canne, nel territorio di Fasano): si tratta del \u201cPesce mangia plastica\u201d, un\u2019installazione che, grazie all\u2019aiuto dei bagnanti, ha lo scopo di raccogliere nella sua pancia tutti i rifiuti presenti sul litorale che altrimenti finirebbero in mare. <\/p>\n<p>Durante il Festival, condotto da Valeria Todisco, verr\u00e0 proiettato il documentario \u201cAnche i pesci piangono\u201d di Domitilla Segni (regia di Francesco Cabras) che racconta, attraverso interviste e riprese realizzate nelle principali marinerie della Puglia, le trasformazioni dell\u2019Adriatico, un mare che fino a pochi decenni fa custodiva una grande ricchezza di biodiversit\u00e0 e che oggi si ritrova impoverito e malato. Il racconto di una parabola impreziosito da Rachele Andrioli, una tra le pi\u00f9 belle voci del Mediterraneo.<\/p>\n<p>Ad intrattenere i visitatori nella due giorni della manifestazione, ci saranno anche i giovani attori dell\u2019Associazione teatrale amatoriale \u201cGli amici di Gi\u00f9\u00e0ann\u00e8edd\u201d, vincitrice del Premio Bandiera Verde Agricoltura 2017 promosso da C.I.A. &#8211; Agricoltori Italiani, che riproporranno in vernacolo uno spaccato di vita quotidiana in provincia, e la Apluvia Small Orchestra che canter\u00e0 De Andr\u00e9. <\/p>\n<p>L\u2019evento \u00e8 realizzato nell\u2019ambito del PO FEAMP 2014-2010 (MIS. 4.63 \u2013 SSL GAL VALLE D\u2019ITRIA \u2013 Intervento 1.7 \u2013 Realizzazione di eventi di promozione di prodotti della pesca), con i patrocini del Fondo Europeo Agricolo per lo Sviluppo Rurale, Ministero delle Politiche Agricole Alimentari, Forestali e del Turismo, Regione Puglia, Repubblica Italiana, Programma Operativo FEAMP 2014-2020 e Psr Puglia.<\/p>\n<p> In allegato il programma completo dell&#8217;evento.<\/p>\n<p>Ufficio stampa 41 Agenzia TV<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 29 e 30 giugno torna il Fasano Fish Festival, organizzato dal GAL Valle d\u2019Itria (che comprende i comuni di Fasano, Locorotondo, Martina Franca e Cisternino). Dopo l\u2019appuntamento nel centro storico di Fasano a dicembre, questa volta l\u2019evento dedicato al pesce del Mediterraneo, si svolger\u00e0 nella caratteristica area portuale di Savelletri. Affacciandosi sul mare, a partire dalle 19 di sabato e domenica, si potranno assaggiare le prelibatezze preparate dagli chef della Valle d\u2019Itria. Dai piatti vegani ai tradizionali sapori del Mediterraneo, passando per gustosissimi finger food preparati rigorosamente con il pescato locale e con materie prime pugliesi, saranno tante le ricette da scoprire in una due giorni ricca di eventi. Non soltanto food e degustazioni nella seconda edizione del Fasano Fish Festival: ampio spazio sar\u00e0 dedicato anche ai temi ambientali, a partire dalla sensibilizzazione verso l\u2019inquinamento provocato dalla plastica in mare. Dai primi giorni di giugno un\u2019opera d\u2019arte campeggia sulla spiaggia di Lido Morelli, nel Parco delle Dune Costiere (nei pressi di Torre Canne, nel territorio di Fasano): si tratta&#8230;<\/p>\n","protected":false},"author":2,"featured_media":157161,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-157158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=157158"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157158\/revisions"}],"predecessor-version":[{"id":157162,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157158\/revisions\/157162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/157161"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=157158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=157158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=157158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}