{"id":15720,"date":"2014-06-18T10:30:44","date_gmt":"2014-06-18T08:30:44","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=15720"},"modified":"2014-06-18T12:01:48","modified_gmt":"2014-06-18T10:01:48","slug":"lippolis-la-sconfitta-del-centrodestra-francavillese-sia-punto-di-partenza","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/lippolis-la-sconfitta-del-centrodestra-francavillese-sia-punto-di-partenza\/","title":{"rendered":"Lippolis: &#8220;la sconfitta del centrodestra francavillese sia punto di partenza&#8221;"},"content":{"rendered":"<p>Se continuiamo a parlare di Francavilla come di una citt\u00e0 di centro destra, continuiamo a sbagliare dimostrando arroganza e mancato rispetto di quello che \u00e8 stato il dato elettorale. E cio\u00e8, Francavilla dal 9 di giugno \u00e8 governata dalla sinistra.<\/p>\n<p>Questo significa che i cittadini attraverso il voto e l\u2019astensione hanno scelto l\u2019alternanza, cosa ben diversa dal cambiamento.<\/p>\n<p>&nbsp;<\/p>\n<p>Determinanti per la nostra sconfitta, a mio avviso, sono stati i giovani.<\/p>\n<p>Non siamo stati in grado di comunicare con loro, sia durante la campagna elettorale, che negli ultimi venti anni. Avremmo dovuto capire che avevano bisogno di noi. Non ci chiedevano di cambiare casacca, ma di cambiare il modo di fare la politica.<\/p>\n<p>Hanno atteso il momento giusto per punirci e, diversamente dal passato, hanno condizionato anche l\u2019atteggiamento di noi genitori.<\/p>\n<p>&nbsp;<\/p>\n<p>Si, \u00e8 accaduto proprio il contrario di quello che accadeva in passato nelle nostre famiglie, dove il padre dava indicazioni di voto e loro, solo per una forma di rispetto, accettavano a testa bassa.<\/p>\n<p>Non dobbiamo dimenticarci, inoltre, che dal 2006 ad oggi, Francavilla \u00e8 stata commissariata per ben due volte.<\/p>\n<p>Una prima volta a causa dell\u2019abbandono volontario del sindaco Marinotti, che decise di accomodarsi tra i banchi della Regione Puglia dimenticando di aver ricevuto dagli elettori un mandato non a termine, ma a scadenza.<\/p>\n<p>Una seconda volta per un abbandono del sindaco della Corte, sempre volontario, ma conseguente ad una vicenda giudiziaria che interessava la sua vita professionale e non amministrativa.<\/p>\n<p>Tutti ingredienti che hanno contribuito alla nostra sconfitta.<\/p>\n<p>&nbsp;<\/p>\n<p>Ovviamente la mia \u00e8 un\u2019analisi che non mi esclude da quelle che sono state anche le mie responsabilit\u00e0 di padre e di amministratore.<\/p>\n<p>L\u2019unica cosa che mi inorgoglisce della mia breve esperienza amministrativa, \u00e8 di aver contribuito, anche a volte con scelte impopolari, vedi la massa degli accertamenti prodotti nel settore tributi, a consegnare alla dottoressa Iaculli prima ed alla citt\u00e0 dopo, un bilancio sano e veritiero.<\/p>\n<p>Mi auguro che questa esperienza negativa possa essere un punto di partenza per una diversa classe dirigente, che tanto avr\u00e0 da lavorare perch\u00e9 Francavilla possa tornare ad essere amministrata da gente moderata e di centro destra.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin: 0cm 0cm 0pt; text-align: justify; line-height: normal;\"><strong><span style=\"color: #000000; font-family: Calibri; font-size: medium;\">Romeo Lippolis<\/span><\/strong><\/p>\n<p style=\"margin: 0cm 0cm 0pt; text-align: justify; line-height: normal;\"><strong><span style=\"color: #000000; font-family: Calibri; font-size: medium;\">Ex ass.re al Bilancio, patrimonio e tributi<\/span><\/strong><\/p>\n<p style=\"margin: 0cm 0cm 0pt; text-align: justify; line-height: normal;\"><strong><span style=\"color: #000000; font-family: Calibri; font-size: medium;\">del comune di Francavilla Fontana<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se continuiamo a parlare di Francavilla come di una citt\u00e0 di centro destra, continuiamo a sbagliare dimostrando arroganza e mancato rispetto di quello che \u00e8 stato il dato elettorale. E cio\u00e8, Francavilla dal 9 di giugno \u00e8 governata dalla sinistra. Questo significa che i cittadini attraverso il voto e l\u2019astensione hanno scelto l\u2019alternanza, cosa ben diversa dal cambiamento. &nbsp; Determinanti per la nostra sconfitta, a mio avviso, sono stati i giovani. Non siamo stati in grado di comunicare con loro, sia durante la campagna elettorale, che negli ultimi venti anni. Avremmo dovuto capire che avevano bisogno di noi. Non ci chiedevano di cambiare casacca, ma di cambiare il modo di fare la politica. Hanno atteso il momento giusto per punirci e, diversamente dal passato, hanno condizionato anche l\u2019atteggiamento di noi genitori. &nbsp; Si, \u00e8 accaduto proprio il contrario di quello che accadeva in passato nelle nostre famiglie, dove il padre dava indicazioni di voto e loro, solo per una forma di rispetto, accettavano a testa bassa. Non dobbiamo dimenticarci, inoltre,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":15721,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[27,2118],"class_list":["post-15720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-francavilla","tag-lippolis"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/15720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=15720"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/15720\/revisions"}],"predecessor-version":[{"id":15722,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/15720\/revisions\/15722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/15721"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=15720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=15720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=15720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}