{"id":157257,"date":"2019-06-28T18:12:32","date_gmt":"2019-06-28T16:12:32","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=157257"},"modified":"2019-06-28T15:20:30","modified_gmt":"2019-06-28T13:20:30","slug":"francavilla-martedi-2-consiglio-comunale-monotematico-su-emergenza-rifiuti","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/francavilla-martedi-2-consiglio-comunale-monotematico-su-emergenza-rifiuti\/","title":{"rendered":"Francavilla: Marted\u00ec 2 Consiglio Comunale monotematico su Emergenza rifiuti"},"content":{"rendered":"<p>Marted\u00ec 2 luglio alle ore 16.30 \u00e8 stato convocato un Consiglio Comunale monotematico sull\u2019emergenza rifiuti.<\/p>\n<p>Nel corso della seduta sar\u00e0 discussa la mozione presentata dai gruppi di maggioranza che, a seguito dei disservizi nella raccolta e conferimento dei rifiuti della frazione organica e delle tre ordinanze firmate dal Presidente Emiliano, chiede un approfondimento e un intervento dell\u2019Amministrazione Comunale.<\/p>\n<p>Lo stato di emergenza \u00e8 stato causato dalla indisponibilit\u00e0 di centri per il conferimento della frazione organica a livello regionale. Negli scorsi giorni i Sindaci della provincia di Brindisi hanno sottoscritto un documento unitario con il quale sollecitavano il Presidente Emiliano e l\u2019Ager a programmare un incontro per affrontare in maniera coordinata il problema che ciclicamente si ripresenta creando enormi disagi alla cittadinanza e all\u2019ambiente.<br \/>\nL\u2019ultima ordinanza del Presidente della Regione, la terza in pochi giorni, dispone sino al 31 luglio il conferimento della frazione organica, non gestibile negli impianti individuati con i due precedenti provvedimenti, presso i centri di trattamento meccanico biologico ubicati nelle province di Taranto, Lecce e Bari.<br \/>\nSalvo ulteriori sviluppi negativi, quindi, sar\u00e0 garantita la continuit\u00e0 del servizio sino al 31 luglio. Per quella data dovranno essere predisposti nuovi provvedimenti atti ad allontanare definitivamente lo spettro dell&#8217;emergenza.<\/p>\n<p>Al Consiglio Comunale sono stati invitati a partecipare i rappresentanti di Aro, Ager, Regione Puglia e Provincia.<\/p>\n<p>I lavori saranno trasmessi in diretta streaming sul canale youtube del Comune di Francavilla Fontana e in differita radiofonica dall\u2019emittente Radio85.<\/p>\n<p>Francavilla Fontana<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marted\u00ec 2 luglio alle ore 16.30 \u00e8 stato convocato un Consiglio Comunale monotematico sull\u2019emergenza rifiuti. Nel corso della seduta sar\u00e0 discussa la mozione presentata dai gruppi di maggioranza che, a seguito dei disservizi nella raccolta e conferimento dei rifiuti della frazione organica e delle tre ordinanze firmate dal Presidente Emiliano, chiede un approfondimento e un intervento dell\u2019Amministrazione Comunale. Lo stato di emergenza \u00e8 stato causato dalla indisponibilit\u00e0 di centri per il conferimento della frazione organica a livello regionale. Negli scorsi giorni i Sindaci della provincia di Brindisi hanno sottoscritto un documento unitario con il quale sollecitavano il Presidente Emiliano e l\u2019Ager a programmare un incontro per affrontare in maniera coordinata il problema che ciclicamente si ripresenta creando enormi disagi alla cittadinanza e all\u2019ambiente. L\u2019ultima ordinanza del Presidente della Regione, la terza in pochi giorni, dispone sino al 31 luglio il conferimento della frazione organica, non gestibile negli impianti individuati con i due precedenti provvedimenti, presso i centri di trattamento meccanico biologico ubicati nelle province di Taranto, Lecce e Bari. Salvo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":152615,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-157257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=157257"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157257\/revisions"}],"predecessor-version":[{"id":157263,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157257\/revisions\/157263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/152615"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=157257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=157257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=157257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}