{"id":157378,"date":"2019-06-30T20:29:34","date_gmt":"2019-06-30T18:29:34","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=157378"},"modified":"2019-06-30T20:29:34","modified_gmt":"2019-06-30T18:29:34","slug":"karate-medaglia-di-bronzo-per-il-brindisino-michele-martina-ai-giochi-olimpici-europei-di-minsk","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/karate-medaglia-di-bronzo-per-il-brindisino-michele-martina-ai-giochi-olimpici-europei-di-minsk\/","title":{"rendered":"Karate: medaglia di bronzo per il brindisino Michele Martina ai giochi olimpici europei di Minsk."},"content":{"rendered":"<p>Si chiude splendidamente la seconda edizione dei giochi olimpici europei per la spedizione azzurra che, con il bronzo di Martina Michele, si consacra al quarto posto nel medagliere totale.<\/p>\n<p>L\u2019ex atleta della societ\u00e0 brindisina Dojo Dokko Do, oggi in forze al Gruppo Sportivo delle Fiamme Oro della Polizia di Stato, ha disputato un\u2019ottima gara qualificandosi come secondo in un girone equilibratissimo, accedendo cos\u00ec alla semi-finale contro il campione del mondo croato.<\/p>\n<p>Il brindisino \u00e8 partito deciso dominando nettamente la prima parte dell\u2019incontro con un risultato di 2-0, ma il sogno di accesso alla finale \u00e8 svanito per un dubbio giudizio arbitrale che ha terminato anzitempo l\u2019incontro squalificando l\u2019azzurro.<\/p>\n<p>Martina nonostante ci\u00f2, ha portato a casa un pregiato bronzo che lo ricolloca tra i pi\u00f9 forti al mondo nella sua categoria, dandogli la giusta spinta per ripartire alla rincorsa verso Tokyo 2020.<\/p>\n<p>Il presidente della dojo dokko do Giuseppe D\u2019Arpa ed i tecnici federali Vincenzo De Leo e Nicola Ciarloni. Pg Facebook ed Instagram: Asd Dojo Dokko Do Karate <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si chiude splendidamente la seconda edizione dei giochi olimpici europei per la spedizione azzurra che, con il bronzo di Martina Michele, si consacra al quarto posto nel medagliere totale. L\u2019ex atleta della societ\u00e0 brindisina Dojo Dokko Do, oggi in forze al Gruppo Sportivo delle Fiamme Oro della Polizia di Stato, ha disputato un\u2019ottima gara qualificandosi come secondo in un girone equilibratissimo, accedendo cos\u00ec alla semi-finale contro il campione del mondo croato. Il brindisino \u00e8 partito deciso dominando nettamente la prima parte dell\u2019incontro con un risultato di 2-0, ma il sogno di accesso alla finale \u00e8 svanito per un dubbio giudizio arbitrale che ha terminato anzitempo l\u2019incontro squalificando l\u2019azzurro. Martina nonostante ci\u00f2, ha portato a casa un pregiato bronzo che lo ricolloca tra i pi\u00f9 forti al mondo nella sua categoria, dandogli la giusta spinta per ripartire alla rincorsa verso Tokyo 2020. Il presidente della dojo dokko do Giuseppe D\u2019Arpa ed i tecnici federali Vincenzo De Leo e Nicola Ciarloni. Pg Facebook ed Instagram: Asd Dojo Dokko Do Karate<\/p>\n","protected":false},"author":2,"featured_media":157379,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-157378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=157378"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157378\/revisions"}],"predecessor-version":[{"id":157380,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157378\/revisions\/157380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/157379"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=157378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=157378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=157378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}