{"id":157441,"date":"2019-07-02T17:48:05","date_gmt":"2019-07-02T15:48:05","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=157441"},"modified":"2019-07-02T17:48:05","modified_gmt":"2019-07-02T15:48:05","slug":"beccato-con-300-grammi-di-cocaina-purissima-arrestato-cittadino-del-gambia","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/beccato-con-300-grammi-di-cocaina-purissima-arrestato-cittadino-del-gambia\/","title":{"rendered":"Beccato con 300 grammi di cocaina purissima: arrestato cittadino del Gambia"},"content":{"rendered":"<p>I Carabinieri della Stazione di Brindisi Centro, nel corso dei servizi perlustrativi effettuati nelle adiacenze della Stazione Ferroviaria, attivit\u00e0 giornaliera finalizzata alla prevenzione e repressione dei reati predatori, nonch\u00e9 al controllo di persone che gravitano nella piazza e per infrenare lo spaccio di sostanze stupefacenti soprattutto tra le giovani generazioni, hanno tratto in arresto in flagranza di reato Kane Nfally 35enne del Gambia. Erano circa le ore 12.00, e l\u2019uomo era stato notato dalla pattuglia dei militari della Stazione di Brindisi Centro, aggirarsi a piedi con fare sospetto tra le aiuole nelle adiacenze della stazione ferroviaria in Piazza Crispi. <\/p>\n<p>Pertanto, \u00e8 stato fermato e controllato, risultando sprovvisto di regolare permesso di soggiorno, nella circostanza ha subito mostrato segni di nervosismo e insofferenza. Sulle spalle uno zainetto e tra le mani una busta di plastica di colore giallo all\u2019interno della quale vi erano due banane e una busta di carta di colore bianco con un involucro di carta stagnola che il 35enne ha riferito contenere un panino con il formaggio. Considerato il peso e la consistenza, all\u2019interno della carta stagnola \u00e8 stata rinvenuta una busta di plastica contenente stupefacente del tipo cocaina in pietra, purissima come risultato dall\u2019esame del narcotest. <\/p>\n<p>A seguito di perquisizione personale effettuata sull\u2019uomo gli \u00e8 stato rinvenuto un biglietto ferroviario per la tratta Milano-Brindisi, infatti una delle ipotesi pi\u00f9 accreditate \u00e8 quella che il cittadino extracomunitario rifornisse di stupefacente suoi connazionali in Brindisi. Il cittadino gambiano, che parla correttamente la lingua italiana, tratto in arresto per detenzione al fine di spaccio di stupefacente, non ha voluto rispondere a nessuna domanda relativa alla cocaina sequestrata del peso di 300 grammi. <\/p>\n<p>Nel corso delle attivit\u00e0 di identificazione, \u00e8 stato anche  deferito per ingresso e soggiorno illegale nel territorio dello Stato. Espletate le formalit\u00e0 di rito \u00e8 stato associato nella Casa Circondariale di Brindisi a disposizione dell\u2019Autorit\u00e0 Giudiziaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Carabinieri della Stazione di Brindisi Centro, nel corso dei servizi perlustrativi effettuati nelle adiacenze della Stazione Ferroviaria, attivit\u00e0 giornaliera finalizzata alla prevenzione e repressione dei reati predatori, nonch\u00e9 al controllo di persone che gravitano nella piazza e per infrenare lo spaccio di sostanze stupefacenti soprattutto tra le giovani generazioni, hanno tratto in arresto in flagranza di reato Kane Nfally 35enne del Gambia. Erano circa le ore 12.00, e l\u2019uomo era stato notato dalla pattuglia dei militari della Stazione di Brindisi Centro, aggirarsi a piedi con fare sospetto tra le aiuole nelle adiacenze della stazione ferroviaria in Piazza Crispi. Pertanto, \u00e8 stato fermato e controllato, risultando sprovvisto di regolare permesso di soggiorno, nella circostanza ha subito mostrato segni di nervosismo e insofferenza. Sulle spalle uno zainetto e tra le mani una busta di plastica di colore giallo all\u2019interno della quale vi erano due banane e una busta di carta di colore bianco con un involucro di carta stagnola che il 35enne ha riferito contenere un panino con il formaggio. Considerato&#8230;<\/p>\n","protected":false},"author":2,"featured_media":157442,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-157441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=157441"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157441\/revisions"}],"predecessor-version":[{"id":157443,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157441\/revisions\/157443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/157442"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=157441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=157441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=157441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}