{"id":157749,"date":"2019-07-09T10:25:19","date_gmt":"2019-07-09T08:25:19","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=157749"},"modified":"2019-07-09T10:25:19","modified_gmt":"2019-07-09T08:25:19","slug":"alla-scoperta-dei-sotterranei-del-castello-dentice-di-frasso-di-carovigno","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/alla-scoperta-dei-sotterranei-del-castello-dentice-di-frasso-di-carovigno\/","title":{"rendered":"Alla scoperta dei sotterranei del Castello Dentice di Frasso di Carovigno"},"content":{"rendered":"<p>\u201cCosa si nasconde al di sotto del Castello?\u201d \u00e8 la prossima iniziativa promossa dalla Associazione Le Colonne che si terr\u00e0 domenica 14 luglio presso il Castello Dentice di Frasso di Carovigno, in provincia di Brindisi.<\/p>\n<p>&nbsp;<\/p>\n<p>A partire dalle 19 sino a mezzanotte, sar\u00e0 possibile visitare i sotterranei del castello.<\/p>\n<p>&nbsp;<\/p>\n<p>Si tratta di una lunga galleria sotterranea di origine normanna che, all\u2019epoca della fondazione, ospitava le prigioni. Nel corso dei secoli i locali sotterranei hanno cambiato destinazione d\u2019uso e sono stati parzialmente modificati per sopperire a nuove necessit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>Per informazioni, costi e prenotazioni contattare il numero 3930834404.<\/p>\n<p>Pagina Ufficiale Facebook del Castello Dentice Di Frasso al seguente link:<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/castellocarovigno\/?modal=admin_todo_tour\">https:\/\/www.facebook.com\/castellocarovigno\/?modal=admin_todo_tour<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Castello Dentice di Frasso \u2013 Musbi<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cCosa si nasconde al di sotto del Castello?\u201d \u00e8 la prossima iniziativa promossa dalla Associazione Le Colonne che si terr\u00e0 domenica 14 luglio presso il Castello Dentice di Frasso di Carovigno, in provincia di Brindisi. &nbsp; A partire dalle 19 sino a mezzanotte, sar\u00e0 possibile visitare i sotterranei del castello. &nbsp; Si tratta di una lunga galleria sotterranea di origine normanna che, all\u2019epoca della fondazione, ospitava le prigioni. Nel corso dei secoli i locali sotterranei hanno cambiato destinazione d\u2019uso e sono stati parzialmente modificati per sopperire a nuove necessit\u00e0. &nbsp; Per informazioni, costi e prenotazioni contattare il numero 3930834404. Pagina Ufficiale Facebook del Castello Dentice Di Frasso al seguente link: https:\/\/www.facebook.com\/castellocarovigno\/?modal=admin_todo_tour &nbsp; Castello Dentice di Frasso \u2013 Musbi<\/p>\n","protected":false},"author":2,"featured_media":157754,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-157749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=157749"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157749\/revisions"}],"predecessor-version":[{"id":157755,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/157749\/revisions\/157755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/157754"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=157749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=157749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=157749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}