{"id":158216,"date":"2019-07-16T14:58:18","date_gmt":"2019-07-16T12:58:18","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=158216"},"modified":"2019-07-16T14:58:18","modified_gmt":"2019-07-16T12:58:18","slug":"antonio-greco-presidente-del-gruppo-folk-citta-di-ostuni-vince-loscar-mondiale-del-folklore","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/antonio-greco-presidente-del-gruppo-folk-citta-di-ostuni-vince-loscar-mondiale-del-folklore\/","title":{"rendered":"Antonio Greco, Presidente del Gruppo Folk Citt\u00e0 di Ostuni, vince l&#8217;Oscar Mondiale del Folklore"},"content":{"rendered":"<p>Un nuovo riconoscimento va ad arricchire la prestigiosa bacheca di Antonio Greco e dei suoi ragazzi del Gruppo Folk Citt\u00e0 di Ostuni. Lo speciale encomio sar\u00e0 consegnato dalla IGF \u2013 WORLD FOLKLORE UNION, un\u2019organizzazione fondata nel 1949 con l\u2019intento di curare i rapporti tra le federazioni nazionali di folklore di tutto il mondo. Ogni anno la IGF ricerca e seleziona le figure di spicco del folklore di tutto il mon-do premiandole con l\u2019IGF GOLD STAR \u2013 OSCAR MONDIALE DEL FOLKLORE, il pi\u00f9 prestigioso ricono-scimento mondiale  per chi opera nell\u2019ambito della cultura e delle tradizioni popolari.<br \/>\nLa giuria, analizzando i profili delle numerose figure candidate, ha scelto di premiare, insieme ad altri, il Presidente del Gruppo Folk Citt\u00e0 di Ostuni Sig. Antonio Greco, forte del suo curriculum e delle molteplici iniziative portate avanti con la sua associazione culturale.<br \/>\nLa cerimonia di premiazione si terr\u00e0 il prossimo 29 Luglio a Bistrita, famoso comune nella regione della Transilvania in Romania, dove sette personalit\u00e0 benemerite provenienti da nazioni diverse, riceveranno l\u2019ambito riconoscimento. Antonio Greco, unico italiano presente, rappresenter\u00e0 l\u2019Italia intera in una cerimo-nia di gala dove saranno presenti tv e giornalisti di tutto il mondo.<br \/>\n\u201cQuesto genere di riconoscimento \u2013 ha dichiarato Antonio Greco &#8211; non \u00e8 un punto di arrivo, bens\u00ec un punto di partenza per costruire un futuro longevo del folklore ostunese, che sappia far avvicinare i giovani e valorizzare quelle che sono le caratteristiche identitarie della citt\u00e0 di Ostuni. \u00c9 giusto precisare che l\u2019oscar mondiale del folklore sar\u00e0 consegnato alla mia persona, ma questo \u00e8 avvenuto grazie al fantastico lavoro di squadra con tutti i miei soci del Gruppo Folk Citt\u00e0 di Ostuni, con I quail mi sento di condividere questa gioia. Senza di loro tutto ci\u00f2 non si sarebbe realizzato. Ci tengo a sottolineare, inoltre, che tale rico-noscimento deve ritenersi motivo di vanto e orgoglio per l\u2019intera cittadina ostunese, per l\u2019Amministrazione Comunale di Ostuni, per tutte le associazioni folkloriche della citt\u00e0, oltre che per l\u2019intera famiglia della FE-DERAZIONE ITALIANA TRADIZIONI POPOLARI, nella persona del Presidente Nazionale Benito Ripoli, che da oltre venti anni ci guida in questa bellissima avventura culturale e associativa.\u201d<br \/>\nAd Antonio Greco giungono anche le congratulazioni del Sindaco di Ostuni Guglielmo Cavallo: \u201cUn riconoscimento cos\u00ec importante non pu\u00f2 che vedere la soddisfazione dell\u2019intera comunit\u00e0. Al presidente del Gruppo Folk Citt\u00e0 di Ostuni, esprimo i miei personali auguri e quelli di tutta la citt\u00e0. Le tradizioni espresse dalla musica folkloristica \u2013 conclude Cavallo &#8211;  sono espressione dell\u2019identit\u00e0 del nostro territorio e farle conoscere al mondo deve rientrare nell\u2019impegno nostro e di tutte le associazioni della citt\u00e0 che di folklore si occupano.\u201d<br \/>\nAntonio Greco  forte della sua ventennale esperienza, ha operato nel mondo della cultura e del folklore, spendendosi in maniera disinteressata nell\u2019educare i ragazzi a vivere l\u2019associazionismo in maniera pulita e sana. E\u2019 lui il vero e proprio fulcro di questa associazione, meritevole di aver contribuito a portare in alto il nome della Puglia nel mondo, confermando il Gruppo Folk Citt\u00e0 di Ostuni come una delle realt\u00e0 artistiche culturali pi\u00f9 conosciute e ricercate del sud Italia. Instancabile, tenace e inesauribile \u00e8 il suo impegno quoti-diano, assiduo e perseverante verso i valori della vita e del folklore, tanto da essere considerato punto fo-cale per adulti e ragazzi che lo circondano e che lo considerano un padre di vita.<\/p>\n<p>Comune di Ostuni &#8211; Ufficio stampa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nuovo riconoscimento va ad arricchire la prestigiosa bacheca di Antonio Greco e dei suoi ragazzi del Gruppo Folk Citt\u00e0 di Ostuni. Lo speciale encomio sar\u00e0 consegnato dalla IGF \u2013 WORLD FOLKLORE UNION, un\u2019organizzazione fondata nel 1949 con l\u2019intento di curare i rapporti tra le federazioni nazionali di folklore di tutto il mondo. Ogni anno la IGF ricerca e seleziona le figure di spicco del folklore di tutto il mon-do premiandole con l\u2019IGF GOLD STAR \u2013 OSCAR MONDIALE DEL FOLKLORE, il pi\u00f9 prestigioso ricono-scimento mondiale per chi opera nell\u2019ambito della cultura e delle tradizioni popolari. La giuria, analizzando i profili delle numerose figure candidate, ha scelto di premiare, insieme ad altri, il Presidente del Gruppo Folk Citt\u00e0 di Ostuni Sig. Antonio Greco, forte del suo curriculum e delle molteplici iniziative portate avanti con la sua associazione culturale. La cerimonia di premiazione si terr\u00e0 il prossimo 29 Luglio a Bistrita, famoso comune nella regione della Transilvania in Romania, dove sette personalit\u00e0 benemerite provenienti da nazioni diverse, riceveranno l\u2019ambito riconoscimento. Antonio Greco,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":79129,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-158216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/158216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=158216"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/158216\/revisions"}],"predecessor-version":[{"id":158217,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/158216\/revisions\/158217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/79129"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=158216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=158216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=158216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}