{"id":158222,"date":"2019-07-16T15:13:53","date_gmt":"2019-07-16T13:13:53","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=158222"},"modified":"2019-07-16T15:13:53","modified_gmt":"2019-07-16T13:13:53","slug":"bilancio-piu-che-positivo-per-la-prima-edizione-del-puglia-book-fest","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/bilancio-piu-che-positivo-per-la-prima-edizione-del-puglia-book-fest\/","title":{"rendered":"Bilancio pi\u00f9 che positivo per la prima edizione del Puglia Book Fest"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/07\/puglia-book-fest-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-158225\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/07\/puglia-book-fest-2-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/07\/puglia-book-fest-2-225x300.jpg 225w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/07\/puglia-book-fest-2-300x400.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/07\/puglia-book-fest-2.jpg 720w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><br \/>\n<\/a>Pi\u00f9 di tremila le presenze registrate durante la prima edizione del Puglia Book Fest, la manifestazione dedicata ai libri, alla letteratura e ai saperi che si \u00e8 svolta nel centro storico di Brindisi lo scorso fine settimana.<\/p>\n<p>Un grande successo di pubblico ma anche di consensi per un\u2019iniziativa culturale che ha coinvolto 5 beni monumentali della citt\u00e0, facendo scoprire e riscoprire alcuni dei luoghi pi\u00f9 belli di Brindisi: il giardino dell\u2019ex Convento Santa Chiara, il chiostro di San Paolo Eremita, il complesso delle ex Scuole Pie, il Museo Archeologico e Palazzo Nervegna.<\/p>\n<p>&nbsp;<\/p>\n<p>Un totale di 45 presentazioni di libri, 26 case editrici pugliesi ospitate con i loro volumi e i loro autori, 13 grandi autori del panorama nazionale, 4 librerie coinvolte, e poi eventi per bambini, teatro, mostre. Tutto questo \u00e8 stato il Puglia Book Fest, nato dalla collaborazione tra la Feltrinelli Point Brindisi e la rivista Amazing Puglia, con il patrocinio del Comune di Brindisi.<\/p>\n<p>&nbsp;<\/p>\n<p>Una scommessa vinta quella di creare il primo festival culturale diffuso della citt\u00e0 di Brindisi, a conferma che la promozione del territorio pu\u00f2 e deve passare attraverso gli eventi e in questo caso i libri. Migliaia le visualizzazioni sulla pagina facebook Puglia Book Fest, centinaia le condivisioni e le interazioni, entusiastici i commenti.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/07\/scuole-pie4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-158226 alignright\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/07\/scuole-pie4-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/07\/scuole-pie4-300x225.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/07\/scuole-pie4-768x576.jpg 768w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/07\/scuole-pie4.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/>\n<\/a>Per quanto riguarda le presentazioni dei libri il pubblico ha premiato non solo i personaggi pi\u00f9 popolari ma anche quelli del panorama culturale nazionale. Da Piergiorgio Odifreddi a Michela Marzano, da Ascanio Celestini a Costantino D\u2019Orazio, da Rita Dalla Chiesa a Catena Fiorello, da Chiara Francini a Rosario Pellecchia, ogni location \u00e8 stata affollata e, in alcuni casi, presa proprio d\u2019assalto. Il tutto nonostante il tempo atmosferico incerto che ha caratterizzato questo ultimo week-end.<\/p>\n<p>&nbsp;<\/p>\n<p>Grande, dunque, la soddisfazione degli organizzatori per la riuscita di questo evento che ringraziano quanti hanno collaborato attivamente e tutti i partecipanti che con la loro presenza hanno premiato un\u2019idea progettuale coraggiosa e complessa.<\/p>\n<p>&nbsp;<\/p>\n<p>Il Puglia Book Fest \u00e8 stato organizzato dall&#8217;Associazione Puglia Book ETS con il patrocinio del Comune di Brindisi. Sponsor della manifestazione Chemgas, Consorzio ASI Brindisi, Sanofi, Rosy e Paola Barretta, Locopress Industria Grafica. Official Partner: Inchiostri di Puglia, Rotary Club Brindisi, Fondazione \u201cTonino Di Giulio\u201d, Recensionilibri.org, Ristorante Piazzetta Colonne, Hotel Executive Inn, Hotel Orientale.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pi\u00f9 di tremila le presenze registrate durante la prima edizione del Puglia Book Fest, la manifestazione dedicata ai libri, alla letteratura e ai saperi che si \u00e8 svolta nel centro storico di Brindisi lo scorso fine settimana. Un grande successo di pubblico ma anche di consensi per un\u2019iniziativa culturale che ha coinvolto 5 beni monumentali della citt\u00e0, facendo scoprire e riscoprire alcuni dei luoghi pi\u00f9 belli di Brindisi: il giardino dell\u2019ex Convento Santa Chiara, il chiostro di San Paolo Eremita, il complesso delle ex Scuole Pie, il Museo Archeologico e Palazzo Nervegna. &nbsp; Un totale di 45 presentazioni di libri, 26 case editrici pugliesi ospitate con i loro volumi e i loro autori, 13 grandi autori del panorama nazionale, 4 librerie coinvolte, e poi eventi per bambini, teatro, mostre. Tutto questo \u00e8 stato il Puglia Book Fest, nato dalla collaborazione tra la Feltrinelli Point Brindisi e la rivista Amazing Puglia, con il patrocinio del Comune di Brindisi. &nbsp; Una scommessa vinta quella di creare il primo festival culturale diffuso della&#8230;<\/p>\n","protected":false},"author":2,"featured_media":158226,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-158222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/158222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=158222"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/158222\/revisions"}],"predecessor-version":[{"id":158228,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/158222\/revisions\/158228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/158226"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=158222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=158222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=158222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}