{"id":158265,"date":"2019-07-17T14:42:22","date_gmt":"2019-07-17T12:42:22","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=158265"},"modified":"2019-07-17T14:42:22","modified_gmt":"2019-07-17T12:42:22","slug":"20enne-segnalato-in-prefettura-per-il-possesso-di-due-bustine-contenenti-ketamina","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/20enne-segnalato-in-prefettura-per-il-possesso-di-due-bustine-contenenti-ketamina\/","title":{"rendered":"20enne segnalato in prefettura per il possesso di due bustine contenenti ketamina"},"content":{"rendered":"<p>I Carabinieri della Sezione Radiomobile della Compagnia di Fasano, hanno segnalato per detenzione di stupefacente per uso personale un 20enne del luogo, fermato a piedi in viale dello Zoo.<br \/>\nA seguito di perquisizione personale gli sono state rinvenute due bustine contenenti polvere bianca che aveva precedentemente occultato alla base del tronco di un albero.<\/p>\n<p>Gli speditivi accertamenti con il narcotest effettuati dai Carabinieri, hanno riscontrato che la sostanza \u00e8 Ketamina.<\/p>\n<p>Si tratta di un anestetico, che \u00e8 anche una droga sintetica, scoperto negli anni 60 da un chimico americano.<br \/>\nNegli anni 70 il governo statunitense lo approv\u00f2 come anestetico, i medici militari ne fecero largo uso durante la guerra del Vietnam, per poi diffondersi anche in Europa al di fuori dell\u2019ambiente sanitario.<br \/>\nAttualmente continua ad essere impiegata come anestetico generale e viene utilizzata come droga d\u2019abuso e molto spesso assunta in associazione ad altri tipi di sostanze stupefacenti o allucinogene.<\/p>\n<p>Per la legge italiana la Ketamina \u00e8 una sostanza illegale, si trova sotto forma di liquido, capsule o in compresse vendute come ecstasy.<br \/>\nCome anestetico generale \u00e8 somministrata per via endovenosa e si presenta sotto forma di liquido incolore dall\u2019aspetto e dalla consistenza simile all\u2019acqua.<br \/>\nQuando \u00e8 impiegata come stupefacente \u00e8 sottoposta ad un processo di evaporizzazione in modo da ottenere una polvere bianca che solitamente \u00e8 inalata, ma anche assunta per via orale attraverso pastiglie.<\/p>\n<p>Gli effetti che produce la Ketamina sono quelli allucinatori di durata piuttosto breve, il meccanismo d\u2019azione varia da 10 minuti fino a qualche ora a seconda della modalit\u00e0 d\u2019assunzione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Carabinieri della Sezione Radiomobile della Compagnia di Fasano, hanno segnalato per detenzione di stupefacente per uso personale un 20enne del luogo, fermato a piedi in viale dello Zoo. A seguito di perquisizione personale gli sono state rinvenute due bustine contenenti polvere bianca che aveva precedentemente occultato alla base del tronco di un albero. Gli speditivi accertamenti con il narcotest effettuati dai Carabinieri, hanno riscontrato che la sostanza \u00e8 Ketamina. Si tratta di un anestetico, che \u00e8 anche una droga sintetica, scoperto negli anni 60 da un chimico americano. Negli anni 70 il governo statunitense lo approv\u00f2 come anestetico, i medici militari ne fecero largo uso durante la guerra del Vietnam, per poi diffondersi anche in Europa al di fuori dell\u2019ambiente sanitario. Attualmente continua ad essere impiegata come anestetico generale e viene utilizzata come droga d\u2019abuso e molto spesso assunta in associazione ad altri tipi di sostanze stupefacenti o allucinogene. Per la legge italiana la Ketamina \u00e8 una sostanza illegale, si trova sotto forma di liquido, capsule o in compresse&#8230;<\/p>\n","protected":false},"author":2,"featured_media":158266,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-158265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/158265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=158265"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/158265\/revisions"}],"predecessor-version":[{"id":158267,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/158265\/revisions\/158267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/158266"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=158265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=158265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=158265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}