{"id":158947,"date":"2019-08-02T15:35:38","date_gmt":"2019-08-02T13:35:38","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=158947"},"modified":"2019-08-02T18:45:06","modified_gmt":"2019-08-02T16:45:06","slug":"torna-la-festa-patronale-di-savelletri","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/torna-la-festa-patronale-di-savelletri\/","title":{"rendered":"Torna la Festa patronale di Savelletri"},"content":{"rendered":"<p>Torna, come ogni anno, la Festa patronale di Savelletri. La frazione marinara si appresta a rendere omaggio al santo patrono San Francesco da Paola nei giorni 8-9-10-11 agosto.<br \/>\nIl programma civile e religioso \u00e8 stato messo a punto da un comitato del tutto rinnovato, con idee fresche e giovani sempre nel rispetto della tradizione.<\/p>\n<p>&nbsp;<\/p>\n<p>Tutto avr\u00e0 inizio gioved\u00ec 8 agosto alle ore 19.00 con la prima serata del triduo religioso, l\u2019intronizzazione della statua sul presbiterio, la celebrazione eucaristica nella chiesa parrocchiale e la venerazione del santo.<\/p>\n<p>&nbsp;<\/p>\n<p>Venerd\u00ec 9 agosto, alle ore 19.00, la seconda serata del triduo dedicata agli ammalati con adorazione eucaristica, celebrazione della Santa messa e benedizione dell\u2019ammalato.<\/p>\n<p>&nbsp;<\/p>\n<p>Sabato 10 agosto, durante la terza serata del triduo, alle ore 18.30 da Largo Amati partir\u00e0 la processione con benedizione del labaro raffigurativo di San Francesco da Paola accompagnata dai Timpanisti Fajanensis. Alle ore 19.00 \u00e8 previsto l\u2019arrivo della processione in Piazza Costantinopoli e la celebrazione della Santa messa con benedizione delle famiglie presenti.<\/p>\n<p>&nbsp;<\/p>\n<p>In serata, alle ore 20.30, avr\u00e0 luogo la tradizionale Sagra del Pesce Spada sul suggestivo porto, con intrattenimento a cura del gruppo folkloristico \u201cPiripicchio Company\u201d e, alle ore 21.00, lo spettacolo-esibizione della scuola di ballo \u201cTop Dance Academy\u201d in Largo Porto.<\/p>\n<p>&nbsp;<\/p>\n<p>La festa entrer\u00e0 nel vivo domenica 10 agosto alle ore 9.30 con la celebrazione della messa solenne per i pescatori e, alle 17.30, la storica processione per terra e per mare, accompagnata dalla Banda Musicale Fasanese \u201cSanta Cecilia\u201d, durante la quale verr\u00e0 recitata la preghiera commemorativa per i defunti in mare con conseguente lancio della corona di alloro da parte del sindaco di Fasano Francesco Zaccaria.<br \/>\nAl rientro, sar\u00e0 celebrata la messa solenne serale presieduta dal vescovo della diocesi Conversano-Monopoli, mons. Giuseppe Favale.<\/p>\n<p>&nbsp;<\/p>\n<p>Al termine della celebrazione eucaristica, Savelletri ospiter\u00e0 il concerto del cantante neomelodico Michele D\u2019Andria e la sua band e, a seguire, quello degli \u201c88Max\u201d &#8211; Tribute Band degli 883.<\/p>\n<p>&nbsp;<\/p>\n<p>Il gran finale lascer\u00e0 spazio allo spettacolo di mezzanotte dei fuochi pirotecnici sul mare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torna, come ogni anno, la Festa patronale di Savelletri. La frazione marinara si appresta a rendere omaggio al santo patrono San Francesco da Paola nei giorni 8-9-10-11 agosto. Il programma civile e religioso \u00e8 stato messo a punto da un comitato del tutto rinnovato, con idee fresche e giovani sempre nel rispetto della tradizione. &nbsp; Tutto avr\u00e0 inizio gioved\u00ec 8 agosto alle ore 19.00 con la prima serata del triduo religioso, l\u2019intronizzazione della statua sul presbiterio, la celebrazione eucaristica nella chiesa parrocchiale e la venerazione del santo. &nbsp; Venerd\u00ec 9 agosto, alle ore 19.00, la seconda serata del triduo dedicata agli ammalati con adorazione eucaristica, celebrazione della Santa messa e benedizione dell\u2019ammalato. &nbsp; Sabato 10 agosto, durante la terza serata del triduo, alle ore 18.30 da Largo Amati partir\u00e0 la processione con benedizione del labaro raffigurativo di San Francesco da Paola accompagnata dai Timpanisti Fajanensis. Alle ore 19.00 \u00e8 previsto l\u2019arrivo della processione in Piazza Costantinopoli e la celebrazione della Santa messa con benedizione delle famiglie presenti. &nbsp; In serata,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":158951,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-158947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/158947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=158947"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/158947\/revisions"}],"predecessor-version":[{"id":158956,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/158947\/revisions\/158956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/158951"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=158947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=158947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=158947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}