{"id":159044,"date":"2019-08-05T07:35:31","date_gmt":"2019-08-05T05:35:31","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=159044"},"modified":"2019-08-05T07:35:31","modified_gmt":"2019-08-05T05:35:31","slug":"notte-di-fuoco-a-fasano-fermate-quattro-persone","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/notte-di-fuoco-a-fasano-fermate-quattro-persone\/","title":{"rendered":"Notte di fuoco a Fasano: fermate quattro persone"},"content":{"rendered":"<p>Nel pomeriggio di ieri, i Carabinieri hanno sottoposto a fermo quattro pregiudicati del luogo, ritenuti responsabili &#8211; a vario titolo e in concorso fra loro &#8211; dal tentato omicidio, al porto abusivo di armi clandestine, esplosioni pericolose, danneggiamento seguito da incendio e danneggiamento aggravato, rapina aggravata dalla violazione di domicilio, rissa e lesioni aggravate.<\/p>\n<p>L&#8217;operazione, condotta su provvedimento \u00e8 stato emesso dal Dott. Giovanni Marino, Pubblico Ministero della Procura della Repubblica di Brindisi, \u00e8 stata eseguita, oltre che dai Carabinieri della Compagnia di Fasano attivamente supportati durante la fase esecutiva da quelli del Nucleo Investigativo del Reparto Operativo del Comando Provinciale di Brindisi, delle Aliquote di Primo Impiego antiterrorismo della Compagnia di Brindisi, nonch\u00e9 dello Squadrone Eliportato Cacciatori Puglia di Jacotenente (FG) e da un velivolo del Nucleo Elicotteri di Bari, <\/p>\n<p>i fermi sono stati eseguiti a Fasano (BR) e in localit\u00e0 \u201cSignora Pulita\u201d.<\/p>\n<p>In particolare, tre dei fermati &#8211; resisi irreperibili nell\u2019immediatezza del citato raid e datisi alla fuga alla vista degli operanti &#8211; sono stati sorpresi all\u2019interno di un isolato casolare di campagna, mentre il quarto, libero vigilato, \u00e8 stato rintracciato presso il proprio domicilio.<\/p>\n<p>Nella circostanza, occultata sotto una pietraia, \u00e8 stata rinvenuta una pistola (marca illeggibile, probabilmente provenienza est Europa) cal. 7.65 con matricola abrasa e 5 colpi in serbatoio, perfettamente funzionante, promanante forte odore di cordite, nonch\u00e9 una ventina di grammi di marijuana suddivisi in tre buste, rinvenute in un mobile della cucina del citato fabbricato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel pomeriggio di ieri, i Carabinieri hanno sottoposto a fermo quattro pregiudicati del luogo, ritenuti responsabili &#8211; a vario titolo e in concorso fra loro &#8211; dal tentato omicidio, al porto abusivo di armi clandestine, esplosioni pericolose, danneggiamento seguito da incendio e danneggiamento aggravato, rapina aggravata dalla violazione di domicilio, rissa e lesioni aggravate. L&#8217;operazione, condotta su provvedimento \u00e8 stato emesso dal Dott. Giovanni Marino, Pubblico Ministero della Procura della Repubblica di Brindisi, \u00e8 stata eseguita, oltre che dai Carabinieri della Compagnia di Fasano attivamente supportati durante la fase esecutiva da quelli del Nucleo Investigativo del Reparto Operativo del Comando Provinciale di Brindisi, delle Aliquote di Primo Impiego antiterrorismo della Compagnia di Brindisi, nonch\u00e9 dello Squadrone Eliportato Cacciatori Puglia di Jacotenente (FG) e da un velivolo del Nucleo Elicotteri di Bari, i fermi sono stati eseguiti a Fasano (BR) e in localit\u00e0 \u201cSignora Pulita\u201d. In particolare, tre dei fermati &#8211; resisi irreperibili nell\u2019immediatezza del citato raid e datisi alla fuga alla vista degli operanti &#8211; sono stati sorpresi all\u2019interno di&#8230;<\/p>\n","protected":false},"author":2,"featured_media":151926,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-159044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=159044"}],"version-history":[{"count":2,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159044\/revisions"}],"predecessor-version":[{"id":159059,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159044\/revisions\/159059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/151926"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=159044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=159044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=159044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}