{"id":159405,"date":"2019-08-13T19:02:38","date_gmt":"2019-08-13T17:02:38","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=159405"},"modified":"2019-08-13T19:02:38","modified_gmt":"2019-08-13T17:02:38","slug":"confcommercio-brindisi-piu-accessibile-grazie-al-mare-proposta-della-cna-pienamente-condivisibile","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/confcommercio-brindisi-piu-accessibile-grazie-al-mare-proposta-della-cna-pienamente-condivisibile\/","title":{"rendered":"ConfCommercio: Brindisi pi\u00f9 accessibile grazie al mare. Proposta della CNA pienamente condivisibile"},"content":{"rendered":"<p>La proposta formulata dalla CNA nell\u2019ambito della programmazione di interventi per il Contratto Istituzionale di Sviluppo (CIS) ci vede pienamente d\u2019accordo. Ampliare gli attuali confini della Circolare del mare e creare delle nuove aree di sosta sulle dorsali nord e sud consentirebbe un pi\u00f9 agevole accesso alla citt\u00e0. Il tutto, con evidenti benefici per l\u2019intero comparto commerciale. Importante anche aver ipotizzato un collegamento diretto tra porto e aeroporto (realizzato via mare) in quanto potrebbe determinare una notevole crescita del traffico crocieristico. E si integra perfettamente in un piano di valorizzazione della citt\u00e0 anche la creazione di un\u2019area fieristica, sempre in ambito portuale.<\/p>\n<p>&nbsp;<\/p>\n<p>La Confcommercio di Brindisi, pertanto, si augura che l\u2019Amministrazione Comunale esprima formale condivisione per tali proposte e dichiara la propria totale disponibilit\u00e0 ad approfondire le tematiche relative allo sviluppo commerciale ed economico della citt\u00e0, attraverso un miglioramento della mobilit\u00e0 urbana.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Confcommercio della provincia di Brindisi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La proposta formulata dalla CNA nell\u2019ambito della programmazione di interventi per il Contratto Istituzionale di Sviluppo (CIS) ci vede pienamente d\u2019accordo. Ampliare gli attuali confini della Circolare del mare e creare delle nuove aree di sosta sulle dorsali nord e sud consentirebbe un pi\u00f9 agevole accesso alla citt\u00e0. Il tutto, con evidenti benefici per l\u2019intero comparto commerciale. Importante anche aver ipotizzato un collegamento diretto tra porto e aeroporto (realizzato via mare) in quanto potrebbe determinare una notevole crescita del traffico crocieristico. E si integra perfettamente in un piano di valorizzazione della citt\u00e0 anche la creazione di un\u2019area fieristica, sempre in ambito portuale. &nbsp; La Confcommercio di Brindisi, pertanto, si augura che l\u2019Amministrazione Comunale esprima formale condivisione per tali proposte e dichiara la propria totale disponibilit\u00e0 ad approfondire le tematiche relative allo sviluppo commerciale ed economico della citt\u00e0, attraverso un miglioramento della mobilit\u00e0 urbana. &nbsp; &nbsp; Confcommercio della provincia di Brindisi<\/p>\n","protected":false},"author":2,"featured_media":155848,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-159405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=159405"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159405\/revisions"}],"predecessor-version":[{"id":159407,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159405\/revisions\/159407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/155848"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=159405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=159405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=159405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}