{"id":159510,"date":"2019-08-16T12:30:24","date_gmt":"2019-08-16T10:30:24","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=159510"},"modified":"2019-08-18T13:22:52","modified_gmt":"2019-08-18T11:22:52","slug":"happy-casa-brindisi-ecco-i-numeri-della-prossima-stagione-conferme-per-brown-00-e-banks-0","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/happy-casa-brindisi-ecco-i-numeri-della-prossima-stagione-conferme-per-brown-00-e-banks-0\/","title":{"rendered":"Happy Casa Brindisi, ecco i numeri della prossima stagione: conferme per Brown 00 e Banks 0"},"content":{"rendered":"<p>Tra conferme e volti nuovi, la stagione sportiva 2019\/2020 della Happy Casa Brindisi comincia, giorno dopo giorno, a prendere sempre pi\u00f9 forma.<\/p>\n<p>In queste ore il team biancoazzurro, a seguito del raduno iniziato luned\u00ec scorso, \u00e8 in palestra per svolgere e completare la prima settimana di lavoro atletico e fisico sotto la guida del preparatore Marco Sist e dello staff tecnico della Happy Casa.<br \/>\nUna nuova stagione ricca di impegni e appuntamenti: tra regular season di Lega A, fase a gironi della FIBA Basketball Champions League e la Supercoppa Italiana di Bari saranno infatti almeno 48 le partite ufficiali che la squadra affronter\u00e0 nel suo percorso stagionale.<\/p>\n<p>&nbsp;<\/p>\n<p>Questa \u00e8 la numerazione scelta dai giocatori biancoazzurri per la stagione sportiva 2019\/2020:<br \/>\n#00 \u2013 John Brown III<br \/>\n#0 \u2013 Adrian Banks<br \/>\n#1 \u2013 Kelvin Martin<br \/>\n#6 \u2013 Alessandro Zanelli<br \/>\n#7 \u2013 Antonio Iannuzzi<br \/>\n#10 \u2013 Raphael Gaspardo<br \/>\n#12 \u2013 Luca Campogrande<br \/>\n#15 \u2013 Darius Thompson<br \/>\n#18 \u2013 Riccardo Cattapan<br \/>\n#33 \u2013 Tyler Stone<br \/>\n#35 \u2013 Iris Ikangi<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Ufficio Stampa Happy Casa Brindisi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tra conferme e volti nuovi, la stagione sportiva 2019\/2020 della Happy Casa Brindisi comincia, giorno dopo giorno, a prendere sempre pi\u00f9 forma. In queste ore il team biancoazzurro, a seguito del raduno iniziato luned\u00ec scorso, \u00e8 in palestra per svolgere e completare la prima settimana di lavoro atletico e fisico sotto la guida del preparatore Marco Sist e dello staff tecnico della Happy Casa. Una nuova stagione ricca di impegni e appuntamenti: tra regular season di Lega A, fase a gironi della FIBA Basketball Champions League e la Supercoppa Italiana di Bari saranno infatti almeno 48 le partite ufficiali che la squadra affronter\u00e0 nel suo percorso stagionale. &nbsp; Questa \u00e8 la numerazione scelta dai giocatori biancoazzurri per la stagione sportiva 2019\/2020: #00 \u2013 John Brown III #0 \u2013 Adrian Banks #1 \u2013 Kelvin Martin #6 \u2013 Alessandro Zanelli #7 \u2013 Antonio Iannuzzi #10 \u2013 Raphael Gaspardo #12 \u2013 Luca Campogrande #15 \u2013 Darius Thompson #18 \u2013 Riccardo Cattapan #33 \u2013 Tyler Stone #35 \u2013 Iris Ikangi &nbsp; &nbsp; Ufficio Stampa&#8230;<\/p>\n","protected":false},"author":2,"featured_media":159511,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-159510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=159510"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159510\/revisions"}],"predecessor-version":[{"id":159512,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159510\/revisions\/159512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/159511"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=159510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=159510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=159510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}