{"id":159537,"date":"2019-08-17T19:37:28","date_gmt":"2019-08-17T17:37:28","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=159537"},"modified":"2019-08-18T10:41:43","modified_gmt":"2019-08-18T08:41:43","slug":"dipietrangelo-cosa-si-vuole-che-diventi-il-porto-di-brindisi","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/dipietrangelo-cosa-si-vuole-che-diventi-il-porto-di-brindisi\/","title":{"rendered":"Dipietrangelo: &#8220;Cosa si vuole che diventi il porto di Brindisi?&#8221;"},"content":{"rendered":"<p>Sul porto di Brindisi si continua da anni a discutere senza mai una fine. Convegni, polemiche, scelte discutibili, si susseguono ma il porto rimane sempre quello che era: un porto naturale, infrastrutturato nei secoli passati e per ultimo negli anni 60 al servizio della zona industriale. Interventi seri per adeguarlo alle esigenze di tutti i cambiamenti che ci sono stati nella competizione portuale italiana e mediterranea sono stati molto pochi e qualche volta sbagliati e inutili o addirittura bloccati. Il porto di Brindisi rimane bello a guardarlo, cos\u00ec come le sue potenzialit\u00e0 polifunzionali. Ma tutto questo non \u00e8 sufficiente per essere reso produttivo, attrattivo e competitivo. Il ritorno al passato sia quello dei turisti dei traghetti per la Grecia (anni 60\/70\/80) cos\u00ec come quello al servizio di una industria di base e di servizio(petrolchimica e combustibili fossili) non \u00e8 pi\u00f9 proponibile. In Grecia la stragrande maggioranza dei turisti va in aereo e le navi attuali di ultima generazione non possono pi\u00f9 essere ospitate nel piccolo porto interno, il vecchio apparato produttivo industriale si sta ridimensionando e una parte di esso \u00e8 in una fase d\u00ec esaurimento. Sono indicativi i dati della movimentazione delle merci e delle rinfuse di questi ultimi anni cos\u00ec come chiare dovrebbero essere le prospettive di alcuni settori come quello energetico.<\/p>\n<p>Allora il porto pu\u00f2 rimanere lo stesso dei decenni passati o addirittura far tornare le sue aree a quando c\u2019erano le spiagge? In tutti i vecchi porti del Mediterraneo \u00e8 stata fatta una pianificazione da cui sono scaturiti investimenti strutturali e infrastrutturali, a questi porti si sono aggiunti nuovi porti come quelli costruiti nel nord Africa che gi\u00e0 intercettano vecchi e nuovi traffici marittimi. E noi a Brindisi facciamo convegni e polemiche. Sono stato tra quelli che salutarono con favore la legge che istitu\u00ec le autorit\u00e0 portuali e che BRINDISI fosse stata dotata di una sua autorit\u00e0 sganciandola da quello che era il consorzio del porto e dell\u2019area industriale.<\/p>\n<p>&nbsp;<\/p>\n<p>Nell\u2019ulteriore e successiva riforma(quella Delrio) ho sostenuto l\u2019opportunit\u00e0 di dar vita in Puglia ad una unica autorit\u00e0 portuale. Ne furono decise invece due, una a Taranto e una Bari a discapito del porto di Brindisi che cos\u00ec ha perso in autonomia e in funzionalit\u00e0 competitiva. Purtroppo il bilancio di queste riforme non \u00e8 lusinghiero per il porto a tal punto che mai come in questa situazione si pu\u00f2 dire&#8230; che si stava meglio quando pensavamo che stavamo peggio&#8230;.. Tutti i presidenti e commissari che si sono susseguiti in questi anni non sono stati all\u2019altezza delle potenzialit\u00e0 del porto ma soprattutto non hanno capito in tempo che la portualita\u2019, le navi, i traffici stavano cambiando con la globalizzazione e che i servizi e le infrastrutture del porto di Brindisi erano ormai datati.<\/p>\n<p>&nbsp;<\/p>\n<p>Si \u00e8 perso molto tempo a pensare e a progettare interventi nuovi e necessari per ridare attrattivita\u2019 e competitivit\u00e0 al porto. Ma quello che \u00e8 stato e tuttora \u00e8 il maggiore limite \u00e8 che non c\u2019\u00e8 mai una discussione serena e competente per decidere quello che si vuole che sia il porto di Brindisi, sia alla luce dei nuovi possibili traffici e sia di quelle che sono le sue necessarie riconversioni a fronte di quello che \u00e8 il lento esaurimento del vecchio apparato industriale brindisino.<\/p>\n<p>&nbsp;<\/p>\n<p>Ci sono molti soggetti di una presunta governance allargata che l\u2019ultima riforma dei porti ha accentuato. Il porto di Brindisi si trova al crocevia di poteri che invece di interagire, interferiscono. Una autorit\u00e0 portuale che si trova a Bari, un Consorzio Asi che ha potest\u00e0 su aree retroportuali, la capitaneria di porto con tutte le sue funzioni, il comune che si trova con un porto dentro la citt\u00e0 e che lo considera giustamente uno degli asset del proprio sviluppo. Se non si trova una sede e se non si costruisce un approccio collaborativo e sinergico, il porto di Brindisi \u00e8 destinato ad uscire fuori dai traffici pi\u00f9 interessanti e redditizi per diventare sempre pi\u00f9 residuale rispetto alla portualita\u2019 del mediterraneo che nel frattempo continua a spostare e ad attrarre vecchi e nuovi traffici. Allora la domanda che si devono fare coloro che hanno delle responsabilit\u00e0 amministrative ed economiche, cosa si vuole che diventi il porto di Brindisi? I porti sono attivit\u00e0 economiche come tali richiedono investimenti, adeguamenti e innovazioni continui. Le navi non sono quelle di una volta e richiedono infrastrutture, fondali, servizi diversi, qualificati ed efficienti, altrimenti o non arrivano o se ne vanno altrove.<\/p>\n<p>Abbiamo letto del parere negativo dato alla colmata, bene, ma quale \u00e8 l\u2019alternativa che va data e realizzata per adeguare i fondali o si deve bloccare tutto sine die? Cos\u00ec come si \u00e8 letto in queste ore che ci sarebbe un parere negativo da parte dell\u2019amministrazione comunale per il pontile a briccole per utilizzare in sicurezza banchine utili agli attuali traffici. Quale \u00e8 il motivo? Mi auguro che si faccia chiarezza definitiva su tutte le banchine e sulle aree portuali, sulla loro fruizione compatibile e sostenibile. Che ci vuole per definire un piano degli spazi attuali e delle aree necessarie per nuovi, qualificati e sicuri servizi, liberandosi da vecchie logiche e consuetudini? Insomma se il porto \u00e8 un asset importante dello sviluppo di brindisi va reso produttivo e attrattivo di traffici, altrimenti non \u00e8 un porto! L\u2019ultimo piano triennale delle opere portuali deciso e approvato dall\u2019Autorita\u2019 di sistema sembrava andare in questa direzione anche se in maniera alquanto frenata in materia di investimenti se non per quelli a suo tempo progettati.<\/p>\n<p>&nbsp;<\/p>\n<p>Di tutto ha bisogno il porto tranne che di ulteriori conflitti, polemiche o addirittura di vecchi attriti che nulla hanno a che fare con la nostra citt\u00e0.<br \/>\nInfine mi sono chiesto pi\u00f9 volte se quelli che parlano e intervengono sul porto di Brindisi, hanno mai visto e visitato un porto o se conoscono il porto di Brindisi, la sua conformazione, le sue aree.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Carmine Dipietrangelo<br \/>\nPresidente Left Brindisi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sul porto di Brindisi si continua da anni a discutere senza mai una fine. Convegni, polemiche, scelte discutibili, si susseguono ma il porto rimane sempre quello che era: un porto naturale, infrastrutturato nei secoli passati e per ultimo negli anni 60 al servizio della zona industriale. Interventi seri per adeguarlo alle esigenze di tutti i cambiamenti che ci sono stati nella competizione portuale italiana e mediterranea sono stati molto pochi e qualche volta sbagliati e inutili o addirittura bloccati. Il porto di Brindisi rimane bello a guardarlo, cos\u00ec come le sue potenzialit\u00e0 polifunzionali. Ma tutto questo non \u00e8 sufficiente per essere reso produttivo, attrattivo e competitivo. Il ritorno al passato sia quello dei turisti dei traghetti per la Grecia (anni 60\/70\/80) cos\u00ec come quello al servizio di una industria di base e di servizio(petrolchimica e combustibili fossili) non \u00e8 pi\u00f9 proponibile. In Grecia la stragrande maggioranza dei turisti va in aereo e le navi attuali di ultima generazione non possono pi\u00f9 essere ospitate nel piccolo porto interno, il vecchio apparato&#8230;<\/p>\n","protected":false},"author":2,"featured_media":102102,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-159537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=159537"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159537\/revisions"}],"predecessor-version":[{"id":159538,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159537\/revisions\/159538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/102102"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=159537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=159537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=159537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}