{"id":159627,"date":"2019-08-19T14:26:39","date_gmt":"2019-08-19T12:26:39","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=159627"},"modified":"2019-08-19T14:36:44","modified_gmt":"2019-08-19T12:36:44","slug":"presentata-la-xxii-edizione-della-rassegna-di-musica-antica-barocco-festival-leonardo-leo","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/presentata-la-xxii-edizione-della-rassegna-di-musica-antica-barocco-festival-leonardo-leo\/","title":{"rendered":"Presentata la XXII edizione della rassegna di musica antica  \u201cBarocco Festival Leonardo Leo\u201d"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/08\/Visual-2019.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-159633\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/08\/Visual-2019-214x300.jpg\" alt=\"\" width=\"214\" height=\"300\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/08\/Visual-2019-214x300.jpg 214w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/08\/Visual-2019.jpg 684w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a>Nella mattinata di luned\u00ec 19 agosto \u00e8 stata presentata nel salone di rappresentanza della Prefettura di Brindisi la XXII Edizione della rassegna di musica antica &#8220;Barocco Festival Leonardo Leo&#8221;. All&#8217;incontro hanno preso parte il Viceprefetto Maria Rita COLUCCIA, il sindaco di San Vito dei Normanni, Domenico CONTE, il Sindaco di Brindisi, Riccardo ROSSI, il Vice Sindaco di Ostuni, Antonella PALMISANO e il direttore artistico del Festival, Cosimo Prontera nonch\u00e9 il prof. Dinko FABRIS.<\/p>\n<p>&nbsp;<\/p>\n<p>La rassegna avr\u00e0 inizio gioved\u00ec 22 agosto p.v., presso il Chiostro dei Domenicani a San Vito dei Normanni e proseguir\u00e0 con altri 6 appuntamenti organizzati nei Comuni che hanno collaborato alla realizzazione di questa edizione .<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217; ingresso \u00e8 gratuito.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/08\/Programma-edizione-2019.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-159632 alignleft\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/08\/Programma-edizione-2019-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/08\/Programma-edizione-2019-212x300.jpg 212w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/08\/Programma-edizione-2019-768x1087.jpg 768w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/08\/Programma-edizione-2019-723x1024.jpg 723w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/08\/Programma-edizione-2019.jpg 1413w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><br \/>\n<\/a>PROGRAMMA:<br \/>\n____________________________________________<\/p>\n<p>Gioved\u00ec 22 agosto ore 21.00 &#8211; San Vito dei Normanni, Chiostro dei Domenicani<br \/>\nInaugurazione Festival<br \/>\nDALLA MORTE ALLA VITA DI SANTA MARIA MADDALENA<br \/>\nDramma sacro &#8211; Musica di Leonardo Leo<br \/>\nPrima esecuzione assoluta<\/p>\n<p>Orchestra Barocca La Confraternita de\u2019 Musici<br \/>\nCosimo Prontera direttore<\/p>\n<p>Raffaele Romano conduzione serata<\/p>\n<p>___________________________________________________<\/p>\n<p>Domenica 25 agosto ore 21.00 &#8211; Brindisi, ex Chiostro di San Paolo Eremita<br \/>\nL\u2019EUROPA, L\u2019ITALIA, NAPOLI<br \/>\nLa letteratura per flauto dolce<br \/>\nDan Laurin flauto dolce<\/p>\n<p>Orchestra Barocca La Confraternita de\u2019 Musici<br \/>\nCosimo Prontera direttore<\/p>\n<p>___________________________________________________<\/p>\n<p>Marted\u00ec 27 agosto ore 21.00 &#8211; San Vito dei Normanni, Chiostro dei Domenicani<br \/>\nSOY CONTENTO Y VOS SERVIDA<br \/>\nLa Spagna rinascimentale<br \/>\nBaltazar Z\u00fa\u00f1iga tenore<\/p>\n<p>Ensemble Contrarco Consort<br \/>\nGianfranco Russo viola e direzione<\/p>\n<p>___________________________________________________<\/p>\n<p>Gioved\u00ec 29 agosto ore 21.00 &#8211; Brindisi, Chiostro del Palazzo Vescovile<br \/>\nTARTINI<br \/>\nTra colleghi, amici, rivali<\/p>\n<p>Ensemble L\u2019arte dell\u2019arco<br \/>\nFederico Guglielmo violino solista<\/p>\n<p>___________________________________________________<\/p>\n<p>Sabato 31 agosto ore 21.00 &#8211; Ostuni, chiesa dell\u2019Annunziata (Chiostro)<br \/>\nFRIEND OR FOE? (Amici o nemici?)<br \/>\nLeonardo Vinci e Leonardo Leo<br \/>\nMarta Redaelli soprano<\/p>\n<p>Ensemble Armonia antiqua<br \/>\nLuca Campana direttore<\/p>\n<p>___________________________________________________<\/p>\n<p>Marted\u00ec 3 settembre ore 21.00 &#8211; Brindisi, zona Sciabiche (porto vecchio)<br \/>\nALFABETI<br \/>\nMusiche dal Mediterraneo<\/p>\n<p>Ensemble Kapsberger<br \/>\nRolf Lislevand direttore<\/p>\n<p>Antonio Celeste conduzione serata<\/p>\n<p>___________________________________________________<\/p>\n<p>Sabato 7 settembre ore 21.00 &#8211; San Vito dei Normanni, Chiostro dei Domenicani<br \/>\nLEONARDO|ODRANOEL<br \/>\nMusica e danza al tempo di Leonardo da Vinci a 500 anni dalla morte<\/p>\n<p>Ensemble Concentus &amp; Tempus Saltandi &#8211; Compagnia di danze storiche<\/p>\n<p>___________________________________________________<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella mattinata di luned\u00ec 19 agosto \u00e8 stata presentata nel salone di rappresentanza della Prefettura di Brindisi la XXII Edizione della rassegna di musica antica &#8220;Barocco Festival Leonardo Leo&#8221;. All&#8217;incontro hanno preso parte il Viceprefetto Maria Rita COLUCCIA, il sindaco di San Vito dei Normanni, Domenico CONTE, il Sindaco di Brindisi, Riccardo ROSSI, il Vice Sindaco di Ostuni, Antonella PALMISANO e il direttore artistico del Festival, Cosimo Prontera nonch\u00e9 il prof. Dinko FABRIS. &nbsp; La rassegna avr\u00e0 inizio gioved\u00ec 22 agosto p.v., presso il Chiostro dei Domenicani a San Vito dei Normanni e proseguir\u00e0 con altri 6 appuntamenti organizzati nei Comuni che hanno collaborato alla realizzazione di questa edizione . &nbsp; L&#8217; ingresso \u00e8 gratuito. &nbsp; PROGRAMMA: ____________________________________________ Gioved\u00ec 22 agosto ore 21.00 &#8211; San Vito dei Normanni, Chiostro dei Domenicani Inaugurazione Festival DALLA MORTE ALLA VITA DI SANTA MARIA MADDALENA Dramma sacro &#8211; Musica di Leonardo Leo Prima esecuzione assoluta Orchestra Barocca La Confraternita de\u2019 Musici Cosimo Prontera direttore Raffaele Romano conduzione serata ___________________________________________________ Domenica 25 agosto ore 21.00&#8230;<\/p>\n","protected":false},"author":2,"featured_media":159628,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-159627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=159627"}],"version-history":[{"count":4,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159627\/revisions"}],"predecessor-version":[{"id":159635,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159627\/revisions\/159635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/159628"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=159627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=159627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=159627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}