{"id":159832,"date":"2019-08-23T21:18:35","date_gmt":"2019-08-23T19:18:35","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=159832"},"modified":"2019-08-23T18:20:58","modified_gmt":"2019-08-23T16:20:58","slug":"mandorle-e-sapori-a-corte-approda-a-carovigno","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/mandorle-e-sapori-a-corte-approda-a-carovigno\/","title":{"rendered":"&#8220;Mandorle e Sapori a Corte\u201d approda a Carovigno"},"content":{"rendered":"<p>\u201cMandorle e Sapori a Corte\u201d \u00e8 un evento dedicato alla Mandorla; non una sagra ma una festa liberamente ispirata al frutto dalla mille qualit\u00e0 la cui produzione e lavorazione sono molto radicate in Puglia: versatile in cucina, poliedrico nella sua applicazione in cosmetica come nella dietetica.<br \/>\nL&#8217;offerta culturale ed artistica associata alle giornate dell&#8217;evento spinge ad una migliore comprensione dell&#8217;humus in cui la manifestazione \u00e8 nata e cresce, edizione dopo edizione. Si affacciano, nel cartellone, animazione e musica per bambini, eventi culturali, degustazioni, passando per animazione e musica dal vivo. L&#8217;iniziativa \u00e8 organizzata con il patrocinio del Comune di Carovigno, della Regione Puglia, in collaborazione con la Coldiretti di Brindisi, la CIA (Confederazione Italiana Agricoltura), il Gal Alto Salento e l&#8217;Associazione Culturale Sud Est nel Cuore.<br \/>\nNel corso di un\u2019apposita presentazione, il prossimo 26 Agosto, alle ore 17.30 presso la Sala delle Cerimonie del Castello Dentice di Frasso, il sindaco Massimo Vittorio Lanzillotti e l\u2019assessore al Turismo e Marketing Territoriale Antonella Tateo di Carovigno insieme a Michele Fortunato e Maria Mazzarelli  dell\u2019Associazione Sud Est nel Cuore renderanno noti l\u2019iniziativa e il programma completo degli eventi che animeranno il centro storico del comune del brindisino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cMandorle e Sapori a Corte\u201d \u00e8 un evento dedicato alla Mandorla; non una sagra ma una festa liberamente ispirata al frutto dalla mille qualit\u00e0 la cui produzione e lavorazione sono molto radicate in Puglia: versatile in cucina, poliedrico nella sua applicazione in cosmetica come nella dietetica. L&#8217;offerta culturale ed artistica associata alle giornate dell&#8217;evento spinge ad una migliore comprensione dell&#8217;humus in cui la manifestazione \u00e8 nata e cresce, edizione dopo edizione. Si affacciano, nel cartellone, animazione e musica per bambini, eventi culturali, degustazioni, passando per animazione e musica dal vivo. L&#8217;iniziativa \u00e8 organizzata con il patrocinio del Comune di Carovigno, della Regione Puglia, in collaborazione con la Coldiretti di Brindisi, la CIA (Confederazione Italiana Agricoltura), il Gal Alto Salento e l&#8217;Associazione Culturale Sud Est nel Cuore. Nel corso di un\u2019apposita presentazione, il prossimo 26 Agosto, alle ore 17.30 presso la Sala delle Cerimonie del Castello Dentice di Frasso, il sindaco Massimo Vittorio Lanzillotti e l\u2019assessore al Turismo e Marketing Territoriale Antonella Tateo di Carovigno insieme a Michele Fortunato e Maria&#8230;<\/p>\n","protected":false},"author":2,"featured_media":159836,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-159832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=159832"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159832\/revisions"}],"predecessor-version":[{"id":159838,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159832\/revisions\/159838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/159836"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=159832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=159832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=159832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}