{"id":159845,"date":"2019-08-24T11:40:16","date_gmt":"2019-08-24T09:40:16","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=159845"},"modified":"2019-08-24T11:40:16","modified_gmt":"2019-08-24T09:40:16","slug":"controlli-dei-carabinieri-a-mesagne-e-latiano-sequestri-e-denunce","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/controlli-dei-carabinieri-a-mesagne-e-latiano-sequestri-e-denunce\/","title":{"rendered":"Controlli dei Carabinieri a Mesagne e Latiano: sequestri e denunce"},"content":{"rendered":"<p>Prevenzione e repressione dei reati, \u00e8 questa la finalit\u00e0 delle attivit\u00e0 preventive e repressive proiettate sul territorio al fine di contrastare ogni forma di reato, al fine di assicurare l\u2019ordine e la sicurezza pubblica per i cittadini e infrenare tutte le forme di criminalit\u00e0 di qualsiasi matrice. Deferite 5 persone in stato di libert\u00e0 per vari reati, 8 soggetti segnalati quali assuntori di stupefacenti. Sono state effettuate 24 perquisizioni tra personali e domiciliari, 133 le auto controllate con oltre 248 persone identificate di cui 25 di particolare interesse operativo. Numerosi i posti di blocco effettuati sulle principali strade. Monitorati nell\u2019arco notturno 18 soggetti sottoposti dall\u2019Autorit\u00e0 Giudiziaria agli arresti domiciliari o alla sorveglianza speciale di pubblica sicurezza con obbligo di soggiorno.<\/p>\n<p>&nbsp;<\/p>\n<p>I Carabinieri del Comando Provinciale di Brindisi hanno effettuato un servizio straordinario di controllo del territorio ad \u201cAlto Impatto\u201d nelle citt\u00e0 di Latiano e Mesagne, con l\u2019esecuzione di numerosi posti di blocco e perquisizioni sia domiciliari che personali e di autoveicoli. L\u2019attivit\u00e0 \u00e8 stata finalizzata alla prevenzione e repressione dei reati contro la persona e il patrimonio e il contrasto allo spaccio di stupefacenti, nonch\u00e9 al controllo della circolazione stradale sulle arterie interessate da maggior traffico, per prevenire e reprimere condotte di guida che mettono in pericolo l\u2019incolumit\u00e0 delle persone. Il servizio attuato ha anche interessato le aree periferiche nonch\u00e9 le contrade rurali dei due Comuni.<\/p>\n<p>&nbsp;<\/p>\n<p>Nell\u2019ambito delle attivit\u00e0, i militari hanno denunciato in stato di libert\u00e0 7 persone rispettivamente:<\/p>\n<p>&#8211; un 3 soggetti di etnia Rom, denunciati a piede libero per furto aggravato, rispettivamente di 49, 41 e 33 anni due residenti in provincia di Bergamo e uno in provincia di Padova. Sul conto dei tre sono stati raccolti elementi di prova in relazione al furto di uno zaino contenente la somma di 3.600,00\u20ac asportato al proprietario di un esercizio commerciale.<\/p>\n<p>&#8211; Un 45enne residente a Carovigno, fermato alla guida dell\u2019autovettura Fiat Punto della moglie e sottoposto ad accertamento con l\u2019etilometro, le analisi gli hanno riscontrato un tasso alcolemico pari a 1,33G\/L. La patente di guida \u00e8 stata ritirata e il veicolo consegnato alla congiunta;<\/p>\n<p>&#8211; Un 22enne residente a Latiano \u00e8 stato sorpreso alla guida della vettura Lancia Y, in stato di alterazione psicofisica. Nella circostanza ha rifiutato di essere sottoposto agli accertamenti per la verifica dell\u2019assunzione di stupefacente e a seguito di perquisizione, \u00e8 stato trovato in possesso di un grammo di hashish. La patente di guida \u00e8 stata ritirata, il veicolo affidato al proprietario e lo stupefacente sottoposto a sequestro;<\/p>\n<p>&#8211; un 30enne di Latiano sorpreso alla guida di una Ford Fiesta di propriet\u00e0 di un\u2019amica, senza aver mai conseguito la patente di guida, con l\u2019aggravante della recidiva perch\u00e9 sanzionato per analoga violazione nello scorso mese di giugno dai Carabinieri di Gallipoli. Il veicolo \u00e8 stato restituito alla proprietaria denunciata per incauto affidamento.<\/p>\n<p>Nel corso di alcune perquisizioni, effettuate per la ricerca di stupefacente, sono stati segnalati alla Prefettura di Brindisi otto giovani, residenti tre in San Vito dei Normanni, due a Latiano, uno a Mesagne, due a Ostuni, trovati in possesso di modiche quantit\u00e0 di stupefacenti, nel complesso sono stati rinvenuti 7 grammi di hashish e 5 di marijuana sottoposti a sequestro.<\/p>\n<p>Nel complesso, i Carabinieri hanno eseguito 24 perquisizioni tra personali, domiciliari e di autoveicoli, identificato 248 persone di cui 25 di particolare interesse operativo, controllato 133 autoveicoli oltre a 7 esercizi pubblici. Sono state anche controllate 18 persone sottoposte dall\u2019Autorit\u00e0 Giudiziaria agli arresti domiciliari o alla Sorveglianza Speciale con obbligo di soggiorno nei comuni di Mesagne e Latiano<\/p>\n<p>&nbsp;<\/p>\n<p>Tutti i servizi effettuati dalla Compagnia hanno avuto il supporto di un\u2019aliquota di militari della Compagnia di Intervento Operativo dell\u201911 Reggimento Carabinieri \u201cPuglia\u201d di Bari. Si tratta di contingenti di militari particolarmente addestrati nel controllo del territorio impiegati a supporto dei reparti stanziali al fine di prevenire e reprimere attraverso una pi\u00f9 visibile ed intensa attivit\u00e0 di controllo del territorio la recrudescenza di specifici fenomeni criminosi. Il personale destinato a questo tipo di Reparto (8 sono le Compagnie C.I.O. istituite sul territorio nazionale e sono inquadrate all\u2019interno dei Reggimenti e Battaglioni Mobili), \u00e8 costituito da militari selezionati, tutti volontari, previo un periodo di particolare addestramento e periodico ricondizionamento, improntato alla difesa personale al tiro di emergenza operativo, alle tecniche del controllo del territorio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prevenzione e repressione dei reati, \u00e8 questa la finalit\u00e0 delle attivit\u00e0 preventive e repressive proiettate sul territorio al fine di contrastare ogni forma di reato, al fine di assicurare l\u2019ordine e la sicurezza pubblica per i cittadini e infrenare tutte le forme di criminalit\u00e0 di qualsiasi matrice. Deferite 5 persone in stato di libert\u00e0 per vari reati, 8 soggetti segnalati quali assuntori di stupefacenti. Sono state effettuate 24 perquisizioni tra personali e domiciliari, 133 le auto controllate con oltre 248 persone identificate di cui 25 di particolare interesse operativo. Numerosi i posti di blocco effettuati sulle principali strade. Monitorati nell\u2019arco notturno 18 soggetti sottoposti dall\u2019Autorit\u00e0 Giudiziaria agli arresti domiciliari o alla sorveglianza speciale di pubblica sicurezza con obbligo di soggiorno. &nbsp; I Carabinieri del Comando Provinciale di Brindisi hanno effettuato un servizio straordinario di controllo del territorio ad \u201cAlto Impatto\u201d nelle citt\u00e0 di Latiano e Mesagne, con l\u2019esecuzione di numerosi posti di blocco e perquisizioni sia domiciliari che personali e di autoveicoli. L\u2019attivit\u00e0 \u00e8 stata finalizzata alla prevenzione e repressione&#8230;<\/p>\n","protected":false},"author":2,"featured_media":159846,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-159845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=159845"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159845\/revisions"}],"predecessor-version":[{"id":159847,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159845\/revisions\/159847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/159846"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=159845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=159845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=159845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}