{"id":159886,"date":"2019-08-25T12:11:31","date_gmt":"2019-08-25T10:11:31","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=159886"},"modified":"2019-08-25T12:11:31","modified_gmt":"2019-08-25T10:11:31","slug":"bms-articolo-uno-fa-specie-leggere-le-dichiarazioni-del-dottor-palasciano","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/bms-articolo-uno-fa-specie-leggere-le-dichiarazioni-del-dottor-palasciano\/","title":{"rendered":"BMS, Articolo Uno: &#8220;Fa specie leggere le dichiarazioni del dottor Palasciano&#8221;"},"content":{"rendered":"<p>Fa specie, e parecchio, leggere le dichiarazioni del dottor Palasciano, amministratore unico della Brindisi Multiservizi, sulla stampa.<br \/>\nEgli dichiara, facendo riferimento quello che generalmente \u00e8 il ruolo di un amministratore di societ\u00e0: \u201cla capacit\u00e0 dell\u2019amministratore, semmai, \u00e8 quella di mantenere sempre l\u2019equilibrio economico e finanziario con le risorse che il Comune trasferisce. Quando non ci riesce, lo comunica e ognuno ne prende atto\u201d.<\/p>\n<p>Dimenticando che l\u2019amministratore non deve solo mantenere in equilibrio la societ\u00e0; a lui \u00e8 richiesto di mostrare livelli di diligenza adeguati alla mansione. Livelli che importano evidentemente non solo preparazioni professionali ma capacit\u00e0 gestionali e competenze organizzative, capacit\u00e0 di pianificare e controllare i costi e gestire le risorse umane e non .<br \/>\nSe cos\u00ec non fosse sarebbe stato sufficiente reclutare un ragioniere con buone competenze.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019amministratore deve avere la capacit\u00e0 di rappresentare gli indirizzi di chi lo ha designato orientato l\u2019azione della societ\u00e0 in modo coerente agli interessi del socio, e nel caso della BMS nell\u2019interesse della collettivit\u00e0.<\/p>\n<p>Pi\u00f9 volte \u00e8 stato chiesto al dott. Palasciano, da parte del sindaco e degli amministratori, di provvedere alla riorganizzazione del personale al fine di rendere servizi idonei al bisogno della Citt\u00e0.<br \/>\nPi\u00f9 volte \u00e8 stato lo stesso Sindaco, superando i ruoli e con il fine di mettersi a disposizione della collettivit\u00e0, a dare indicazioni sulle modalit\u00e0 di riorganizzazione della squadra del verde. Senza sortire risultati duraturi.<br \/>\nE lo stato in cui versa della citt\u00e0 lo dimostra.<\/p>\n<p>&nbsp;<\/p>\n<p>E le incongruenze si leggono anche confrontandolo nel piano industriale predisposto dallo stesso amministratore. In questo documento egli evidenzia che il settore del verde \u00e8 composto da 26 unit\u00e0, di cui 24 operai. In realt\u00e0 la composizione della squadra che quotidianamente opera sul verde, come accertato durante vari sopralluoghi, vede impegnati mediamente 10 operatori.<br \/>\nE di tutta evidenza, quindi, che problema non \u00e8, come dichiara l\u2019amministratore, risolvibile \u201ccon le assunzioni anche part-time\u201d se prima non viene posta in atto una riorganizzazione dell\u2019azienda e definito un piano gestione del personale.<br \/>\nDiventa anche difficile comprendere come saranno spesi gli oltre 7 milioni di euro che saranno trasferiti nell\u2019arco del 2019 dal Comune di Brindisi alla BMS.<br \/>\nSolo dopo aver \u201cnormalizzato\u201d la partecipata sar\u00e0 possibile pensare a nuove assunzioni in funzione dei servizi che il Comune affider\u00e0 con il prossimo contratto di servizio.<\/p>\n<p>Bisogna prendere spunto da questa situazione di malessere per fare le opportune valutazioni sull\u2019operato delle partecipate dal Comune di Brindisi (BMS, Energeko, Farmacie Comunali, Consorzio ASI ed STP) misurando efficacia e grado di efficienza dei servizi erogati e quindi una valutazione degli amministratori, della loro diligenza ma soprattutto della loro adeguatezza.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Articolo Uno<\/strong><\/em><br \/>\n<em><strong>Coordinamento cittadino di Brindisi<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fa specie, e parecchio, leggere le dichiarazioni del dottor Palasciano, amministratore unico della Brindisi Multiservizi, sulla stampa. Egli dichiara, facendo riferimento quello che generalmente \u00e8 il ruolo di un amministratore di societ\u00e0: \u201cla capacit\u00e0 dell\u2019amministratore, semmai, \u00e8 quella di mantenere sempre l\u2019equilibrio economico e finanziario con le risorse che il Comune trasferisce. Quando non ci riesce, lo comunica e ognuno ne prende atto\u201d. Dimenticando che l\u2019amministratore non deve solo mantenere in equilibrio la societ\u00e0; a lui \u00e8 richiesto di mostrare livelli di diligenza adeguati alla mansione. Livelli che importano evidentemente non solo preparazioni professionali ma capacit\u00e0 gestionali e competenze organizzative, capacit\u00e0 di pianificare e controllare i costi e gestire le risorse umane e non . Se cos\u00ec non fosse sarebbe stato sufficiente reclutare un ragioniere con buone competenze. &nbsp; L\u2019amministratore deve avere la capacit\u00e0 di rappresentare gli indirizzi di chi lo ha designato orientato l\u2019azione della societ\u00e0 in modo coerente agli interessi del socio, e nel caso della BMS nell\u2019interesse della collettivit\u00e0. Pi\u00f9 volte \u00e8 stato chiesto al dott. Palasciano,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":98835,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-159886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=159886"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159886\/revisions"}],"predecessor-version":[{"id":159890,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159886\/revisions\/159890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/98835"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=159886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=159886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=159886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}