{"id":159970,"date":"2019-08-27T12:52:17","date_gmt":"2019-08-27T10:52:17","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=159970"},"modified":"2019-08-27T12:13:10","modified_gmt":"2019-08-27T10:13:10","slug":"terramare-apre-la-terza-edizione-del-cabiria-art-fest","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/terramare-apre-la-terza-edizione-del-cabiria-art-fest\/","title":{"rendered":"\u201cTerrAmare\u201d apre la terza edizione del Cabiria Art Fest"},"content":{"rendered":"<p>Tutto pronto per la III edizione del Cabiria Art Fest che da gioved\u00ec 29 agosto fino a domenica 1 settembre animer\u00e0 l\u2019incantevole chiostro del Castello Normanno Svevo di Mesagne. Una festa lunga tre giorni e dedicata alle diverse forme d\u2019Arte organizzata dall\u2019associazione Cabiria e patrocinata dal Comune di Mesagne e Arci Brindisi. La direzione artistica \u00e8 affidata ad Anna Rita Pinto che anche quest\u2019anno ha selezionato spettacoli di intrattenimento diversi e adatti a un pubblico vasto ma sempre attento alla qualit\u00e0 della proposta. Ogni serata sar\u00e0 divisa in 3 momenti: dalle ore 21:00 alle ore 21:30 si esibiranno Artisti del territorio; dalle 21:30 alle 23:00 si dar\u00e0 spazio a spettacoli a distribuzione nazionale; dalle 23:00 alle 23:30 i protagonisti degli spettacoli si concederanno in un\u2019intervista aperta con il pubblico che potr\u00e0 interagire con loro con domande e curiosit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>Il primo appuntamento \u00e8 per gioved\u00ec 29 agosto alle ore 21:00 con \u201cPiccole storie\u201d Reading di racconti brevi di diversi generi scritti dagli Autori dell\u2019Accademia di Cinema e Scrittura Creativa \u201cCine Script\u201d Giuseppe Summa, Raffaella Ricci, Francesca D\u2019Abramo e interpretati dall\u2019attore Davide Scalera. Alle ore 21:30 spettacolo teatrale \u201cTerrAmare\u201d di Marcantonio Gallo e Fabrizio Cito con Marcantonio Gallo, Antonella Colucci, Giuseppe Nacci, Giampiera Dimonte, Antonio D\u2019Andria e con Luciano Gennari alla chitarra. Ispirata ad una leggenda dell&#8217;entroterra pugliese e in un&#8217;epoca in cui la natura di certi amori \u00e8 inconfessabile, a TerrAmare si mescolano i desideri e i destini dei suoi abitanti che cambieranno in una notte.<\/p>\n<p>&nbsp;<\/p>\n<p>Il secondo appuntamento \u00e8 venerd\u00ec 30 agosto con la proiezione del cortometraggio \u201cViaggiare dentro\u201d di Anna Rita Pinto e Giovanni Politi e a seguire la proiezione del lungometraggio \u201cIl pi\u00f9 grande sogno\u201d di Michele Vannucci. Al termine, incontro con Mirko Frezza, l\u2019attore protagonista a cui \u00e8 ispirata la storia.<\/p>\n<p>Ogni serata ha un costo variabile dalle 3 alle 5 euro a persona (abbonamento 8 euro per i soci di Cabiria). Sar\u00e0 possibile acquistare i biglietti solo in prevendita fino ad esaurimento posti presso la sede dell\u2019associazione Cabiria a Mesagne, in piazza Orsini del Balzo 9 dalle 18:30 alle 21:00 e nei giorni del Festival dalle 20:00 alle ore 21:30. Info e prevendita al 327 4237720.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Ufficio Stampa Cabiria<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tutto pronto per la III edizione del Cabiria Art Fest che da gioved\u00ec 29 agosto fino a domenica 1 settembre animer\u00e0 l\u2019incantevole chiostro del Castello Normanno Svevo di Mesagne. Una festa lunga tre giorni e dedicata alle diverse forme d\u2019Arte organizzata dall\u2019associazione Cabiria e patrocinata dal Comune di Mesagne e Arci Brindisi. La direzione artistica \u00e8 affidata ad Anna Rita Pinto che anche quest\u2019anno ha selezionato spettacoli di intrattenimento diversi e adatti a un pubblico vasto ma sempre attento alla qualit\u00e0 della proposta. Ogni serata sar\u00e0 divisa in 3 momenti: dalle ore 21:00 alle ore 21:30 si esibiranno Artisti del territorio; dalle 21:30 alle 23:00 si dar\u00e0 spazio a spettacoli a distribuzione nazionale; dalle 23:00 alle 23:30 i protagonisti degli spettacoli si concederanno in un\u2019intervista aperta con il pubblico che potr\u00e0 interagire con loro con domande e curiosit\u00e0. &nbsp; Il primo appuntamento \u00e8 per gioved\u00ec 29 agosto alle ore 21:00 con \u201cPiccole storie\u201d Reading di racconti brevi di diversi generi scritti dagli Autori dell\u2019Accademia di Cinema e Scrittura Creativa \u201cCine&#8230;<\/p>\n","protected":false},"author":2,"featured_media":141616,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-159970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=159970"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159970\/revisions"}],"predecessor-version":[{"id":159972,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/159970\/revisions\/159972"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/141616"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=159970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=159970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=159970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}