{"id":160069,"date":"2019-08-29T18:59:23","date_gmt":"2019-08-29T16:59:23","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=160069"},"modified":"2019-08-29T18:59:23","modified_gmt":"2019-08-29T16:59:23","slug":"giovedi-5-a-brindisi-va-in-scena-lo-spettacolo-teatrale-humana-vergogna","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/giovedi-5-a-brindisi-va-in-scena-lo-spettacolo-teatrale-humana-vergogna\/","title":{"rendered":"Gioved\u00ec 5 a Brindisi va in scena lo spettacolo teatrale \u00abHumana Vergogna\u00bb"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/08\/Humana-Vergogna-6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-160075\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/08\/Humana-Vergogna-6-210x300.jpg\" alt=\"\" width=\"210\" height=\"300\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/08\/Humana-Vergogna-6-210x300.jpg 210w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/08\/Humana-Vergogna-6-768x1098.jpg 768w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/08\/Humana-Vergogna-6-716x1024.jpg 716w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2019\/08\/Humana-Vergogna-6.jpg 992w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/a><br \/>\nRiparte da Brindisi, gioved\u00ec 5 settembre alle ore 21 nel giardino dell\u2019ex Convento Santa Chiara (ingresso gratuito con prenotazioni al T. 338 3746581), il tour internazionale dello spettacolo teatrale \u00abHumana Vergogna\u00bb. Poi tappe a Podgorica (Montenegro, 9 settembre) e Skopje (Macedonia del Nord, 16 settembre).<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abHumana Vergogna\u00bb, la performance coprodotta da Fondazione Matera-Basilicata 2019 e #reteteatro41 (Compagnia teatrale Petra, Gommalacca Teatro, L\u2019Albero e IAC), diretta da Silvia Gribaudi e Matteo Maffesanti, nell\u2019ambito del programma culturale di Matera 2019 Capitale Europea della Cultura, riprende la sua circuitazione internazionale.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abHumana Vergogna\u00bb sar\u00e0 il prossimo gioved\u00ec 5 settembre &#8211; ore 21 &#8211; a Brindisi, in collaborazione con la Fondazione Teatro Verdi, nel giardino dell\u2019ex Convento Santa Chiara (ingresso gratuito con prenotazione obbligatoria T. 338 3746581) per poi partecipare a due tra i pi\u00f9 importanti festival dei Balcani: il 9 settembre per la cerimonia di apertura del Fiat Festival &#8211; Festival Internacionalnog Alternativnog Teatra di Podgorica) e il 16 settembre al Mot Festival di Skopje. Il tour \u00e8 realizzato grazie al sostegno dei festival balcanici e di Eu Japan Fest.<\/p>\n<p>&nbsp;<\/p>\n<p>Lo spettacolo indaga le nostre vergogne, personali e collettive, familiari e sociali, quelle che teniamo nascoste e che il pudore ci impedisce di mostrare: vergogne che trattengono paure, fragilit\u00e0, disagi. Nasce da queste e da pi\u00f9 ampie riflessioni lo spettacolo tenuto a battesimo nella Casa Circondariale di Matera, e che ha visto direttamente coinvolti gli stessi detenuti, diretti testimoni di uno stato di grande vulnerabilit\u00e0. In scena cinque performer &#8211; Mattia Giordano, Antonella Iallorenzi, Mariagrazia Nacci, Simona Spirovska e Ema Tashiro &#8211; che si rivelano sotto una pelliccia da orso che funge da schermo protettivo che presto cadr\u00e0 a pezzi per fare posto a una realt\u00e0 taciuta fino a quel momento. E allora sar\u00e0 il tempo di liberarsi, con autoironia e leggerezza, di pesi legati all\u2019anima come massi di pietra, dunque di mostrare obesit\u00e0, imperfezioni e bellezze del proprio fisico, di confessare davanti a tutti le proprie vergogne. Come quella di una donna di baciare un\u2019altra donna, o la vergogna del diverso, del fallimento, dei pregiudizi. C\u2019\u00e8 anche la vergogna per il proprio Paese (come a Skopie, dove \u00e8 consentito ai cittadini di uccider e i cani), o quella di chi \u00e8 costretto a subire derive autoritarie che legittimano soprusi e iniquit\u00e0. E \u201cvergogna\u201d \u00e8 anche la parola (seguita dall\u2019aggettivo \u201cnazionale\u201d) che cinquanta anni fa Palmiro Togliatti scelse per denunciare, all\u2019Italia tutta, le condizioni disumane in cui vivevano gli abitanti di Matera dentro le anguste grotte dei Sassi.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abHumana Vergogna\u00bb, attraverso un linguaggio ironico che unisce teatro e danza, gioca sull\u2019elemento pop e sulla relazione diretta con lo spettatore. Il tema della vergogna \u00e8 scansionato attraverso una costruzione drammaturgica nella quale il corpo diventa narrazione e conduce lo spettatore in una dimensione ludica.<\/p>\n<p>&nbsp;<\/p>\n<p>Un supporto significativo al tour \u00e8 messo a disposizione dalla Regione Puglia &#8211; Assessorato all\u2019Industria Culturale e Turistica &#8211; e dal Teatro Pubblico Pugliese che, a valere sul Fondo di Sviluppo e Coesione Patto per la Puglia 2014-2020, hanno stipulato con #reteteatro41 e Fondazione Matera-Basilicata 2019 un protocollo d\u2019intesa finalizzato a sostenere la programmazione delle produzioni e coproduzioni artistiche pugliesi (l\u2019Accademia Mediterranea dell\u2019Attore di Lecce \u00e8 partner del progetto \u00abLa poetica della vergogna\u00bb) in contesti nazionali ed internazionali, al fine di consolidare la presenza delle stesse all\u2019interno dei pi\u00f9 importanti festival e vetrine di richiamo nazionale e internazionale.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abHumana Vergogna\u00bb \u00e8 il risultato performativo del progetto \u00abLa poetica della vergogna\u00bb, coprodotto da #reteteatro41 e Fondazione Matera-Basilicata 2019 in partenariato con Compagnia Teatrale Petra, Accademia Mediterranea dell\u2019Attore di Lecce, Osservatorio Balcani-Caucaso, Artopia di Skopje, Ballo di Podgorica, Digital Wolf, in collaborazione con Zebra Cultural Zoo. Info: 338 3746581<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riparte da Brindisi, gioved\u00ec 5 settembre alle ore 21 nel giardino dell\u2019ex Convento Santa Chiara (ingresso gratuito con prenotazioni al T. 338 3746581), il tour internazionale dello spettacolo teatrale \u00abHumana Vergogna\u00bb. Poi tappe a Podgorica (Montenegro, 9 settembre) e Skopje (Macedonia del Nord, 16 settembre). &nbsp; \u00abHumana Vergogna\u00bb, la performance coprodotta da Fondazione Matera-Basilicata 2019 e #reteteatro41 (Compagnia teatrale Petra, Gommalacca Teatro, L\u2019Albero e IAC), diretta da Silvia Gribaudi e Matteo Maffesanti, nell\u2019ambito del programma culturale di Matera 2019 Capitale Europea della Cultura, riprende la sua circuitazione internazionale. &nbsp; \u00abHumana Vergogna\u00bb sar\u00e0 il prossimo gioved\u00ec 5 settembre &#8211; ore 21 &#8211; a Brindisi, in collaborazione con la Fondazione Teatro Verdi, nel giardino dell\u2019ex Convento Santa Chiara (ingresso gratuito con prenotazione obbligatoria T. 338 3746581) per poi partecipare a due tra i pi\u00f9 importanti festival dei Balcani: il 9 settembre per la cerimonia di apertura del Fiat Festival &#8211; Festival Internacionalnog Alternativnog Teatra di Podgorica) e il 16 settembre al Mot Festival di Skopje. Il tour \u00e8 realizzato grazie al sostegno&#8230;<\/p>\n","protected":false},"author":2,"featured_media":160073,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-160069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/160069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=160069"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/160069\/revisions"}],"predecessor-version":[{"id":160080,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/160069\/revisions\/160080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/160073"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=160069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=160069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=160069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}