{"id":160193,"date":"2019-08-31T12:07:00","date_gmt":"2019-08-31T10:07:00","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=160193"},"modified":"2019-08-31T14:10:12","modified_gmt":"2019-08-31T12:10:12","slug":"antonucci-a-gennaio-a-brindisi-non-ci-sara-piu-modo-di-ricorrere-al-parto-indolore","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/antonucci-a-gennaio-a-brindisi-non-ci-sara-piu-modo-di-ricorrere-al-parto-indolore\/","title":{"rendered":"Antonucci: &#8220;a Gennaio, a Brindisi, non ci sar\u00e0 pi\u00f9 modo di ricorrere al parto indolore&#8221;"},"content":{"rendered":"<p>&#8220;Da Gennaio, a Brindisi, non ci sar\u00e0 pi\u00f9 modo di ricorrere al parto indolore, l&#8217;ennesimo diritto negato sulla pelle delle donne&#8221;, \u00e8 quanto denuncia la dott. Livia Antonucci, esponente di Forza Italia, rispetto alla grave inadempienza del servizio sanitario regionale sull&#8217;implementazione della partoanelgesia.<br \/>\n&#8220;Fino ad ora &#8211; spiega Antonucci &#8211; una minima possibilit\u00e0 di ricorrere al trattamento farmacologico del dolore, durante il travaglio, era stata garantita dalle prestazioni della clinica Salus che, per\u00f2, da gennaio, ha annunciato la chiusura del reparto di ostetricia, per legittime ragioni aziendali. Ci\u00f2 significa che il territorio della provincia di Brindisi rester\u00e0 del tutto scoperto da tale servizio. La partoanelgesia &#8211; evidenzia Antonucci &#8211; \u00e8 una prestazione inserita nei livelli essenziali di assistenza (LEA) gi\u00e0 con il DPCM del 23 aprile 2008 e confermata dall&#8217;aggiornamento dei Lea con il DPCM del 18 aprile 2017. Un diritto riconosciuto solo sulla carta per il servizio sanitario della Regione Puglia che, nel 2017, con la delibera di Giunta n\u00b0796, ha approvato il modello organizzativo di implementazione della partoanlgesia nei punti nascita con pi\u00f9 di mille parti all&#8217;anno, rimasto, ad oggi, lettera morta&#8221;.<br \/>\n&#8220;La diffusione delle tecniche antalgiche- incalza &#8211; oltre a tutelare il benessere psico fisico delle donne, comporta, come ampiamente evidenziato dal piano operativo 2016-2018, una sostanziale riduzione del ricorso al parto cesareo con conseguente contenimento della spesa pubblica sanitaria, ma, evidentemente, questo tipo di razionalizzazione che fa bene anche all&#8217;utenza, non interessa al presidente Emiliano&#8221;.<br \/>\n&#8220;Sta di fatto che, da gennaio 2020, le donne di brindisi non potranno pi\u00f9 scegliere come partorire perch\u00e8 non vi sar\u00e0 nessuna struttura, n\u00e9 privata, e men che meno pubblica , a garantire il diritto al parto indolore. A questa grave inefficienza, si aggiunge un&#8217;ulteriore preoccupante criticit\u00e0 che \u00e8 quella della congestione del Reparto di ostetricia dell&#8217;ospedale Perrino di Brindisi: gli ultimi dati disponibili, infatti, pongono il reparto del nosocomio brindisino tra i punti nascita con pi\u00f9 di mille parti all&#8217;anno (1354) e quello della Clinica Salus catalogato nella classe 500-999, con 787 parti. Ci\u00f2 evidenzia che la struttura privata ha &#8216;assorbito&#8217;, finora, circa la met\u00e0 delle nascite avvenute nell&#8217;ospedale pubblico&#8221;.<br \/>\n&#8220;Cosa ha intenzione di fare il Governatore Emiliano?&#8221; si chiede Antonucci , &#8220;Mentre \u00e8 impegnato nella sua campagna elettorale nel tentativo disperato di acquisire un consenso perso con cinque anni di cattiva amministrazione &#8211; conclude- i cittadini subiscono, con conseguenze concrete nelle proprie vite, i ritardi e le inadempienze di questa Giunta. Di certo, le donne in gravidanza della provincia di brindisi non possono aspettare le elezioni della prossima primavera, hanno bisogno di servizi dignitosi e degni di un paese civile, subito. Noi di Forza Italia interesseremo i nostri consiglieri regionali affinch\u00e9 l&#8217;assessore competente riferisca, con urgenza, in aula, sul futuro della partoanelgesia nella nostra provincia e il potenziamento dei reparti di maternit\u00e0 dei nostri ospedali&#8221;.<\/p>\n<p>Livia Antonucci (Forza Italia) <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Da Gennaio, a Brindisi, non ci sar\u00e0 pi\u00f9 modo di ricorrere al parto indolore, l&#8217;ennesimo diritto negato sulla pelle delle donne&#8221;, \u00e8 quanto denuncia la dott. Livia Antonucci, esponente di Forza Italia, rispetto alla grave inadempienza del servizio sanitario regionale sull&#8217;implementazione della partoanelgesia. &#8220;Fino ad ora &#8211; spiega Antonucci &#8211; una minima possibilit\u00e0 di ricorrere al trattamento farmacologico del dolore, durante il travaglio, era stata garantita dalle prestazioni della clinica Salus che, per\u00f2, da gennaio, ha annunciato la chiusura del reparto di ostetricia, per legittime ragioni aziendali. Ci\u00f2 significa che il territorio della provincia di Brindisi rester\u00e0 del tutto scoperto da tale servizio. La partoanelgesia &#8211; evidenzia Antonucci &#8211; \u00e8 una prestazione inserita nei livelli essenziali di assistenza (LEA) gi\u00e0 con il DPCM del 23 aprile 2008 e confermata dall&#8217;aggiornamento dei Lea con il DPCM del 18 aprile 2017. Un diritto riconosciuto solo sulla carta per il servizio sanitario della Regione Puglia che, nel 2017, con la delibera di Giunta n\u00b0796, ha approvato il modello organizzativo di implementazione della partoanlgesia&#8230;<\/p>\n","protected":false},"author":2,"featured_media":14682,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-160193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/160193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=160193"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/160193\/revisions"}],"predecessor-version":[{"id":160194,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/160193\/revisions\/160194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/14682"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=160193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=160193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=160193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}