{"id":160541,"date":"2019-09-09T12:05:25","date_gmt":"2019-09-09T10:05:25","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=160541"},"modified":"2019-09-09T12:05:25","modified_gmt":"2019-09-09T10:05:25","slug":"albergatore-picchiato-per-apprezzamenti-ad-una-ragazza-denunciate-tre-persone","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/albergatore-picchiato-per-apprezzamenti-ad-una-ragazza-denunciate-tre-persone\/","title":{"rendered":"Albergatore picchiato per apprezzamenti ad una ragazza: denunciate tre persone"},"content":{"rendered":"<p>Venerd\u00ec 6 settembre, alle ore 1:30, il Pronto Soccorso dell\u2019Ospedale di Ceglie Messapica ha segnalato il ricovero di un ferito 57enne del luogo, titolare di un\u2019attivit\u00e0 ricettiva, a seguito di aggressione. La vittima ha riferito che alle ore 01:00 circa, tre individui di corporatura robusta e con accento del luogo lo avevano aggredito nel piazzale antistante la struttura ricettiva, pestandolo brutalmente senza rivelarne le motivazioni.<\/p>\n<p>Dopo le prime cure, la parte offesa \u00e8 stata trasferita presso l&#8217;ospedale di Francavilla Fontana dove \u00e8 gli \u00e8 stata diagnosticata la frattura dell&#8217;orbita oculare e del setto nasale. A seguito degli accertamenti effettuati, i Carabinieri della locale Stazione hanno deferito in stato di libert\u00e0 tre persone, un 54enne, un 30enne e un 24enne del luogo, tutti per concorso in lesioni personali gravi. Nello specifico, \u00e8 stato accertato che i tre indagati si sono resi responsabili dell\u2019aggressione in danno del 57enne. Il movente della vicenda \u00e8 da ricercare in alcuni apprezzamenti e lusinghe rivolte dal ristoratore alla fidanzata di uno dei tre e precisamente il 30enne, fatto avvenuto all\u2019interno di un locale pubblico di Ceglie.<\/p>\n<p>L\u2019evento fa scattare una spedizione punitiva da parte dei tre indagati, viene rintracciato il 57enne che viene aggredito violentemente, attualmente \u00e8 ricoverato, in osservazione presso ospedale civile di Francavilla Fontana con la diagnosi \u201ctrauma cranio facciale con frattura composta tetto orbitale sinistro \u2013 frattura composta ossa del naso \u2013 contusioni toraciche multiple\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Nella circostanza, a seguito di conseguente perquisizione domiciliare, il 54enne cegliese \u00e8 stato, altres\u00ec, denunciato per la violazione dei previsti obblighi di custodia in riferimento alla detenzione di un fucile calibro 20 marca Beretta, nonch\u00e9 per l\u2019illecita detenzione di 18 munizioni calibro 7.65; l\u2019arma e le munizioni sono state sottoposte a sequestro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 6 settembre, alle ore 1:30, il Pronto Soccorso dell\u2019Ospedale di Ceglie Messapica ha segnalato il ricovero di un ferito 57enne del luogo, titolare di un\u2019attivit\u00e0 ricettiva, a seguito di aggressione. La vittima ha riferito che alle ore 01:00 circa, tre individui di corporatura robusta e con accento del luogo lo avevano aggredito nel piazzale antistante la struttura ricettiva, pestandolo brutalmente senza rivelarne le motivazioni. Dopo le prime cure, la parte offesa \u00e8 stata trasferita presso l&#8217;ospedale di Francavilla Fontana dove \u00e8 gli \u00e8 stata diagnosticata la frattura dell&#8217;orbita oculare e del setto nasale. A seguito degli accertamenti effettuati, i Carabinieri della locale Stazione hanno deferito in stato di libert\u00e0 tre persone, un 54enne, un 30enne e un 24enne del luogo, tutti per concorso in lesioni personali gravi. Nello specifico, \u00e8 stato accertato che i tre indagati si sono resi responsabili dell\u2019aggressione in danno del 57enne. Il movente della vicenda \u00e8 da ricercare in alcuni apprezzamenti e lusinghe rivolte dal ristoratore alla fidanzata di uno dei tre e precisamente il&#8230;<\/p>\n","protected":false},"author":2,"featured_media":25428,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-160541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/160541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=160541"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/160541\/revisions"}],"predecessor-version":[{"id":160543,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/160541\/revisions\/160543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/25428"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=160541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=160541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=160541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}