{"id":160602,"date":"2019-09-10T19:32:34","date_gmt":"2019-09-10T17:32:34","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=160602"},"modified":"2019-09-10T21:24:04","modified_gmt":"2019-09-10T19:24:04","slug":"giovedi-12-pamela-spinelli-presenta-tranquilla-presso-la-caffetteria-letteraria-nervegna","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/giovedi-12-pamela-spinelli-presenta-tranquilla-presso-la-caffetteria-letteraria-nervegna\/","title":{"rendered":"Gioved\u00ec 12 Pamela Spinelli presenta &#8220;Tranquilla&#8221; presso la Caffetteria letteraria Nervegna"},"content":{"rendered":"<p>Prosegue con successo il tour promozionale di \u201cTranquilla\u201d  il romanzo d\u2019esordio della giornalista Pamela Spinelli, edito dalla casa editrice Il Raggio Verde, che il 12 settembre 2019 approda alla Caffetteria Nervegna, in via Duomo, 20 Brindisi. Dialogher\u00e0 con l\u2019autrice la giornalista Federica Marangio.<\/p>\n<p>Una narrazione avvincente, che riesce a tenere il lettore con il fiato sospeso fino alla conclusione per nulla scontata del romanzo che vede protagonisti Angela, un\u2019affascinante donna di 44 anni, esperta in marketing d\u2019impresa, con una serie di storie sbagliate alle spalle,  compreso un matrimonio \u201ctenuto in piedi come un\u2019equilibrista\u201d. Una donna solare e sorridente ma sostanzialmente insicura che incrocia sul suo cammino, una sera durante una cena, il carismatico avvocato Ernesto, sposato e padre di Ilaria che lo ha reso nonno. La differenza tra i due \u00e8 notevole e non si tratta solo dei 21 anni che li separano anagraficamente. Eppure l\u2019attrazione tra i due \u00e8 tangibile quanto inevitabile. \u201cTranquilla\u201d, come la parola che lui le ripete spesso, \u00e8 una storia d\u2019amore ma non solo. \u00c8 un continuo affacciarsi alla vita, un attraversamento nei sentimenti pi\u00f9 disparati e a volte contrastanti: l\u2019amore, in primis, sentimento totale che come un filo rosso tesse la trama di un incontro casuale che sconvolge l\u2019incedere lento dei giorni. Ernesto e Angela. Un uomo e una donna. Il tempo e lo spazio. E nel bel mezzo le affinit\u00e0 elettive, quella magia sottesa che \u00e8 fatta di sguardi, parole e silenzi. Di una complicit\u00e0 naturale quanto inspiegabile e inarrestabile. Un vortice di emozioni. E poi la vita che \u00e8 sempre un punto interrogativo che pu\u00f2 sconfinare nel sogno o nell\u2019incubo perch\u00e9 la banalit\u00e0 del male \u00e8 dietro l\u2019angolo e il pi\u00f9 delle volte potrebbe essere evitabile.<\/p>\n<p>Pamela Spinelli \u00e8 nata nel 1972 e vive a Brindisi. Dopo la maturit\u00e0 scientifica, ha conseguito la Laurea in Scienze Motorie presso l&#8217;Isef di L&#8217;Aquila. Giornalista professionista, ha iniziato a lavorare nel 1995 scrivendo sulle pagine dei quotidiani &#8220;Roma&#8221; e &#8220;Corriere del Giorno&#8221;. Ha curato gli Uffici Stampa di diversi Enti pubblici e delle massime societ\u00e0 sportive di basket e di calcio di Brindisi, oltre a curare la comunicazione di due parlamentari pugliesi.  Nel 2001 \u00e8 stata corrispondente per Brindisi per l\u2019emittente televisiva Antenna Sud, mentre nel 2007 ha iniziato a lavorare per Telenorba, azienda per la quale continua a collaborare tutt\u2019oggi come inviata della trasmissione di approfondimento \u201cIl Graffio\u201d. Ha scritto anche per il \u201cNuovo Quotidiano di Puglia\u201d e dal 2016 ha fondato il giornale on line www.newspam.it, del quale \u00e8 editore e direttore responsabile.  Sposata, ha una figlia, Giulia, di 15 anni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prosegue con successo il tour promozionale di \u201cTranquilla\u201d il romanzo d\u2019esordio della giornalista Pamela Spinelli, edito dalla casa editrice Il Raggio Verde, che il 12 settembre 2019 approda alla Caffetteria Nervegna, in via Duomo, 20 Brindisi. Dialogher\u00e0 con l\u2019autrice la giornalista Federica Marangio. Una narrazione avvincente, che riesce a tenere il lettore con il fiato sospeso fino alla conclusione per nulla scontata del romanzo che vede protagonisti Angela, un\u2019affascinante donna di 44 anni, esperta in marketing d\u2019impresa, con una serie di storie sbagliate alle spalle, compreso un matrimonio \u201ctenuto in piedi come un\u2019equilibrista\u201d. Una donna solare e sorridente ma sostanzialmente insicura che incrocia sul suo cammino, una sera durante una cena, il carismatico avvocato Ernesto, sposato e padre di Ilaria che lo ha reso nonno. La differenza tra i due \u00e8 notevole e non si tratta solo dei 21 anni che li separano anagraficamente. Eppure l\u2019attrazione tra i due \u00e8 tangibile quanto inevitabile. \u201cTranquilla\u201d, come la parola che lui le ripete spesso, \u00e8 una storia d\u2019amore ma non solo. \u00c8&#8230;<\/p>\n","protected":false},"author":2,"featured_media":146574,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-160602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/160602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=160602"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/160602\/revisions"}],"predecessor-version":[{"id":160604,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/160602\/revisions\/160604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/146574"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=160602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=160602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=160602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}