{"id":160868,"date":"2019-09-17T07:14:30","date_gmt":"2019-09-17T05:14:30","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=160868"},"modified":"2019-09-17T07:14:30","modified_gmt":"2019-09-17T05:14:30","slug":"badante-georgiana-picchia-e-maltratta-anziana-invalida","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/badante-georgiana-picchia-e-maltratta-anziana-invalida\/","title":{"rendered":"Badante georgiana picchia e maltratta anziana invalida"},"content":{"rendered":"<p>I Carabinieri del Nucleo Operativo e Radiomobile della Compagnia di Francavilla Fontana, a conclusione degli accertamenti, hanno tratto in arresto in flagranza di reato, per maltrattamenti in famiglia, una 43enne badante di nazionalit\u00e0 georgiana, irregolare sul territorio nazionale.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019attivit\u00e0 d\u2019indagine supportata anche dall\u2019analisi delle immagini del sistema di videosorveglianza, autonomamente installato dai congiunti all\u2019interno della camera da letto della vittima, ha fatto emergere ripetute violenze fisiche e vessazioni, in danno di una 84enne del luogo, vedova e invalida.<\/p>\n<p>&nbsp;<\/p>\n<p>La telecamera installata dai parenti ha documentato i gravi fatti verificatisi nei riguardi dell\u2019inerme assistita, eventi riferiti allo scorso mese di agosto e settembre ma non si esclude che analoghi fatti si siano verificati anche in precedenza.<\/p>\n<p>&nbsp;<\/p>\n<p>Nella serata di domenica 15 settembre, la vittima ha subito ulteriori angherie, alle quali hanno assistito i congiunti entrati di sorpresa nell\u2019appartamento, da una porta collocata sul retro dell\u2019abitazione, nella circostanza hanno constatato e interrotto le azioni violente della badante.<\/p>\n<p>La vittima \u00e8 stata trasportata da un\u2019autoambulanza del servizio 118 presso Pronto Soccorso dell\u2019Ospedale di Francavilla Fontana, visitata dai sanitari \u00e8 stata riscontrata \u201cvigile ma non collaborante, presentava la cute pallida e secca, disidratata, con una piccola tumefazione nella regione frontale sinistra, ecchimosi sul braccio sinistro e altre due ecchimosi evidenziate su anca e coscia sinistra, provocate all\u2019incirca da qualche giorno.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019anziana da due anni \u00e8 allettata e necessita di continua assistenza, poich\u00e9 ha dei momenti di smarrimento.<\/p>\n<p>Dal 22 giugno scorso, nonostante l\u2019assidua presenza dei congiunti che le fanno visita pi\u00f9 volte al giorno e dopo aver avuto altre due badanti, \u00e8 stata accudita dalla georgiana assunta tramite un\u2019agenzia che invece di assisterla l\u2019ha sottoposta a maltrattamenti.<\/p>\n<p>&nbsp;<\/p>\n<p>Da un primo esame delle immagini, sono state focalizzate le manifestazioni di maltrattamento nei riguardi dell\u2019anziana che \u00e8 apparsa in alcuni frangenti in difficolt\u00e0 e sofferente, in particolare quando la badante le somministrava cibo e farmaci. La sua assistente, che avrebbe dovuto accudirla, non teneva assolutamente conto dei tempi necessari per far ingerire quanto somministrato all\u2019anziana che veniva ingozzata, nonostante manifestasse il disagio con la mimica facciale.<\/p>\n<p>&nbsp;<\/p>\n<p>Al termine degli accertamenti, l\u2019arrestata espletate le formalit\u00e0 di rito, \u00e8 stata tradotta nella Casa Circondariale Lecce, come disposto dall\u2019Autorit\u00e0 Giudiziaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Carabinieri del Nucleo Operativo e Radiomobile della Compagnia di Francavilla Fontana, a conclusione degli accertamenti, hanno tratto in arresto in flagranza di reato, per maltrattamenti in famiglia, una 43enne badante di nazionalit\u00e0 georgiana, irregolare sul territorio nazionale. &nbsp; L\u2019attivit\u00e0 d\u2019indagine supportata anche dall\u2019analisi delle immagini del sistema di videosorveglianza, autonomamente installato dai congiunti all\u2019interno della camera da letto della vittima, ha fatto emergere ripetute violenze fisiche e vessazioni, in danno di una 84enne del luogo, vedova e invalida. &nbsp; La telecamera installata dai parenti ha documentato i gravi fatti verificatisi nei riguardi dell\u2019inerme assistita, eventi riferiti allo scorso mese di agosto e settembre ma non si esclude che analoghi fatti si siano verificati anche in precedenza. &nbsp; Nella serata di domenica 15 settembre, la vittima ha subito ulteriori angherie, alle quali hanno assistito i congiunti entrati di sorpresa nell\u2019appartamento, da una porta collocata sul retro dell\u2019abitazione, nella circostanza hanno constatato e interrotto le azioni violente della badante. La vittima \u00e8 stata trasportata da un\u2019autoambulanza del servizio 118 presso Pronto&#8230;<\/p>\n","protected":false},"author":2,"featured_media":52015,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-160868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/160868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=160868"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/160868\/revisions"}],"predecessor-version":[{"id":160869,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/160868\/revisions\/160869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/52015"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=160868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=160868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=160868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}