{"id":16648,"date":"2014-06-30T17:47:22","date_gmt":"2014-06-30T15:47:22","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=16648"},"modified":"2014-06-30T17:48:56","modified_gmt":"2014-06-30T15:48:56","slug":"tentano-di-bruciare-lauto-del-vicesindaco-di-san-donaci","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/tentano-di-bruciare-lauto-del-vicesindaco-di-san-donaci\/","title":{"rendered":"Tentano di bruciare l&#8217;auto del vicesindaco di San Donaci"},"content":{"rendered":"<p>Ieri sera alcuni ignoti hanno cercato di incendiare l&#8217;auto di Mariangela Presta, 39 anni, vicesindaco del Comune di San Donaci (Brindisi) con delega alle Attivit\u00e0 produttive ed alla Programmazione economica.<\/p>\n<p>L&#8217;auto era posteggiata nei pressi dell&#8217;abitazione della donna. Secondo le prime indiscrezioni \u00e8 stata proprio lei ad accorgersi che la sua auto era stata presa di mira da alcuni sconosciuti. La Presta, dopo aver fermato il tentativo di incendio, ha chiamato i Carabinieri che si sono immediatamente recati sul posto  ed hanno rinvenuto tracce di materiale infiammabile.<\/p>\n<p>\u201cSolidariet\u00e0 e vicinanza\u201d al vicesindaco di San Donaci, Mariangela Presta, \u00e8 stata espressa dal capogruppo del Pd alla Regione Puglia, Pino Romano: \u201cA nome di tutto i consiglieri democratici \u2013 spiega Romano \u2013 voglio assicurare a Presta che le siamo vicini dopo l\u2019intimidazione ricevuta da parte di alcuni balordi che hanno provato a incendiare la sua auto, la scorsa notte\u201d. Per Romano, \u201cnon va pi\u00f9 sottovalutato il fenomeno delle intimidazioni agli amministratori pubblici che, in Puglia, si registrano in maniera superiore al resto d\u2019Italia, cos\u00ec come ha riconosciuto pochi giorni fa la Commissione parlamentare d\u2019inchiesta giunta a Bari per le audizioni\u201d. \u201cLa politica &#8211; sottolinea Romano \u2013 deve ribellarsi con una sola voce a qualsiasi forma violenta e terroristica di contrasto alle attivit\u00e0 di chi lavora al servizio e per il bene dei cittadini\u201d. \u201cNessuno di noi ha paura \u2013 conclude Romano \u2013 e a questi vigliacchi che non hanno altro modo di agire, se non con la violenza, diciamo che non riusciranno mai a fermare il lavoro delle istituzioni e il volere dei cittadini onesti\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ieri sera alcuni ignoti hanno cercato di incendiare l&#8217;auto di Mariangela Presta, 39 anni, vicesindaco del Comune di San Donaci (Brindisi) con delega alle Attivit\u00e0 produttive ed alla Programmazione economica. L&#8217;auto era posteggiata nei pressi dell&#8217;abitazione della donna. Secondo le prime indiscrezioni \u00e8 stata proprio lei ad accorgersi che la sua auto era stata presa di mira da alcuni sconosciuti. La Presta, dopo aver fermato il tentativo di incendio, ha chiamato i Carabinieri che si sono immediatamente recati sul posto ed hanno rinvenuto tracce di materiale infiammabile. \u201cSolidariet\u00e0 e vicinanza\u201d al vicesindaco di San Donaci, Mariangela Presta, \u00e8 stata espressa dal capogruppo del Pd alla Regione Puglia, Pino Romano: \u201cA nome di tutto i consiglieri democratici \u2013 spiega Romano \u2013 voglio assicurare a Presta che le siamo vicini dopo l\u2019intimidazione ricevuta da parte di alcuni balordi che hanno provato a incendiare la sua auto, la scorsa notte\u201d. Per Romano, \u201cnon va pi\u00f9 sottovalutato il fenomeno delle intimidazioni agli amministratori pubblici che, in Puglia, si registrano in maniera superiore al resto&#8230;<\/p>\n","protected":false},"author":2,"featured_media":16649,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[2210,684],"class_list":["post-16648","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-presta","tag-san-donaci"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/16648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=16648"}],"version-history":[{"count":2,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/16648\/revisions"}],"predecessor-version":[{"id":16651,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/16648\/revisions\/16651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/16649"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=16648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=16648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=16648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}