{"id":16838,"date":"2014-07-01T11:50:26","date_gmt":"2014-07-01T09:50:26","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=16838"},"modified":"2014-07-01T12:30:34","modified_gmt":"2014-07-01T10:30:34","slug":"san-donaci-dopo-lattentato-al-vicesindaco-i-carabinieri-stingono-le-maglie-dei-controlli","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/san-donaci-dopo-lattentato-al-vicesindaco-i-carabinieri-stingono-le-maglie-dei-controlli\/","title":{"rendered":"San Donaci: dopo l&#8217;attentato al vicesindaco i Carabinieri stingono le maglie dei controlli"},"content":{"rendered":"<p>Dopo l&#8217;attentato incendiario all&#8217;automobile del vicensindaco Presta, che per fortuna non \u00e8 andato a buon fine, i  carabinieri della Stazione di San Donaci hanno stretto le maglie dei controlli sul territorio.<\/p>\n<p>Nella giornata di ieri, i militari dell&#8217;Arma, assieme ai colleghi del personale del Nucleo Cinofili di Modugno (BA) e dei reparti dipendenti dalla Compagnia di Francavilla Fontana, hanno ottenuto i seguenti risultati:<\/p>\n<p>Hanno tratto in arresto in flagranza di reato, per furto aggravato, i due fratelli Luigi e Antonio Corbascio, rispettivamente 38 e 41 anni, entrambi vicini alla SCU. Assieme a loro sono scattate le manette per la madre, Rosa Barba 63 anni.<br \/>\nNel corso di una perquisizione domiciliare, i militari hanno accertato che i due fratelli alimentavano l&#8217;impianto elettrico della propria abitazione mediante un cavo clandestino. In tal modo hanno cagionato all&#8217;ente elettrico un danno stimato in 9.000,00 euro circa. Tra l&#8217;altro Luigi Corbascio \u00e8 stato trovato in possesso di un grammo di marijuana e quindi segnalato all&#8217;Autorit\u00e0 Amministrativa mentre Antonio Corbascio, sorvegliato speciale con obbligo di dimora, \u00e8 stato deferito anche per inosservanza degli obblighi imposti con la misura in espiazione.<\/p>\n<p>Inoltre i Carabinieri hanno rinvenuto in un canale di scolo, in quella via Walter Tobagi, col fiuto dell&#8217;unit\u00e0 cinofila, una busta contenente 150 grammi circa di esplosivo del tipo \u201ccordite\u201d, sottoposto a sequestro.<\/p>\n<p>Infine, i militari dell&#8217;Arma hanno deferito in stato di libert\u00e0 4 persone di San Donaci:<br \/>\n.\u00a0\u00a0\u00a0 G.G., 44 anni, gestore di un impianto di distribuzione di carburante per autotrazione, per aver omesso di effettuare la revisione e il controllo degli estintori ivi collocati, non predisponendo, inoltre, la prevista segnaletica;<br \/>\n.\u00a0\u00a0\u00a0 C.A., 37 anni, commerciante, per omessa collocazione della segnaletica prevista per l&#8217;impiego degli estintori;<br \/>\n.\u00a0\u00a0\u00a0 O.L., 43 anni, gestore di un impianto di distribuzione di carburante per autotrazione, per omessa collocazione della segnaletica prevista per l&#8217;impiego degli estintori e per non aver smaltito gli oli esausti secondo la normativa vigente;<br \/>\n.\u00a0\u00a0\u00a0 V.G., 52 anni, per omessa denuncia di un fucile da caccia, sottoposto a sequestro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo l&#8217;attentato incendiario all&#8217;automobile del vicensindaco Presta, che per fortuna non \u00e8 andato a buon fine, i carabinieri della Stazione di San Donaci hanno stretto le maglie dei controlli sul territorio. Nella giornata di ieri, i militari dell&#8217;Arma, assieme ai colleghi del personale del Nucleo Cinofili di Modugno (BA) e dei reparti dipendenti dalla Compagnia di Francavilla Fontana, hanno ottenuto i seguenti risultati: Hanno tratto in arresto in flagranza di reato, per furto aggravato, i due fratelli Luigi e Antonio Corbascio, rispettivamente 38 e 41 anni, entrambi vicini alla SCU. Assieme a loro sono scattate le manette per la madre, Rosa Barba 63 anni. Nel corso di una perquisizione domiciliare, i militari hanno accertato che i due fratelli alimentavano l&#8217;impianto elettrico della propria abitazione mediante un cavo clandestino. In tal modo hanno cagionato all&#8217;ente elettrico un danno stimato in 9.000,00 euro circa. Tra l&#8217;altro Luigi Corbascio \u00e8 stato trovato in possesso di un grammo di marijuana e quindi segnalato all&#8217;Autorit\u00e0 Amministrativa mentre Antonio Corbascio, sorvegliato speciale con obbligo di dimora,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":11273,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[684],"class_list":["post-16838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-san-donaci"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/16838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=16838"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/16838\/revisions"}],"predecessor-version":[{"id":16839,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/16838\/revisions\/16839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/11273"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=16838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=16838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=16838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}