{"id":172759,"date":"2020-05-24T21:50:21","date_gmt":"2020-05-24T19:50:21","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=172759"},"modified":"2020-05-24T21:50:21","modified_gmt":"2020-05-24T19:50:21","slug":"chi-vuole-frequentare-torre-guaceto-deve-rispettarla","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/chi-vuole-frequentare-torre-guaceto-deve-rispettarla\/","title":{"rendered":"Chi vuole frequentare Torre Guaceto deve rispettarla!"},"content":{"rendered":"<p>La stagione balneare 2020 \u00e8 iniziata in anticipo rispetto a quanto imposto dall\u2019ordinanza balneare della Regione Puglia.<br \/>\nNella giornata odierna, la gente ha iniziato a frequentare le spiagge della Riserva Naturale dello Stato e Area Marina Protetta di Torre Guaceto. Nessun assembramento, ma in alcuni casi tanto poco rispetto per l\u2019area protetta.<br \/>\nIl personale impegnato nel costante pattugliamento della Riserva \u00e8 stato costretto a richiedere pi\u00f9 volte agli utenti di attenersi ai comportamenti consentiti all\u2019interno dell\u2019area protetta.<br \/>\nC\u2019era chi, in barba al Regolamento per la fruizione dell\u2019AMP, alla costante informazione della platea di riferimento operata dal Consorzio e ad alla cartellonista sparsa per tutto il perimetro protetto, faceva il bagno nella zona A, chi passeggiava con il proprio cane, chi, addirittura, \u00e8 entrato in barca.<br \/>\nGli operatori del Consorzio di Gestione impegnati nel monitoraggio non hanno potuto fare altro che richiedere l\u2019intervento delle Autorit\u00e0, perch\u00e9, va sottolineato, la prevenzione e repressione delle violazioni al Regolamento dell\u2019area protetta e dei reati spetta alle forze dell\u2019Ordine, gli operatori dell\u2019ente gestore non svolgono un ruolo di polizia giudiziaria.<br \/>\nE la collaborazione con le Autorit\u00e0 preposte ha ancora una volta dato buon esito.<br \/>\nAllertati dal personale di monitoraggio, gli uomini della Guardia costiera di Brindisi sono intervenuti immediatamente.<br \/>\nLa motovedetta partita dal capoluogo ha rintracciato il natante la cui presenza era stata segnalata dal personale all\u2019interno della zona B dell\u2019AMP e, oltre ad imporre l\u2019immediato allontanamento dalla Riserva, ha elevato una sanzione a carico del conduttore.<br \/>\n\u201cRingraziamo vivamente gli uomini della Guardia costiera &#8211; ha commentato il presidente del Consorzio di Gestione di Torre Guaceto, Corrado Tarantino -, per aver eseguito l\u2019intervento risolutivo e per averlo fatto subito\u201d.<br \/>\nPer quanto concerne la presenza dei cani nell\u2019area protetta e dei bagnanti in zona A, la violazione delle norme per la tutela di Torre Guaceto non \u00e8 assolutamente tollerabile. A maggior ragione perch\u00e9, a pochi passi da chi oggi violava il Regolamento in spiaggia, il personale del Consorzio ha rinvenuto la presenza di un nido di fratino.<br \/>\nUn nido tanto prezioso quanto delicato, la ragione per la quale i cani non possono e non devono accedere all\u2019area protetta. Si ribadisce ancora una volta che il fratino \u00e8 una specie a rischio di estinzione che nidifica sulle spiagge di Torre Guaceto. E che chi viola il Regolamento della Riserva accedendo con il proprio cane, rischia una sanzione, alla quale si aggiunge un procedimento penale in caso di predazione.<br \/>\nVa sottolineato, inoltre, che \u00e8 assolutamente vietato l\u2019accesso e la sosta di mezzi a motore nell\u2019area protetta. Chi \u00e8 in possesso di pass per diversamente abili, pu\u00f2 avvicinarsi alla costa sul versante di Punta Penna Grossa, ma poi, una volta consentito alla persona con ridotta mobilit\u00e0 di raggiungere la spiaggia, i mezzi devono allontanarsi immediatamente.<br \/>\n\u201cCapiamo la voglia ed il bisogno di normalit\u00e0 di tutti &#8211; ha dichiarato Tarantino -, ma il desiderio di godere della pace e della bellezza di Torre Guaceto non deve accostarsi al mancato rispetto delle regole senza le quali la Riserva non sarebbe nulla di pi\u00f9 rispetto ad un luogo pi\u00f9 o meno naturale come tutti gli altri. Domani scriveremo alle Autorit\u00e0 competenti per chiedere un rafforzamento della sorveglianza esercitata sull\u2019area protetta ed ai Comuni affinch\u00e9 riparta la pulizia delle spiagge. Dobbiamo essere tutti coesi nel lavoro quotidiano per la difesa di Torre Guaceto e, per questo motivo, preghiamo i fruitori della Riserva di richiedere l\u2019intervento delle forze dell\u2019Ordine ogni qualvolta assistono ad una violazione del Regolamento dell\u2019area protetta\u201d.<br \/>\nIl video https:\/\/youtu.be\/z0rnVui9z7k<\/p>\n<p>COMUNICAZIONE CONSORZIO DI GESTIONE DI TORRE GUACETO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La stagione balneare 2020 \u00e8 iniziata in anticipo rispetto a quanto imposto dall\u2019ordinanza balneare della Regione Puglia. Nella giornata odierna, la gente ha iniziato a frequentare le spiagge della Riserva Naturale dello Stato e Area Marina Protetta di Torre Guaceto. Nessun assembramento, ma in alcuni casi tanto poco rispetto per l\u2019area protetta. Il personale impegnato nel costante pattugliamento della Riserva \u00e8 stato costretto a richiedere pi\u00f9 volte agli utenti di attenersi ai comportamenti consentiti all\u2019interno dell\u2019area protetta. C\u2019era chi, in barba al Regolamento per la fruizione dell\u2019AMP, alla costante informazione della platea di riferimento operata dal Consorzio e ad alla cartellonista sparsa per tutto il perimetro protetto, faceva il bagno nella zona A, chi passeggiava con il proprio cane, chi, addirittura, \u00e8 entrato in barca. Gli operatori del Consorzio di Gestione impegnati nel monitoraggio non hanno potuto fare altro che richiedere l\u2019intervento delle Autorit\u00e0, perch\u00e9, va sottolineato, la prevenzione e repressione delle violazioni al Regolamento dell\u2019area protetta e dei reati spetta alle forze dell\u2019Ordine, gli operatori dell\u2019ente gestore non svolgono&#8230;<\/p>\n","protected":false},"author":2,"featured_media":172760,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-172759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/172759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=172759"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/172759\/revisions"}],"predecessor-version":[{"id":172761,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/172759\/revisions\/172761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/172760"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=172759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=172759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=172759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}