{"id":178054,"date":"2020-10-28T17:22:00","date_gmt":"2020-10-28T16:22:00","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=178054"},"modified":"2020-10-28T17:22:00","modified_gmt":"2020-10-28T16:22:00","slug":"tap-e-cis-rossi-e-salvemini-in-videoconferenza-con-il-sottosegretario-turco","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/tap-e-cis-rossi-e-salvemini-in-videoconferenza-con-il-sottosegretario-turco\/","title":{"rendered":"Tap e Cis: Rossi e Salvemini in videoconferenza con il Sottosegretario Turco"},"content":{"rendered":"<p>Questa mattina il Sindaco di Brindisi Riccardo Rossi ed il Sindaco di Lecce Carlo Salvemini hanno partecipato ad una riunione in videoconferenza con il Sottosegretario alla Presidenza del Consiglio di Ministri, Sen. Mario Turco, per affrontare due importanti temi aperti: gli indennizzi derivanti dal progetto Tap-Snam e il Contratto istituzionale di Sviluppo.<\/p>\n<p>&nbsp;<\/p>\n<p>Sul primo tema, il Sottosegretario Turco, responsabile di gestire il fascicolo TAP per conto della Presidenza del Consiglio, con riferimento alle compensazioni, ha evidenziato, la necessit\u00e0 di sviluppare proposte progettuali orientate a favorire investimenti forieri di sviluppo imprenditoriale, occupazionale o di benessere collettivo e condiviso. Il percorso metodologico condiviso vedr\u00e0 il Governo come interlocutore dei Comuni attraversati dall\u2019opera ai fini del ristoro.<\/p>\n<p>&nbsp;<\/p>\n<p>Sul Contratto istituzionale di Sviluppo, la Presidenza del Consiglio ha in essere approfondimenti con il Ministro per il Sud, Giuseppe Provenzano. Nell\u2019incontro avvenuto oggi si \u00e8 preso atto del lavoro svolto in questi mesi dalle citt\u00e0 di Brindisi e Lecce in merito ai progetti e agli ambiti di intervento presentati, nella prospettiva di uno sviluppo territoriale ampio e coeso. In sede governativa, sar\u00e0 presto aperto un confronto di interlocuzione con le citt\u00e0 di Brindisi e Lecce.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<br \/>\nSperiamo che Mario Turco abbia davvero convinto, cos\u00ec come pare, i sindaci di Brindisi e Lecce a sviluppare proposte progettuali di compensazione per il gasdotto Tap, orientate a favorire investimenti sul territorio. Accolgo quindi con molto favore la notizia dell\u2019esito della videoconferenza svoltasi appunto oggi tra il sottosegretario, Riccardo Rossi e Carlo Salvemini\u201d.<br \/>\nLo dichiara il Consigliere regionale Fabiano Amati.<br \/>\n\u201cMi pare che dopo diversi giorni di tensioni, tra sollecitazioni, timidezze e dibattiti, le cose si stiano mettendo per il verso giusto.<br \/>\n\u00c8 comprensibile che ognuno in queste settimane abbia coltivato il suo metodo per raggiungere il risultato, assecondando un po\u2019 il temperamento e un po\u2019 le necessit\u00e0 di posizionamento politico.<br \/>\nPer chi come me si \u00e8 invece formato alla scuola della concretezza, ci\u00f2 che conta \u00e8 il risultato, cio\u00e8 gli investimenti in favore dei territori.<br \/>\nE per questo mi sento di ringraziare per l\u2019annunciato impegno il sottosegretario Mario Turco e i sindaci Riccardo Rossi e Carlo Salvemini. Spero che in questo gruppo si aggiunga presto anche il Presidente della Provincia di Lecce Stefano Minerva, per completare il quadro della rappresentanza istituzionale delle due province interessate\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questa mattina il Sindaco di Brindisi Riccardo Rossi ed il Sindaco di Lecce Carlo Salvemini hanno partecipato ad una riunione in videoconferenza con il Sottosegretario alla Presidenza del Consiglio di Ministri, Sen. Mario Turco, per affrontare due importanti temi aperti: gli indennizzi derivanti dal progetto Tap-Snam e il Contratto istituzionale di Sviluppo. &nbsp; Sul primo tema, il Sottosegretario Turco, responsabile di gestire il fascicolo TAP per conto della Presidenza del Consiglio, con riferimento alle compensazioni, ha evidenziato, la necessit\u00e0 di sviluppare proposte progettuali orientate a favorire investimenti forieri di sviluppo imprenditoriale, occupazionale o di benessere collettivo e condiviso. Il percorso metodologico condiviso vedr\u00e0 il Governo come interlocutore dei Comuni attraversati dall\u2019opera ai fini del ristoro. &nbsp; Sul Contratto istituzionale di Sviluppo, la Presidenza del Consiglio ha in essere approfondimenti con il Ministro per il Sud, Giuseppe Provenzano. Nell\u2019incontro avvenuto oggi si \u00e8 preso atto del lavoro svolto in questi mesi dalle citt\u00e0 di Brindisi e Lecce in merito ai progetti e agli ambiti di intervento presentati, nella prospettiva di uno&#8230;<\/p>\n","protected":false},"author":2,"featured_media":283,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-178054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/178054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=178054"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/178054\/revisions"}],"predecessor-version":[{"id":178055,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/178054\/revisions\/178055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/283"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=178054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=178054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=178054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}