{"id":17894,"date":"2014-07-17T07:12:40","date_gmt":"2014-07-17T05:12:40","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=17894"},"modified":"2014-07-17T07:12:40","modified_gmt":"2014-07-17T05:12:40","slug":"miss-summer-salento-a-rosamarina-con-carmen-russo-e-enzo-paolo-turchi","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/miss-summer-salento-a-rosamarina-con-carmen-russo-e-enzo-paolo-turchi\/","title":{"rendered":"Miss Summer Salento a Rosamarina con Carmen Russo e Enzo Paolo Turchi"},"content":{"rendered":"<p><strong>Venerd\u00ec 18 luglio alle 21.30 la nomina della reginetta del Villaggio di Cala di Rosamarina a (Ostuni). <\/strong><\/p>\n<p><strong>A cala di Rosamarina con una giuria di eccezione sar\u00e0 eletta Miss Summer Salento 2014 del prestigioso villaggio Ostunese.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>La giuria presieduta dalla showgirl <strong>Camen Russo e Enzo Paolo Turchi<\/strong> avr\u00e0 l&#8217;arduo compito di eleggere ulteriori tre concorrenti da fare accedere alla finale del concorso il prossimo 23 agosto previsto nello stesso villaggio.<\/p>\n<p>Tanya Lupo di Castrano (Le), Selena Mosbah Galatina (Le) e Maria Laura Legali Scorrano (Le) intanto sono le belle elette lo scorso 13 luglio presso il prestigioso club Smaila&#8217;s di Gallipoli Le, da una giuria presieduta dalla stilista di Cavallino (Le.)<\/p>\n<p>Daniela Melcore, acquisendo il biglietto di ingresso per la competizione finale per aggiudicarsi il titolo di reginetta del tacco d&#8217;Italia del concorso Miss Summer Salento, il concorso diretto e organizzato dell&#8217;associazione Flashback di Brindisi con <strong>Direttore Artistico e Organizzatore Marcello Altomare insieme a Niko Fiore e Valentina Cino<\/strong>, per un&#8217;evento organizzato da dalla societ\u00e0 Eco Ambiente Sud di Fasano (Br) che vede come media partner la testata giornalistica brindisilibera.it e il portale degli eventi tuttavia.it sponsor ufficiale del concorso.<\/p>\n<p>In venti a competere per il titolo di Miss Cala di Rosamarina il prossimo Venerdi 18 in uno show che vede protagonisti la nota coppia televisiva che promette spettacolo e sorprese<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 18 luglio alle 21.30 la nomina della reginetta del Villaggio di Cala di Rosamarina a (Ostuni). A cala di Rosamarina con una giuria di eccezione sar\u00e0 eletta Miss Summer Salento 2014 del prestigioso villaggio Ostunese. &nbsp; La giuria presieduta dalla showgirl Camen Russo e Enzo Paolo Turchi avr\u00e0 l&#8217;arduo compito di eleggere ulteriori tre concorrenti da fare accedere alla finale del concorso il prossimo 23 agosto previsto nello stesso villaggio. Tanya Lupo di Castrano (Le), Selena Mosbah Galatina (Le) e Maria Laura Legali Scorrano (Le) intanto sono le belle elette lo scorso 13 luglio presso il prestigioso club Smaila&#8217;s di Gallipoli Le, da una giuria presieduta dalla stilista di Cavallino (Le.) Daniela Melcore, acquisendo il biglietto di ingresso per la competizione finale per aggiudicarsi il titolo di reginetta del tacco d&#8217;Italia del concorso Miss Summer Salento, il concorso diretto e organizzato dell&#8217;associazione Flashback di Brindisi con Direttore Artistico e Organizzatore Marcello Altomare insieme a Niko Fiore e Valentina Cino, per un&#8217;evento organizzato da dalla societ\u00e0 Eco Ambiente Sud di&#8230;<\/p>\n","protected":false},"author":2,"featured_media":17895,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[2314],"class_list":["post-17894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-miss-summer-salento"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/17894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=17894"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/17894\/revisions"}],"predecessor-version":[{"id":17897,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/17894\/revisions\/17897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/17895"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=17894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=17894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=17894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}