{"id":18219,"date":"2014-07-21T16:13:11","date_gmt":"2014-07-21T14:13:11","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=18219"},"modified":"2014-07-23T22:55:51","modified_gmt":"2014-07-23T20:55:51","slug":"tempodestate2014-mercoledi-the-union-experience-e-anteprima-in_chiostri-con-fratelli-mancuso","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/tempodestate2014-mercoledi-the-union-experience-e-anteprima-in_chiostri-con-fratelli-mancuso\/","title":{"rendered":"#tempodestate2014: oggi &#8220;The Union Experience&#8221; e anteprima In_chiostri con &#8220;Fratelli Mancuso&#8221;"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/07\/union-experience.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-18224 size-medium\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/07\/union-experience-300x150.jpg\" alt=\"union experience\" width=\"300\" height=\"150\" data-id=\"18224\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/07\/union-experience-300x150.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/07\/union-experience.jpg 886w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Nell\u2019ambito della programmazione estiva organizzata dal Comune di Brindisi, con la collaborazione tecnica della Fondazione Nuovo Teatro Verdi, Il \u00abSummer Festival 2014\u00bb d\u00e0 appuntamento sul lungomare Regina Margherita con il primo dei due appuntamenti di musica live nel cuore dell\u2019estate.<\/p>\n<p>Mercoled\u00ec 23 luglio, alle ore 21,00, iniziano, infatti, \u00abThe Union Experience\u00bb, un grande palco dedicato a 21 musicisti in arrivo dal Salento nel quale pop, soul, R&amp;B, funk and dance si intrecciano in uno show ad alto tasso di adrenalina di oltre due ore.<br \/>\n<a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/07\/locandina-brindisi-mancuso.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-18223\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/07\/locandina-brindisi-mancuso-206x300.png\" alt=\"locandina brindisi mancuso\" width=\"206\" height=\"300\" data-id=\"18223\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/07\/locandina-brindisi-mancuso-206x300.png 206w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/07\/locandina-brindisi-mancuso-704x1024.png 704w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/07\/locandina-brindisi-mancuso.png 936w\" sizes=\"auto, (max-width: 206px) 100vw, 206px\" \/><\/a>Sempre mercoled\u00ec 23 luglio, alle ore 21,00, nella Piazza San Giovanni al Sepolcro, si terr\u00e0 il Concerto\/anteprima di \u201cIn_chiostri\u201d, Fratelli Mancuso in concerto, dal titolo \u201cCome albero scosso da interna bufera\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Cantare \u00e8 sempre necessario. Non conosciamo un modo diverso per testimoniare la nostra convivenza con il mondo.<br \/>\nCome ai pi\u00f9 sofisticati sismografi affidiamo alla voce, alla parola poetica, al canto il pi\u00f9 intimo e profondo esercizio di decifrazione affinch\u00e9 possa essere del nostro tempo fedele messaggero.<br \/>\nCantare \u00e8 provare a dare nome a ci\u00f2 che nome ancora non ha. Cantare significa scavare, senza sosta, alla ricerca di una lingua universale, cercando in quel suo riverbero sonoro l\u2019alfabeto di una nuova fratellanza.<br \/>\nMai al riparo e in nessun luogo, cerchiamo con il canto di placare la bufera che talvolta scuote ogni singola foglia, ogni esile radice della nostra anima.<br \/>\nDopo il riconoscimento al Festival del Cinema di Venezia in cui \u00e8 stato assegnato loro il Premio Sound Track Stars per la composizione della colonna sonora nel film \u201cVia Castellana Bandiera\u201d, della regista Emma Dante, i Fratelli Mancuso propongono un concerto che \u00e8 l\u2019occasione per conoscere approdi ancora inediti della loro ricerca musicale.<br \/>\nUna ricerca poetica, un diario intimo volto a nuove sperimentazioni. Un linguaggio che affida al canto e alla memoria la bussola per navigare nel mare aperto della contemporaneit\u00e0. Canti di tradizione, musiche che sulla scena teatrale irrompono e si confrontano con le esperienze internazionali pi\u00f9 innovative.<br \/>\nIl titolo del concerto prende spunto da un verso del poeta Eugenio De Signoribus.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/07\/Fratelli_Mancuso_3_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-18221\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/07\/Fratelli_Mancuso_3_1-300x199.jpg\" alt=\"Fratelli_Mancuso_3_1\" width=\"300\" height=\"199\" data-id=\"18221\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/07\/Fratelli_Mancuso_3_1-300x199.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/07\/Fratelli_Mancuso_3_1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Fratelli Mancuso<\/strong><br \/>\n<em>Enzo Mancuso: canto, chitarra classica, saz baglama, ghironda, violinio,sipsy.<\/em><br \/>\n<em> Lorenzo Mancuso: canto, chitarra classica, harmonium, percussioni<\/em><\/p>\n<p><em>Il concerto \u00e8 in collaborazione con Roberto Caroppo per il Manifesto della Cultura<\/em><\/p>\n<p><em>I Fratelli Mancuso sono nati a Sutera. Intorno agli anni \u201970 emigrano a Londra e l\u00ec lavorano per otto anni in fabbrica. Tornati in Italia nel 1981 si stabiliscono a Citt\u00e0 della Pieve. Nel 1986, in collaborazione con J. Diaz, in Spagna, incidono l\u2019album Nesci Maria e nel 1990 Romances de alla y de aca . Nel 1993 raccolgono insieme a composizioni proprie, i canti del loro paese, curando l\u2019edizione del CD Sutera, la tradizione musicale di un paese della Sicilia. Nel 1994 pubblicano Ali di carta, una raccolta di testi delle loro composizioni. Nel 1993 vincono il Premio Recanati e incidono il CD Bella Maria. Nel 1998 partecipano come attori e musicisti al film Il talento di Mister Ripley del regista inglese Anthony Minghella. Incidono Italian Odissey per la Putumayo World music Records, in distribuzione mondiale nel 2000. Nel 1999 cantano al Premio Tenco. Nel 2001 compongono il titolo di coda della fiction televisiva Donne di mafia del regista G. Ferrara. Nel 2002 concerto in diretta su RadioTre dalla Cappella Paolina del Quirinale. Esce nel 2003 il CD Cantu, parallelamente compongono le musiche dello spettacolo Medea con la regia di Emma Dante e la produzione del Teatro Mercadante di Napoli. Nel 2004 incidono, in Spagna, il CD Trazzeri e nello stesso anno presentano alla 59\u00b0 Sagra Musicale Umbra il concerto mistico Requiem. Nel dicembre 2004 in diretta dalla Cappella Paolina su RadioTre eseguono il concerto di novene siciliane. Nel dicembre del 2005 al Teatro Antico di Taormina eseguono Natale nel verso e nel canto accompagnati dall\u2019orchestra da camera di Messina diretta dal M\u00b0 Carlo Pedini, Mauro Pagani, Roberto Fabbriciani e Arnaldo Vacca. Il 31 maggio del 2006 tornano, dopo qualche anno, ad esibirsi al Konzerthaus di Vienna . Nel settembre dello stesso anno cantano al Teatro Bellini di Catania nell\u2019opera Sette storie per lasciare il mondo, regia di Roberto And\u00f2 e musiche di Marco Betta. Nel giugno del 2008 incidono con l\u2019etichetta Amiata il CD Requiem. Nello stesso anno esce per i tipi Squilibri di Roma il volume \u201cL\u2019isola timida\u201d con le fotografie di Antonino Pennisi e i loro testi poetici con in allegato un DVD delle loro musiche. Sempre a Roma cantano al Pantheon e nell\u2019opera di Marco Betta \u201cAlmanacco delle morti presunte\u201d all\u2019Auditorium Parco della musica.<\/em><br \/>\n<em> Nel novembre del 2009 registrano per Radio France in diretta un loro concerto insieme al violista Christophe Desjardins che in quell\u2019occasione esegue il Naturale di Luciano Berio.<\/em><br \/>\n<em> Nel dicembre dello stesso anno sono Radio Tre Suite ospita un loro concerto in diretta dal titolo: \u201cLa voce nuda\u201d.<\/em><br \/>\n<em> Dal mese di maggio a luglio 2010, per il Ravenna Festival e il Teatro delle Albe, compongono ed eseguono le musiche di scena di due opere teatrali: Cercatori di tracce e Rumore di acque con la regia di Marco martinelli.<\/em><br \/>\n<em> Marzo 2012 :concerto in diretta su Rai Radio Tre dal Quirinale<\/em><br \/>\n<em> Giugno 2012 : aprono il Ravenna Festival 2012 con il concerto \u201cLa via dolorosa\u201d<\/em><br \/>\n<em> Giugno 2012 : compongono ed eseguono dal vivo a Bologna per La Cineteca Comunale, le musiche di due cortometraggi in bianco e nero del 1909.<\/em><br \/>\n<em> Ottobre 2012: rimettono in scena al Teatro Olimpico di Vicenza Medea con la regia di Emma Dante.<\/em><br \/>\n<em> 2013 compongono la colonna sonora del film Via Castellana Bandiera con la regia di Emma Dante prodotto da Rai Cinema e da Vivo Film<\/em><br \/>\n<em> Giugno 2013: a Palermo viene presentato il film: Chifteli con la regia di Dario Gurneri. La storia della loro vita umana e artistica, prodotto dal Centro di Cinematografia di Palermo.<\/em><br \/>\n<em> Agosto 2013: Tuor in Finlandia con l\u2019opera Verso Medea.<\/em><br \/>\n<em> Settembre 2013: Il film Via Castellana Bandiera di Emma Dante \u00e8 in concorso alla Mostra del Cinema di Venezia e vengono invitati alla presentazione del film come compositori della colonna sonora.<\/em><br \/>\n<em> 70\u00b0 Mostra del Cinema di Venezia ricevono il premio SoundTrack Stars per avere composto la colonna sonora del film di E. Dante: Via Castellana Bandiera con una menzione speciale.<\/em><\/p>\n<p><em>Ricevono a Lecce il Premio della Critica 2013 Anct (Associazione Nazionale Critici Teatrali)<\/em><br \/>\n<em> Gennaio \u2013 febbraio 2014 si esibisco in un tour di un mese al Teatro La MaMa di New York, tengono una lezione concerto all\u2019Montclair University, al Bard College di Annandale On Hudson e al Links di Chicago.<\/em><\/p>\n<p><em>Il 1 marzo ricevono dal Comune di Sutera , paese loro natio, il riconoscimento:<\/em><br \/>\n<em> Cittadini benemeriti<\/em><\/p>\n<p><em>Maggio 2014: Ottengono la Nomination al Globo d\u2019oro e al Nastro d\u2019argento per la migliore colonna sono del film Via Castellana Bandiera<\/em><\/p>\n<p><em>Maggio 2014: vengono premiati al Festival del Teatro di Turun (Polonia) per le musiche di scena dell\u2019opera teatrale\u201d Verso Medea\u201d con la regia di Emma Dante.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.brundisium.net\/brun\/index.php\/tempodestate2014-tutto-il-cartellone-dellestate-brindisina\/\">TUTTO IL CARTELLONE DELL&#8217;ESTATE BRINDISINA #tempodestate2014<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nell\u2019ambito della programmazione estiva organizzata dal Comune di Brindisi, con la collaborazione tecnica della Fondazione Nuovo Teatro Verdi, Il \u00abSummer Festival 2014\u00bb d\u00e0 appuntamento sul lungomare Regina Margherita con il primo dei due appuntamenti di musica live nel cuore dell\u2019estate. Mercoled\u00ec 23 luglio, alle ore 21,00, iniziano, infatti, \u00abThe Union Experience\u00bb, un grande palco dedicato a 21 musicisti in arrivo dal Salento nel quale pop, soul, R&amp;B, funk and dance si intrecciano in uno show ad alto tasso di adrenalina di oltre due ore. Sempre mercoled\u00ec 23 luglio, alle ore 21,00, nella Piazza San Giovanni al Sepolcro, si terr\u00e0 il Concerto\/anteprima di \u201cIn_chiostri\u201d, Fratelli Mancuso in concerto, dal titolo \u201cCome albero scosso da interna bufera\u201d. &nbsp; Cantare \u00e8 sempre necessario. Non conosciamo un modo diverso per testimoniare la nostra convivenza con il mondo. Come ai pi\u00f9 sofisticati sismografi affidiamo alla voce, alla parola poetica, al canto il pi\u00f9 intimo e profondo esercizio di decifrazione affinch\u00e9 possa essere del nostro tempo fedele messaggero. Cantare \u00e8 provare a dare nome a ci\u00f2&#8230;<\/p>\n","protected":false},"author":2,"featured_media":17989,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[2332],"class_list":["post-18219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-tempodestate"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/18219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=18219"}],"version-history":[{"count":4,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/18219\/revisions"}],"predecessor-version":[{"id":18343,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/18219\/revisions\/18343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/17989"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=18219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=18219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=18219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}